{"id":240839,"date":"2018-04-19T14:29:41","date_gmt":"2018-04-19T17:29:41","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240839"},"modified":"2018-04-19T14:29:41","modified_gmt":"2018-04-19T17:29:41","slug":"professora-chama-crianca-de-demonio-e-ameaca-furar-sua-cabeca-com-murros-secretaria-da-educacao-de-jacobina-emite-nota","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/professora-chama-crianca-de-demonio-e-ameaca-furar-sua-cabeca-com-murros-secretaria-da-educacao-de-jacobina-emite-nota\/","title":{"rendered":"Professora chama crian\u00e7a de dem\u00f4nio e amea\u00e7a furar sua cabe\u00e7a com murros; Secretaria da Educa\u00e7\u00e3o de Jacobina emite nota"},"content":{"rendered":"<header class=\"entry-header\">\n<h1 class=\"entry-title\"><\/h1>\n<\/header>\n<div class=\"entry-content\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\" aligncenter\" src=\"https:\/\/i1.wp.com\/4.bp.blogspot.com\/-V0rXDC-WWnI\/Wti8rBxKnoI\/AAAAAAAEgAs\/df0hjoefy6wHTDnmpeAdc4K1Vzp36QfYwCLcBGAs\/s400\/print_v%25C3%25ADdeo.png?w=584&amp;ssl=1\" width=\"400\" height=\"281\" \/><\/div>\n<div><\/div>\n<div>Circula nas redes sociais, um v\u00eddeo onde supostamente uma professora agride verbalmente um aluno de uma creche municipal no Distrito de Novo Para\u00edso em Jacobina. No v\u00eddeo a mesma chama uma das crian\u00e7as de dem\u00f4nio, que come\u00e7a a chorar. Logo em seguida, a mesma amea\u00e7a furar a cabe\u00e7a da crian\u00e7a com murros, se o mesmo n\u00e3o parasse de conversar.Quanto ao assunto a Secretaria Municipal da Educa\u00e7\u00e3o emitiu Nota de Esclarecimento, confira a nota e o v\u00eddeo na \u00edntegra abaixo:<\/p>\n<\/div>\n<div><b><i>Nota de Esclarecimento<\/i><\/b><\/div>\n<div><b><i>\u00a0<\/i><\/b><\/div>\n<div><b><i>A Secretaria Municipal da Educa\u00e7\u00e3o e Cultura de Jacobina, de posse de um v\u00eddeo onde mostra claramente uma professora agredindo verbalmente um aluno, enviou uma equipe de profissionais at\u00e9 o Distrito de Novo Para\u00edso para ouvir as partes envolvidas e deixar aqui alguns encaminhamentos que foram tomados inicialmente: a professora acusada foi imediatamente afastada da unidade at\u00e9 que todas as provid\u00eancias sejam tomadas; uma equipe do CRAS local atendeu a fam\u00edlia da v\u00edtima e junto ao CREAS far\u00e1 um acompanhamento; uma psicopedagoga da Secretaria da Educa\u00e7\u00e3o acompanhar\u00e1 junto ao CRAS o atendimento ao aluno para evitar maiores transtornos.<\/i><\/b><br \/>\n<b><i><br \/>\n<\/i><\/b><\/div>\n<div><b><i>Ouvimos ainda a dire\u00e7\u00e3o da creche e alguns pais de alunos e n\u00e3o h\u00e1 sobre a professora nenhuma outra\u00a0 acusa\u00e7\u00e3o de maus tratos anterior a essa.<\/i><\/b><br \/>\n<b><i><br \/>\n<\/i><\/b><\/div>\n<div><b><i>A Secretaria da Educa\u00e7\u00e3o e Cultura condena veementemente toda forma de agress\u00e3o e tomar\u00e1 todas as provid\u00eancias poss\u00edveis para que esse tipo de ato n\u00e3o se repita em nenhuma das unidades escolares do munic\u00edpio.<\/i><\/b><\/div>\n<div>\n<div class=\"jetpack-video-wrapper\">\n<p><a href=\"https:\/\/www.youtube.com\/watch?time_continue=7&#038;v=kmccTMZvWSM\">https:\/\/www.youtube.com\/watch?time_continue=7&amp;v=kmccTMZvWSM<\/a><\/p>\n<p>Fonte: Blog Beija Flor 98,7 FM<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal da Educa\u00e7\u00e3o e Cultura de Jacobina, de posse de um v\u00eddeo onde mostra claramente uma professora agredindo verbalmente um aluno, enviou uma equipe de profissionais at\u00e9 o Distrito de Novo Para\u00edso para ouvir as part<\/p>\n","protected":false},"author":5,"featured_media":240840,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sala-de-jacobina.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240839"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/240840"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}