{"id":240983,"date":"2018-04-22T04:56:50","date_gmt":"2018-04-22T07:56:50","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=240983"},"modified":"2018-04-22T04:56:50","modified_gmt":"2018-04-22T07:56:50","slug":"de-goela-abaixo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/de-goela-abaixo\/","title":{"rendered":"De goela abaixo"},"content":{"rendered":"<figure id=\"attachment_175169\" aria-describedby=\"caption-attachment-175169\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-175169 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-620x349.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-768x432.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto-640x360.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2017\/02\/odacy-e-humberto.jpg 1280w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-175169\" class=\"wp-caption-text\">Humberto e Odacy<\/figcaption><\/figure>\n<p>Humberto Costa (PT), em peregrina\u00e7\u00e3o pelo interior, continua dizendo que a sa\u00edda de Jo\u00e3o Paulo do PT fragilizou o partido. Mas fragilizou tamb\u00e9m Jo\u00e3o Paulo, que foi vereador, deputado estadual, deputado federal e prefeito do Recife pela legenda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Humberto Costa (PT), em peregrina\u00e7\u00e3o pelo interior, continua dizendo que a sa\u00edda de Jo\u00e3o Paulo do PT fragilizou o partido. Mas fragilizou tamb\u00e9m Jo\u00e3o Paulo, que foi vereador, deputado estadual, deputado federal e prefeito do Recife pela legenda.<\/p>\n","protected":false},"author":5,"featured_media":17616,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-240983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Humberto-Costa.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=240983"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/240983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/17616"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=240983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=240983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=240983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}