{"id":241213,"date":"2018-04-24T10:14:17","date_gmt":"2018-04-24T13:14:17","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=241213"},"modified":"2018-04-24T14:13:16","modified_gmt":"2018-04-24T17:13:16","slug":"release-sobre-forum-popular-sobre-transporte-coletivo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/release-sobre-forum-popular-sobre-transporte-coletivo\/","title":{"rendered":"Release sobre F\u00f3rum Popular sobre Transporte Coletivo"},"content":{"rendered":"<p style=\"text-align: justify;\">A casa Pl\u00ednio Amorim recebeu na sexta-feira, 20 de abril, um importante debate para a cidade de Petrolina. As licita\u00e7\u00f5es para os transporte coletivos foi pauta de uma audi\u00eancia convocada pelo poder executivo. Estiveram presentes no evento estudantes, comunit\u00e1rios, funcion\u00e1rios e ex-funcion\u00e1rios das empresas de transporte, vereadores\/as, representantes da gest\u00e3o municipal e membros de institui\u00e7\u00f5es importantes como a UNIVASF.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-241214 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte.jpg\" alt=\"\" width=\"470\" height=\"353\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte.jpg 470w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte-160x120.jpg 160w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/p>\n<p style=\"text-align: justify;\">Metodologicamente, a audi\u00eancia possibilitou a participa\u00e7\u00e3o da sociedade civil e os trabalhos foram conduzidos pelo vereador Ronaldo Canc\u00e3o (PTB). O Sr\u00ba Geraldo Miranda, diretor presidente da Autarquia Municipal de Mobilidade de Petrolina (AMMPLA), teve a responsabilidades de responder as quest\u00f5es levantadas ao longo dos debates. No entanto, o tempo de di\u00e1logo estabelecido na audi\u00eancia n\u00e3o foi suficiente para dirimir as d\u00favidas dos\/as presente, nem t\u00e3o pouco suficiente para elaborar todas as propostas necess\u00e1rias.<\/p>\n<p style=\"text-align: justify;\">Pensando em ampliar e potencializar esse debate t\u00e3o importante para a cidade, acreditando na seriedade e honestidade que requer a pauta, o vereador Gilmar Santos (PT) e a vereadora Cristina Costa (PT) convidam todos\/as os\/as interessados\/as a participar de um F\u00f3rum Popular sobre transporte coletivo na pr\u00f3xima quarta-feira, dia 25\/04, na C\u00e2mara Municipal, \u00e0s 15h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A casa Pl\u00ednio Amorim recebeu na sexta-feira, 20 de abril, um importante debate para a cidade de Petrolina. As licita\u00e7\u00f5es para os transporte coletivos foi pauta de uma audi\u00eancia convocada pelo poder executivo. Estiveram presentes no evento estudantes, comunit\u00e1rios, funcion\u00e1rios e ex-funcion\u00e1rios das empresas de transporte, vereadores\/as, representantes da gest\u00e3o municipal e membros de institui\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":241214,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-241213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/forum-transporte.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=241213"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/241214"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=241213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=241213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=241213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}