{"id":241336,"date":"2018-04-25T10:19:52","date_gmt":"2018-04-25T13:19:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=241336"},"modified":"2018-04-25T10:19:52","modified_gmt":"2018-04-25T13:19:52","slug":"homem-e-preso-por-fazer-amor-com-cachorra","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/homem-e-preso-por-fazer-amor-com-cachorra\/","title":{"rendered":"Homem \u00e9 preso por fazer &#8216;amor com cachorra&#8217;"},"content":{"rendered":"<p>De acordo informa\u00e7\u00f5es policiais, um homem foi preso acusado de est\u00e1 fazendo amor com uma cachorra. Assim que os policiais chegaram em sua casa, depois de receberem denuncia de uma moradora vizinha, ele confirmou o ato alegando que &#8220;deu apenas duas cacetadazinha na bichinha que gostou&#8221;. J\u00e1 como no Brasil n\u00e3o tem lei para combater casos de zoofilia, ele ser\u00e1 enquadrado na lei de maus-tratos aos animais.<\/p>\n<figure id=\"attachment_82174\" aria-describedby=\"caption-attachment-82174\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82174 size-medium\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/cachorra-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/cachorra-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/cachorra-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/cachorra.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-82174\" class=\"wp-caption-text\">Ilustra\u00e7\u00e3o<\/figcaption><\/figure>\n<p>J\u00e1 em alguns pa\u00edses da Europa tanto o homem como a mulher j\u00e1 tem esse tipo de relacionamento incestuoso, mas n\u00e3o reconhecido pelas leis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo informa\u00e7\u00f5es policiais, um homem foi preso acusado de est\u00e1 fazendo amor com uma cachorra. Assim que os policiais chegaram em sua casa, depois de receberem denuncia de uma moradora vizinha, ele confirmou o ato alegando que &#8220;deu apenas duas cacetadazinha na bichinha que gostou&#8221;. J\u00e1 como no Brasil n\u00e3o tem lei para combater [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":82174,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-241336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/09\/cachorra.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=241336"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/82174"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=241336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=241336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=241336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}