{"id":241870,"date":"2018-04-30T08:12:01","date_gmt":"2018-04-30T11:12:01","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=241870"},"modified":"2018-04-30T08:12:01","modified_gmt":"2018-04-30T11:12:01","slug":"petista-quer-proibir-tv-justica-de-televisionar-sessoes-do-stf","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/petista-quer-proibir-tv-justica-de-televisionar-sessoes-do-stf\/","title":{"rendered":"Petista quer proibir TV Justi\u00e7a de televisionar sess\u00f5es do STF"},"content":{"rendered":"<div class=\"content-banner-principal\">\n<div class=\"container publicidade\">\n<div class=\"col-md-12\">\n<div id=\"div-gpt-ad-1502987812182-0\" data-google-query-id=\"CMuhl7zu4doCFdYXhgodkj8GQQ\">\n<div id=\"div-gpt-ad-1502987812182-0_ad_container\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row main\">\n<div class=\"container\">\n<section class=\"col-md-8 col-sm-8\">\n<article id=\"post-196689\" class=\"box-noticias box-interna\">\n<header>\n<figure><img decoding=\"async\" class=\"img-responsive\" title=\"Foto: Ag\u00eancia C\u00e2mara\" src=\"http:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2017\/07\/vicente-candido-748x410.jpg\" alt=\"Foto: Ag\u00eancia C\u00e2mara\" \/><figcaption>Foto: Ag\u00eancia C\u00e2mara<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<div id=\"texto-noticia\">\n<p>Em nova ofensiva contra o Judici\u00e1rio, o PT tenta emplacar na pauta da Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da C\u00e2mara um projeto que pro\u00edbe a TV Justi\u00e7a de transmitir as sess\u00f5es do Supremo Tribunal Federal (STF) e demais tribunais superiores. A proposta, de autoria do deputado Vicente C\u00e2ndido (PT-SP), foi apresentada em 2013, mas virou prioridade para o partido depois de a Corte negar HC para soltar o ex-presidente Lula. Petistas avaliam que o resultado poderia ser diferente n\u00e3o fosse a transmiss\u00e3o ao vivo gerar press\u00e3o sobre os ministros.<\/p>\n<p><strong>S\u00f3 o resultado.<\/strong>\u00a0O projeto do deputado petista prev\u00ea que a TV Justi\u00e7a se limite a divulgar os atos do Poder Judici\u00e1rio, \u201csem transmiss\u00e3o ao vivo e sem edi\u00e7\u00e3o de imagens e sonoras das suas sess\u00f5es e dos demais Tribunais Superiores\u201d.<\/p>\n<div id=\"sc-ava-71476338\"><\/div>\n<div id=\"smartIntxt\" class=\"fixed_intext_sc_v1\"><\/div>\n<p><strong>Para o bem deles.<\/strong>\u00a0Vicente C\u00e2ndido justifica que a transmiss\u00e3o ao vivo das sess\u00f5es exp\u00f5e os ministros. \u201cAs entranhas da Justi\u00e7a \u00e9 que est\u00e3o sendo mostradas com sensacionalismo exacerbado por parte de alguns ministros em particular.\u201d<\/p>\n<p><strong>Ele tenta.<\/strong>\u00a0O deputado petista \u00e9 o mesmo que apresentou a \u201cemenda Lula\u201d, revelada pela Coluna e que tinha o prop\u00f3sito de impedir a pris\u00e3o de candidatos oito meses antes da elei\u00e7\u00e3o. Se tivesse avan\u00e7ado, Lula n\u00e3o poderia ter sido preso.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Ag\u00eancia C\u00e2mara Em nova ofensiva contra o Judici\u00e1rio, o PT tenta emplacar na pauta da Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da C\u00e2mara um projeto que pro\u00edbe a TV Justi\u00e7a de transmitir as sess\u00f5es do Supremo Tribunal Federal (STF) e demais tribunais superiores. A proposta, de autoria do deputado Vicente C\u00e2ndido (PT-SP), foi apresentada em [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":241871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-241870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/vicente-candido-748x410.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=241870"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/241870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/241871"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=241870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=241870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=241870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}