{"id":242006,"date":"2018-05-01T09:13:56","date_gmt":"2018-05-01T12:13:56","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=242006"},"modified":"2018-05-02T07:17:05","modified_gmt":"2018-05-02T10:17:05","slug":"sobrinha-de-ivete-deu-primeiros-passos-ao-som-de-sergio-do-forro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sobrinha-de-ivete-deu-primeiros-passos-ao-som-de-sergio-do-forro\/","title":{"rendered":"Sobrinha de Ivete deu primeiros passos ao som de S\u00e9rgio do Forr\u00f3"},"content":{"rendered":"<header>\n<h1><\/h1>\n<\/header>\n<div class=\"story\" style=\"text-align: justify;\">\n<div class=\"header\">\n<figure class=\"vertical_inline\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/extra.globo.com\/incoming\/22641556-f70-8b6\/w448h673-PROP\/xcamila.JPG.pagespeed.ic.oIlb6GTC7M.jpg\" width=\"448\" height=\"673\" \/><figcaption>Camila cantou &#8216;Cheguei pra te amar&#8217; e &#8216;I will survive&#8217; com a tia famosa Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<\/div>\n<p>Na noite do \u00faltimo domingo (29), cerca de 800 mil foli\u00f5es acompanharam a volta de\u00a0<a class=\"tv\" href=\"https:\/\/extra.globo.com\/tv-e-lazer\/ivete-sangalo\/\" rel=\"follow\">Ivete Sangalo<\/a>\u00a0em Salvador, ap\u00f3s quatro meses longe dos palcos e dos trios. Mas a data tamb\u00e9m foi especial para Camila Nunes. Sobrinha da cantora, ela cantou pela primeira vez para uma multid\u00e3o, com o aval da tia famosa (e babona): &#8220;Desde muito pequena Camila j\u00e1 mostrava o seu grande talento para a m\u00fasica. Eu babei mesmo! Ela \u00e9 uma luz de vida. Mimi, te amo infinito!&#8221;, festejou.<\/p>\n<p>Um dia depois da apresenta\u00e7\u00e3o, Camila j\u00e1 estava exercendo sua outra paix\u00e3o: a Psicologia. Depois de cantar para tanta gente, ela passou a tarde da segunda-feira (30) atendendo seus pacientes em consultas individuais, no consult\u00f3rio que abriu h\u00e1 tr\u00eas anos. &#8220;S\u00e3o mundos diferentes, aos quais me dedico com a mesma paix\u00e3o&#8221;, garante ela, que est\u00e1 com 27 anos. &#8220;Sigo a abordagam junguiana da Psicologia. A maioria das pessoas que atendo est\u00e1 entre os 20 e os 30 anos, na mesma faixa et\u00e1ria que eu. Mas tamb\u00e9m tem crian\u00e7as e gente mais velha&#8221;, conta.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641844-6a4-925\/w448\/xcamila-9.JPG.pagespeed.ic.dxI8nYRwe_.jpg\" alt=\"Camila tem um consult\u00f3rio em Salvador\" \/><figcaption>Camila tem um consult\u00f3rio em Salvador Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641563-700-77c\/w448\/xcamila-4.JPG.pagespeed.ic.Z_GJ9pGXHe.jpg\" alt=\"Camila e Ivete cantando no trio\" \/><figcaption>Camila e Ivete cantando no trio Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641614-1b6-949\/w448\/xcamila-7.JPG.pagespeed.ic.0XpvpxxW33.jpg\" alt=\"'Titia' Ivete vibra com a sobrinha Camila\" \/><figcaption>&#8216;Titia&#8217; Ivete vibra com a sobrinha Camila Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<p>Ivete n\u00e3o \u00e9 sua \u00fanica refer\u00eancia musical. Ela \u00e9 filha de M\u00f4nica San Galo, irm\u00e3 de Ivete e tamb\u00e9m cantora, que escolheu um estilo mais voltado para a MPB. &#8220;Minha m\u00e3e \u00e9 formada em m\u00fasica, toca viol\u00e3o divinamente. S\u00e3o duas grandes artistas, que eu tenho o privil\u00e9gio de estar pr\u00f3xima&#8221;, afirma. Quando a tia come\u00e7ou a fazer sucesso \u00e0 frente da banda Eva, Camila ainda era crian\u00e7a. Mas a fama nunca a distanciou da fam\u00edlia: &#8220;Ela \u00e9 a tia da bagun\u00e7a. Sempre foi brincalhona, muito presente na vida de todos os sobrinhos. N\u00e3o tem diferen\u00e7a entre o que ela \u00e9 em casa e a pessoa p\u00fablica&#8221;.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641617-961-b8a\/w448\/xcamila-8.JPG.pagespeed.ic.W-adPvBnQ7.jpg\" alt=\"Camila com a m\u00e3e, a tamb\u00e9m cantora M\u00f4nica San Galo\" \/><figcaption>Camila com a m\u00e3e, a tamb\u00e9m cantora M\u00f4nica San Galo com o cantor e compositor S\u00e9rgio do Forr\u00f3 em Juazeiro Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<div class=\"embeddedInstagramInline\" align=\"center\">\n<div class=\"instagram-22641448\"><iframe loading=\"lazy\" id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BLOEaNVAiaq\/embed\/captioned\/?cr=1&amp;v=8&amp;wp=446&amp;rd=extra.globo.com#%7B%22ci%22%3A0%2C%22os%22%3A4815.999999991618%7D\" width=\"300\" height=\"888\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p>Na adolesc\u00eancia, Ivete era a tia que queria saber das paqueras e que dava conselhos sobre os relacionamentos. N\u00e3o s\u00f3 para Camila, mas tamb\u00e9m para as suas amigas. &#8220;\u00c0s vezes, ela ia pegar a gente no col\u00e9gio e levava pra tomar sorvete. Claro que n\u00e3o era um passeio tranquilo, pois onde ela chega, mesmo em Salvador, junta gente. Mas nunca deixou de fazer isso&#8221;, diz ela, \u00fanica dos oito sobrinhos que j\u00e1 demostrou talento para m\u00fasica: &#8220;Agora tem o Marcelo, filho dela, que arrasa na bateria&#8221;.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641855-303-b7e\/w448\/xcamila-10.JPG.pagespeed.ic.qvQBTN8JnD.jpg\" alt=\"Camila \u00e9 adepta do crossfit: 'Amo atividade f\u00edsica'\" \/><figcaption>Camila \u00e9 adepta do crossfit: &#8216;Amo atividade f\u00edsica&#8217; Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<p>Ainda surpresa com a repercuss\u00e3o de sua participa\u00e7\u00e3o no trio, Camila viu seu n\u00famero de seguidores aumentar de 23 mil para 33 mil, em apenas tr\u00eas dias. No pr\u00f3ximo dia 3, ela se apresenta no Fera Palace Hotel, em Salvador, mostrando seu repert\u00f3rio pop, que mistura Tim Maia, Sandy &amp; Junior, Ed Sheeran e, claro, Gloria Gaynor, cujo hit maior &#8211; &#8220;I will survive &#8211; foi uma das m\u00fasicas que ela cantou com a tia. &#8220;Foi lindo ver todo mundo pulando. Me arrepio s\u00f3 de lembrar. Ser recebido pelos f\u00e3s dela com tanto carinho foi muito especial. Serei eternamente grata&#8221;, garante.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641744-7d9-bf1\/w448\/xcamila-6.JPG.pagespeed.ic.WrKbGl0cbT.jpg\" alt=\"Camila faz show em Salvador no pr\u00f3ximo dia 3\" \/><figcaption>Camila faz show em Salvador no pr\u00f3ximo dia 3 Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641748-e04-a18\/w448\/xcamila-5.JPG.pagespeed.ic.vF75-YekFz.jpg\" alt=\"O repert\u00f3rio de Camila mistura Tim Maia e Ed Sheeran\" \/><figcaption>O repert\u00f3rio de Camila mistura Tim Maia e Ed Sheeran Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<p>Ah, Camila tem namorado. Mas, no meio de tanta novidade, ela esqueceu de perguntar se ele estava disposto a tornar a rela\u00e7\u00e3o p\u00fablica. &#8220;Ele n\u00e3o \u00e9 do ramo. Nem sei se est\u00e1 disposto a aparecer. Ainda estou me acostumando com todo esse interesse sobre mim&#8221;, diverte-se.<\/p>\n<figure><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/22641747-978-de0\/w448\/xcamila-2.JPG.pagespeed.ic.rU5CLUDE4m.jpg\" alt=\"Camila viu seu n\u00famero de seguidores aumentar de 23 mil para 33 mil\" \/><figcaption>Camila viu seu n\u00famero de seguidores aumentar de 23 mil para 33 mil Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Camila com a m\u00e3e, a tamb\u00e9m cantora M\u00f4nica San Galo com o cantor e compositor S\u00e9rgio do Forr\u00f3 em Juazeiro<\/p>\n","protected":false},"author":5,"featured_media":242008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-242006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/05\/sergio1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/242006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=242006"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/242006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/242008"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=242006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=242006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=242006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}