{"id":242149,"date":"2018-05-02T17:45:00","date_gmt":"2018-05-02T20:45:00","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=242149"},"modified":"2018-05-03T09:37:42","modified_gmt":"2018-05-03T12:37:42","slug":"sanatorio-esta-irregular-diz-sesau-em-nota-enviada-para-o-ap","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sanatorio-esta-irregular-diz-sesau-em-nota-enviada-para-o-ap\/","title":{"rendered":"&#8216;Sanat\u00f3rio est\u00e1 irregular&#8217;, diz Sesau em nota enviada para o AP"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Da Reda\u00e7\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">Veja a nota que a Secretaria de Sa\u00fade de Juazeiro enviou para a reportagem do <em><strong>AP<\/strong><\/em> sobre mat\u00e9ria publicada informando a falta de aten\u00e7\u00e3o do munic\u00edpio para com o Sanat\u00f3rio Nossa senhora de F\u00e1tima:<\/p>\n<p style=\"text-align: justify;\">A Secretaria Municipal de Sa\u00fade vem a p\u00fablico informar que o pagamento referente aos servi\u00e7os prestados pelo Sanat\u00f3rio Nossa Senhora de F\u00e1tima foi realizado na \u00faltima segunda-feira, 30. No entanto a Secretaria esclarece ainda que a referida unidade necessita de regulariza\u00e7\u00e3o perante o munic\u00edpio quanto as suas obriga\u00e7\u00f5es tribut\u00e1rias, onde estas constam positivas, ou seja, a unidade n\u00e3o est\u00e1 regular. Isso inviabiliza o cumprimento do contrato, tendo em vista que uma das cl\u00e1usulas do contrato de presta\u00e7\u00e3o de servi\u00e7o \u00e9 a unidade estar em dia com as obriga\u00e7\u00f5es no munic\u00edpio.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-241694 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-620x379.jpg\" alt=\"\" width=\"620\" height=\"379\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-620x379.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-300x183.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-768x469.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-160x98.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio-640x391.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio.jpg 899w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">A conduta da Secret\u00e1ria de Sa\u00fade em exigir os comprovantes de regularidade n\u00e3o est\u00e1 em disson\u00e2ncia com a legisla\u00e7\u00e3o vigente, n\u00e3o se trata de exig\u00eancia ilegal ou arbitr\u00e1ria. Na verdade, o munic\u00edpio n\u00e3o est\u00e1 retendo valores\u00a0 da prestadora de servi\u00e7o, est\u00e1 condicionando o pagamento ao disposto na lei,\u00a0 com base no princ\u00edpio da legalidade (art. 37, caput, da CF\/88), j\u00e1 que \u00e9 dever do Munic\u00edpio cumprir as normas prescritas na lei.<\/p>\n<p style=\"text-align: justify;\">Em nenhum momento a Secretaria Municipal de Sa\u00fade se recusou\/recusa a fazer o pagamento dos servi\u00e7os prestados, no entanto solicita da administra\u00e7\u00e3o da referida unidade a regulariza\u00e7\u00e3o para que nos demais meses n\u00e3o ocorra nenhum contratempo referente a pagamento e os servi\u00e7os continuem sendo prestados de modo a atender a popula\u00e7\u00e3o de forma ampla.<\/p>\n<p style=\"text-align: justify;\">D\u00e9bora Sousa\/ SESAU<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vem a p\u00fablico informar que o pagamento referente aos servi\u00e7os prestados pelo Sanat\u00f3rio Nossa Senhora de F\u00e1tima foi realizado na \u00faltima segunda-feira, 30. No entanto a Secretaria esclarece ainda que a referida unidade necessita de regulariza\u00e7\u00e3o perante o munic\u00edpio quanto as suas obriga\u00e7\u00f5es tribut\u00e1rias, onde estas constam positivas, ou seja, a unidade n\u00e3o<\/p>\n","protected":false},"author":5,"featured_media":241694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,8],"tags":[],"class_list":["post-242149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-noalvo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/sanatorio.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/242149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=242149"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/242149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/241694"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=242149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=242149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=242149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}