{"id":291120,"date":"2019-08-03T10:11:19","date_gmt":"2019-08-03T13:11:19","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291120"},"modified":"2019-08-03T10:11:19","modified_gmt":"2019-08-03T13:11:19","slug":"lixo-escandaloso","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/lixo-escandaloso\/","title":{"rendered":"Lixo escandaloso"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-289756\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-768x433.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17-640x361.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua17.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">O TC pode transformar em letra morta a primeira parceria p\u00fablica privada em gest\u00e3o de res\u00edduos s\u00f3lidos no Estado, em Paulista. O prefeito extinguiu a PPP e contratou, sem licita\u00e7\u00e3o, pelo valor de R$, 2,9 milh\u00f5es, as empresas CTR e Limpmax, para recolher o lixo e fazer servi\u00e7os de limpeza urbana. O mais grave \u00e9 que a PPP, com custos de R$ 35 milh\u00f5es, \u00e9 financiada pelo BNDES. (Magno Martins)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O TC pode transformar em letra morta a primeira parceria p\u00fablica privada em gest\u00e3o de res\u00edduos s\u00f3lidos no Estado, em Paulista. O prefeito extinguiu a PPP e c<\/p>\n","protected":false},"author":5,"featured_media":289752,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/07\/lixo-na-rua13.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291120"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/289752"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}