{"id":291162,"date":"2019-08-03T15:36:42","date_gmt":"2019-08-03T18:36:42","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291162"},"modified":"2019-08-04T14:28:52","modified_gmt":"2019-08-04T17:28:52","slug":"ibicarai-superintendente-da-sudec-visita-distrito-da-salomeia-e-vistoria-area-de-risco","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/ibicarai-superintendente-da-sudec-visita-distrito-da-salomeia-e-vistoria-area-de-risco\/","title":{"rendered":"Ibicara\u00ed: Superintendente da SUDEC visita distrito da Salomeia e vistoria \u00e1rea de risco"},"content":{"rendered":"<p style=\"text-align: justify;\">O Diretor da Superintend\u00eancia de Prote\u00e7\u00e3o e Defesa Civil (SUDEC) do Estado da Bahia, Paulo S\u00e9rgio Menezes Luz, esteve na manh\u00e3 de ontem em Ibicara\u00ed para vistoriar a encosta que corre risco de desmoronamento no distrito da Salomeia. A visita foi decorrente de um pedido feito pelo prefeito Lula Brand\u00e3o, que esteve em Salvador essa semana na sede da SUDEC.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291169 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia7.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\nPaulo Luz estava acompanhado do t\u00e9<span class=\"text_exposed_show\">cnico e motorista Jos\u00e9 Helenito, al\u00e9m do coordenador de Defesa Civil do munic\u00edpio, Ronny Batista, da secret\u00e1ria de Assist\u00eancia Social, Alesandra Brand\u00e3o (e alguns funcion\u00e1rios da Assist\u00eancia Social) e do vereador e representante do distrito, Sidney Mac\u00eado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291168 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia6.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\nNa oportunidade o Diretor-Superintendente da SUDEC vistoriou as \u00e1reas de risco, fotografando a encosta de v\u00e1rios \u00e2ngulos, visitou algumas moradias e conversou com diversos moradores da parte alta e baixada do local. No total s\u00e3o 23 casas que est\u00e3o em situa\u00e7\u00e3o de risco.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291167 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia5.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\n\u201cEsse local no momento representa um risco muito alto para quem vive aqui. Enquanto n\u00e3o resolver e a encosta n\u00e3o for feita \u00e9 necess\u00e1rio viver em total estado de alerta. Vou acelerar o meu parecer t\u00e9cnico pois a situa\u00e7\u00e3o \u00e9 cr\u00edtica\u201d, disse Paulo Luz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291166 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia4.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\nOs moradores Givaldo Neves (casa 173) e Jos\u00e9 de Souza Menezes (casa 156), da rua Aloysio de Castro, mostraram as condi\u00e7\u00f5es em que est\u00e3o morando, na beira do barranco, e as rachaduras que apareceram nas paredes.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291165 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia3.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><br \/>\nO morador da Rua do Asfalto, Vilson de Jesus Oliveira, relatou que j\u00e1 teve o com\u00e9rcio dele invadido pela terra que desce do barranco. \u201cConvivemos diariamente com medo. A cada chuva que cai todos os moradores desse trecho ficam em alerta, pois a qualquer momento tudo pode desmoronar. Estamos nas m\u00e3os de Deus e esperando que o governo libere esse dinheiro para construir essa encosta\u201d, disse Vilson de Jesus.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291164 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-620x413.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia2.jpg 960w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"text_exposed_show\"><br \/>\nA secret\u00e1ria de Assist\u00eancia Social Alesandra Brand\u00e3o acompanhou de perto a visita e mais uma vez pediu a compreens\u00e3o do Superintendente da SUDEC com rela\u00e7\u00e3o a rapidez no processo de constru\u00e7\u00e3o do muro de conten\u00e7\u00e3o no local. \u201cO prefeito Lula Brand\u00e3o esteve no \u00faltimo m\u00eas em Bras\u00edlia, no Minist\u00e9rio de Integra\u00e7\u00e3o Nacional, em busca de recurso para resolver esse problema. Essa semana Brand\u00e3o mais uma vez foi at\u00e9 a Defesa Civil do Estado em busca de uma solu\u00e7\u00e3o. Estamos fazendo tudo que est\u00e1 ao nosso alcance e com f\u00e9 em Deus o recurso ser\u00e1 liberado o mais r\u00e1pido poss\u00edvel e essa obra sair\u00e1 do papel\u201d, disse Alesandra.<\/span><\/p>\n<p style=\"text-align: justify;\">Ascom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paulo Luz estava acompanhado do t\u00e9cnico e motorista Jos\u00e9 Helenito, al\u00e9m do coordenador de Defesa Civil do munic\u00edpio, Ronny Batista, da secret\u00e1ria de Assist\u00eancia Social, Alesandra Brand\u00e3o (e alguns funcion\u00e1rios da Assist\u00eancia Social) e do vereador e representan<\/p>\n","protected":false},"author":5,"featured_media":291163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/salomeia1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291162"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/291163"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}