{"id":291218,"date":"2019-08-04T16:35:51","date_gmt":"2019-08-04T19:35:51","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291218"},"modified":"2019-08-04T16:35:51","modified_gmt":"2019-08-04T19:35:51","slug":"sob-risco-de-perder-a-fala-general-ultra-direitista-passa-defender-maconha-medicinal","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sob-risco-de-perder-a-fala-general-ultra-direitista-passa-defender-maconha-medicinal\/","title":{"rendered":"Sob risco de perder a fala, general ultra-direitista passa defender maconha medicinal"},"content":{"rendered":"<div id=\"media-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-slider-img size-slider-img wp-post-image\" src=\"http:\/\/www.clicknoticias.com.br\/inicio\/wp-content\/uploads\/2019\/08\/cats-13-692x360.jpg\" alt=\"\" width=\"692\" height=\"360\" \/><\/p>\n<div class=\"image-wrapper\"><\/div>\n<div class=\"image-caption\"><\/div>\n<\/div>\n<div class=\"post-info\">\n<div id=\"breadcrumbs\"><\/div>\n<\/div>\n<div id=\"post-content\">\n<div class=\"dw-reactions dw-reactions-post-308077\" data-type=\"vote\" data-nonce=\"ee6dbfc3f7\" data-post=\"308077\">\n<div class=\"dw-reactions-count\"><\/div>\n<\/div>\n<p>Com uma doen\u00e7a neuromotora degenerativa, o general Eduardo Villas B\u00f4as, ex-comandante do Ex\u00e9rcito e atual assessor do GSI (Gabinete de Seguran\u00e7a Institucional) do Pal\u00e1cio do Planalto, corre risco de n\u00e3o falar mais e tem testado tecnologias para substituir o ato da fala. Em meio a outras alternativas, o militar contou em entrevista ao SBT que foi apresentado ao canabidiol \u2013 um dos 113 compostos encontrados na maconha \u2013 e, apesar de n\u00e3o us\u00e1-lo, defendeu o uso do medicamento e falou em \u201chipocrisia social\u201d ao mencionar as dificuldades de quem precisa no acesso ao tratamento<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Com uma doen\u00e7a neuromotora degenerativa, o general Eduardo Villas B\u00f4as, ex-comandante do Ex\u00e9rcito e atual assessor do GSI (Gabinete de Seguran\u00e7a Institucional) do Pal\u00e1cio do Planalto, corre risco de n\u00e3o falar mais e tem testado tecnologias para substituir o ato da fala. Em mei<\/p>\n","protected":false},"author":5,"featured_media":263643,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/general-villas-boas.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291218"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/263643"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}