{"id":291280,"date":"2019-08-05T07:54:55","date_gmt":"2019-08-05T10:54:55","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291280"},"modified":"2019-08-05T07:54:55","modified_gmt":"2019-08-05T10:54:55","slug":"homem-acusado-de-assalto-e-preso-em-remanso","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/homem-acusado-de-assalto-e-preso-em-remanso\/","title":{"rendered":"Homem acusado de assalto \u00e9 preso em Remanso"},"content":{"rendered":"<p><strong>Reda\u00e7\u00e3o<\/strong><\/p>\n<p style=\"font-weight: 400;\">Na madrugada deste domingo (04), ap\u00f3s den\u00fancias de que o indiv\u00edduo identificado por Sidnei de Souza Brito, seria o suspeito do cometimento de assaltos no interior do munic\u00edpio, uma guarni\u00e7\u00e3o policial deslocou \u00e0 localidade do Caldeir\u00e3o do Umbuzeiro, e efetuou a sua pris\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-291281 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida.jpg\" alt=\"\" width=\"550\" height=\"309\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida.jpg 550w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida-480x270.jpg 480w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<p style=\"font-weight: 400;\">Com o referido, foi encontrada uma motocicleta Honda CG Titan 150, com o chassi, e n\u00fameros do motor raspados, apresentando fortes ind\u00edcios de que seja proveniente de il\u00edcitos, e utilizada nas investidas criminosas.<\/p>\n<p style=\"font-weight: 400;\">O imputado foi encaminhado \u00e0 Delegacia de Pol\u00edcia, juntamente com a motocicleta apreendida, para a ado\u00e7\u00e3o dos procedimentos pertinentes.<\/p>\n<p>Fonte: Comando do 3\u00ba Pelot\u00e3o \/ Remanso<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o referido, foi encontrada uma motocicleta Honda CG Titan 150, com o chassi, e n\u00fameros do motor raspados, apresentando fortes ind\u00edcios de que seja proveniente<\/p>\n","protected":false},"author":5,"featured_media":291281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/moto-apreendida.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291280"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/291281"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}