{"id":291462,"date":"2019-08-07T05:44:10","date_gmt":"2019-08-07T08:44:10","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291462"},"modified":"2019-08-07T05:44:10","modified_gmt":"2019-08-07T08:44:10","slug":"alvorlande-cruz-afirma-que-retornara-em-breve","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/alvorlande-cruz-afirma-que-retornara-em-breve\/","title":{"rendered":"Alvorlande Cruz afirma que &#8216;retornar\u00e1 em breve&#8217;"},"content":{"rendered":"<p><strong>Reda\u00e7\u00e3o<\/strong><\/p>\n<p>O vereador cassado Domingos de Crist\u00e1lia\u00a0 (PSL) voltou a ocupar a cadeira mais forte politicamente depois da decis\u00e3o do TSE que suspendeu a determina\u00e7\u00e3o do Tribunal Regional Eleitoral (TRE\/PE) que cassou o seu mandato. Depois da retomada da cadeira, Domingos afirmou que seu compromisso com a popula\u00e7\u00e3o de Petrolina, mais precisamente da localidade de Crist\u00e1lia, &#8216;aumenta mais ainda&#8217;.<\/p>\n<figure id=\"attachment_13800\" aria-describedby=\"caption-attachment-13800\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13800 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Vereador-Alvorlande-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Vereador-Alvorlande-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Vereador-Alvorlande-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Vereador-Alvorlande.jpg 640w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-13800\" class=\"wp-caption-text\">Alvorlande Cruz<\/figcaption><\/figure>\n<p>J\u00e1 o suplente que n\u00e3o chegou a esquentar a cadeira, Alvorlande Cruz (PSL) afirmou que &#8220;retornar\u00e1 em breve, mesmo porque acredito na justi\u00e7a&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador cassado Domingos de Crist\u00e1lia\u00a0 (PSL) voltou a ocupar a cadeira mais forte politicamente depois da decis\u00e3o do TSE que suspendeu a determina\u00e7\u00e3o do Tribunal Regional Eleitoral (TRE\/PE) que cassou o seu mandato. Depois da retomada da cadeira, Domingos afir<\/p>\n","protected":false},"author":5,"featured_media":13800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2013\/09\/Vereador-Alvorlande.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291462"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/13800"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}