{"id":291828,"date":"2019-08-11T11:19:20","date_gmt":"2019-08-11T14:19:20","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291828"},"modified":"2019-08-11T11:19:20","modified_gmt":"2019-08-11T14:19:20","slug":"gremios-estudantis-voltam-a-crescer-nos-colegios-publicos","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/gremios-estudantis-voltam-a-crescer-nos-colegios-publicos\/","title":{"rendered":"Gr\u00eamios estudantis voltam a crescer nos col\u00e9gios p\u00fablicos"},"content":{"rendered":"<header>\n<h1 style=\"text-align: justify;\"><\/h1>\n<\/header>\n<figure class=\"horizontal\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/extra.globo.com\/incoming\/23869427-1b2-384\/w640h360-PROP\/x84035149_ri-rio-de-janeiro-rj-09-08-2019novos-gremioslocal-ciep-brizolao-129jose-maria-na.jpg.pagespeed.ic.uNlqwsguzr.jpg\" alt=\"Gr\u00eamios crescem nas escolas\" width=\"640\" height=\"360\" \/><\/p>\n<div class=\"seedtag-gohan seedtag-adunit st-in-image\">\n<div class=\"st-container\"><\/div>\n<\/div><figcaption><span class=\"credit\">Gr\u00eamios crescem nas escolas Foto: Roberto Moreyra<\/span><\/figcaption><\/figure>\n<div class=\"story\">\n<div class=\"header\" style=\"text-align: justify;\">\n<div class=\"credits info\"><span class=\"author\">Elenilce Bottari<\/span><\/div>\n<div class=\"text_size\"><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Erguido h\u00e1 36 anos, o Ciep Jos\u00e9 Maria Nanci, que atende \u00e0 comunidade da Reta Velha, uma das regi\u00f5es mais carentes de Itabora\u00ed, inaugurou na semana passada sua primeira r\u00e1dio. A emissora foi idealizada, projetada e constru\u00edda pelos oito alunos do nov\u00edssimo gr\u00eamio estudantil, com apoio de toda a escola. O programa dirigido pelos alunos vem transformando o intervalo entre as aulas num atrativo capaz de reter seus mais de 360 estudantes durante todo o turno.<\/p>\n<p style=\"text-align: justify;\">Distante dali, a cerca de 35 quil\u00f4metros, est\u00e1 o Ciep Zuzu Angel, em Arsenal, o maior e mais antigo de S\u00e3o Gon\u00e7alo, onde o tamb\u00e9m rec\u00e9m-empossado gr\u00eamio estudantil est\u00e1 fechando parceria com o Consulado do Equador para trazer curso de idiomas.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s um per\u00edodo de esvaziamento que culminou com a perman\u00eancia de apenas 136 representa\u00e7\u00f5es estudantis, no ano passado, os gr\u00eamios escolares est\u00e3o de volta ao estado e j\u00e1 ocupam 957 das 1.222 escolas p\u00fablicas estaduais. Um crescimento de mais de 600% em um ano.<\/p>\n<p style=\"text-align: justify;\">Garantidos por lei, os gr\u00eamios s\u00e3o entidades aut\u00f4nomas representativas dos interesses dos estudantes secundaristas, com finalidades educacionais, culturais, c\u00edvicas, desportivas e sociais. E agora est\u00e3o sendo considerados a maior ferramenta da Secretaria Estadual de Educa\u00e7\u00e3o para o combate \u00e0 viol\u00eancia nas escolas, ao bullying e para o desenvolvimento de pol\u00edticas que ajudem a educa\u00e7\u00e3o p\u00fablica do estado a sair do vermelho na qualidade de ensino. Segundo o \u00cdndice de Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (IDEB) de 2017 (\u00faltimo divulgado), o Rio de Janeiro est\u00e1 em 17\u00ba lugar, junto com Piau\u00ed, Amazonas e Roraima.<\/p>\n<p style=\"text-align: justify;\">\u2014 Defendemos a participa\u00e7\u00e3o do aluno como parte da solu\u00e7\u00e3o. A ideia \u00e9 que ele acompanhe o or\u00e7amento da escola, participe da escolha de programas e projetos tocados no ambiente estudantil e seja tamb\u00e9m um mediador de conflitos. A ideia \u00e9 que desde os 11 anos o aluno aprenda a mediar, porque a media\u00e7\u00e3o de conflito evita que pequenos conflitos se transformem em atos de viol\u00eancia nas escolas \u2014 diz o secret\u00e1rio estadual de Educa\u00e7\u00e3o, Pedro Fernandes.<\/p>\n<p style=\"text-align: justify;\">O novo gr\u00eamio do Ciep Zuzu Angel j\u00e1 experimentou a import\u00e2ncia da media\u00e7\u00e3o de conflitos. Quando organizou um campeonato de futebol inter-turnos, houve um princ\u00edpio de confus\u00e3o na semifinal que culminou na suspens\u00e3o da decis\u00e3o. O gr\u00eamio pediu ajuda \u00e0 coordenadora pedag\u00f3gica do Zuzu Angel, Solange Barbosa de Souza Barros, e a solu\u00e7\u00e3o foi criar um novo evento para antes da disputa.<\/p>\n<p style=\"text-align: justify;\">\u2014 Ela sugeriu que fiz\u00e9ssemos uma campanha de n\u00e3o viol\u00eancia, com a confec\u00e7\u00e3o de cartazes, faixas incentivando o respeito entre n\u00f3s, acabando com os xingamentos que acabam acirrando os \u00e2nimos \u2014 explica a diretora de esportes do gr\u00eamio, Eduarda Vianna.<\/p>\n<p style=\"text-align: justify;\">O Ciep Jos\u00e9 Maria Nanci atende aos moradores da Reta Velha, uma comunidade onde a \u00e1gua vem de fosso e n\u00e3o h\u00e1 rede de esgotos. Ali, foram criados os amigos Gabriel Bousquet e Jonathan Viana, ambos de 17 anos. No in\u00edcio do ano, criaram um projeto para combater a depress\u00e3o na escola. Foram estimulados pela diretora Arlete Alves Galv\u00e3o a formarem um gr\u00eamio na escola e ganharam a disputa entre duas chapas. Hoje, trabalham tamb\u00e9m pela integra\u00e7\u00e3o com a comunidade:<\/p>\n<p style=\"text-align: justify;\">\u2014 Fazemos campanhas de doa\u00e7\u00e3o de sangue, realizamos eventos abertos \u00e0 comunidade e estamos buscando doa\u00e7\u00f5es para realizar uma grande festa para as crian\u00e7as da comunidade. Isto vem aumentando a esperan\u00e7a de mudar a situa\u00e7\u00e3o da nossa comunidade.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s um per\u00edodo de esvaziamento que culminou com a perman\u00eancia de apenas 136 representa\u00e7\u00f5es estudantis, no ano passado, os gr\u00eamios escolares est\u00e3o de volta ao estado e j\u00e1 ocupam 957 das 1.222 escolas p\u00fablicas estaduais. Um crescimento de mais de 600% em um ano.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291828","post","type-post","status-publish","format-standard","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291828"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291828\/revisions"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}