{"id":291894,"date":"2019-08-12T08:21:06","date_gmt":"2019-08-12T11:21:06","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=291894"},"modified":"2019-08-12T08:21:06","modified_gmt":"2019-08-12T11:21:06","slug":"511-aprovados-em-concurso-da-policia-civil-de-pernambuco-iniciam-curso-de-formacao-nesta-segunda","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/511-aprovados-em-concurso-da-policia-civil-de-pernambuco-iniciam-curso-de-formacao-nesta-segunda\/","title":{"rendered":"511 aprovados em concurso da Pol\u00edcia Civil de Pernambuco iniciam Curso de Forma\u00e7\u00e3o nesta segunda"},"content":{"rendered":"<div class=\"col s12\">\n<section class=\"box-featured full-size header\">\n<h1 style=\"text-align: justify;\"><\/h1>\n<p style=\"text-align: justify;\">Os aprovados v\u00e3o refor\u00e7ar as delegacias do Estado j\u00e1 no in\u00edcio de 2020<\/p>\n<div class=\"header-information\" style=\"text-align: justify;\">\n<p>Por:\u00a0<strong class=\"responsible\">Portal FolhaPE<\/strong><\/p>\n<\/div>\n<div class=\"share-mattler\" style=\"text-align: justify;\">\n<div class=\"row mb-none\">\n<div class=\"col l6 m6 s12\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"content\" style=\"text-align: justify;\">\n<div class=\"col m6 l6 s12 medium-matler\">\n<figure><img decoding=\"async\" src=\"https:\/\/www.folhape.com.br\/obj\/0\/299737,475,80,0,0,475,365,0,0,0,0.jpg\" alt=\"Pol\u00edcia Civil\" \/><\/p>\n<div class=\"caption\">Pol\u00edcia Civil<em>Foto: Arthur Mota\/Folha de Pernambuco<\/em><\/div>\n<\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Os 511 aprovados no concurso de agente da Pol\u00edcia Civil de Pernambuco (PCPE) iniciam o Curso de Forma\u00e7\u00e3o da Academia Integrada de Defesa Social (Acides) nesta segunda-feira (12). A aula inaugural ocorre \u00e0s 9h, no Audit\u00f3rio Tabocas, do Centro de Conven\u00e7\u00f5es, em Olinda, e conta com a presen\u00e7a do governador de Pernambuco, Paulo C\u00e2mara, do secret\u00e1rio de Defesa Social, Antonio de P\u00e1dua, e do chefe da PCPE, Joselito Kehrle do Amaral.<\/p>\n<p>Em 2019, o investimento em seguran\u00e7a p\u00fablica em Pernambuco chega a R$ 4,7 bilh\u00f5es. Enquanto frequentarem a Academia, os alunos t\u00eam direito a bolsa-forma\u00e7\u00e3o de R$ 1.100. Ao fim do curso, os aprovados ficam habilitados para a nomea\u00e7\u00e3o e posse. Os aprovados v\u00e3o refor\u00e7ar as delegacias do Estado j\u00e1 no in\u00edcio de 2020.<br \/>\n<strong><br \/>\n<\/strong><br \/>\nO Curso de Forma\u00e7\u00e3o tem car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio, com 716 horas\/aula, e segue at\u00e9 27 de dezembro. O treinamento inclui disciplinas como Investiga\u00e7\u00e3o Policial; Intelig\u00eancia de Pol\u00edcia Judici\u00e1ria; Abordagem Policial; Armamento, Muni\u00e7\u00e3o e Tiro; Direitos Humanos; Criminal\u00edstica; Pr\u00e1tica Policial; e Gerenciamento de Crises e Desastres.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os 511 aprovados no concurso de agente da Pol\u00edcia Civil de Pernambuco (PCPE) iniciam o Curso de Forma\u00e7\u00e3o da Academia Integrada de Defesa Social (Acides) nesta segunda-feira (12). A aula inaugural ocorre \u00e0s 9h, no Audit\u00f3rio Tabocas, do Centro de Conven\u00e7\u00f5es, em Olinda, e conta com a presen\u00e7a do governador de Pernambuco, Paulo C\u00e2mara, do secret\u00e1rio de Defesa Social, Antonio de P\u00e1dua<\/p>\n","protected":false},"author":5,"featured_media":291895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-291894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/policia-civil-pe.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=291894"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/291894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/291895"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=291894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=291894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=291894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}