{"id":292102,"date":"2019-08-14T06:25:52","date_gmt":"2019-08-14T09:25:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=292102"},"modified":"2019-08-14T06:25:52","modified_gmt":"2019-08-14T09:25:52","slug":"missa-celebra-memoria-de-eduardo-campos-e-de-miguel-arraes","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/missa-celebra-memoria-de-eduardo-campos-e-de-miguel-arraes\/","title":{"rendered":"Missa celebra mem\u00f3ria de Eduardo Campos e de Miguel Arraes"},"content":{"rendered":"<h1 class=\"titulo-materia\" style=\"text-align: justify;\"><\/h1>\n<p class=\"mg_sutia\" style=\"text-align: justify;\"><em><strong>Ambos num 13 de agosto. Eduardo h\u00e1 cinco anos e Miguel Arraes, h\u00e1 14 anos<\/strong><\/em><\/p>\n<div id=\"noticia_dataautor\" style=\"text-align: justify;\">\n<p class=\"data-materia\">\n<\/div>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"bordaimg imgnoticia\" title=\"Renata Campos, Pedro e Jos\u00e9 participaram de missa em mem\u00f3ria de Eduardo Campos, falecido h\u00e1 cinco anos \/ Foto: Alexandre Gondim\/JC Imagem\" src=\"https:\/\/jconlineimagem.ne10.uol.com.br\/imagem\/noticia\/2019\/08\/13\/normal\/b3b6f94fda3ddc83dae3a81116e93abe.jpg\" alt=\"Renata Campos, Pedro e Jos\u00e9 participaram de missa em mem\u00f3ria de Eduardo Campos, falecido h\u00e1 cinco anos \/ Foto: Alexandre Gondim\/JC Imagem\" \/><\/p>\n<div class=\"legenda-foto\" style=\"text-align: justify;\">Renata Campos, Pedro e Jos\u00e9 participaram de missa em mem\u00f3ria de Eduardo Campos, falecido h\u00e1 cinco anos<\/div>\n<div class=\"credito-foto\" style=\"text-align: justify;\">Foto: Alexandre Gondim\/JC Imagem<\/div>\n<div class=\"campo-subassinatura\" style=\"text-align: justify;\"><span class=\"nome-subassinatura\">Angela Fernanda Belfort<\/span><\/p>\n<\/div>\n<div id=\"noticia_corpodanoticia\" class=\"t13 manipularFonte\">\n<p style=\"text-align: justify;\">O governador Paulo C\u00e2mara (PSB) disse, na noite desta ter\u00e7a-feira (13), que \u201co Brasil anda num momento t\u00e3o dif\u00edcil com discuss\u00f5es t\u00e3o pequenas e tantos desafios a serem encarados. Temos que trabalhar muito para diminuir a desigualdade e melhorar a qualidade de vida da popula\u00e7\u00e3o. Para fazer isso, \u00e9 preciso de unidade nacional. Eduardo [CAMPOS] faz falta porque ajudaria muito a formar essa unidade nacional que a gente est\u00e1 precisando hoje\u201d. Ele estava se referindo \u00e0 polariza\u00e7\u00e3o na pol\u00edtica brasileira e o depoimento ocorreu depois de uma missa realizada na Matriz de Casa Forte em mem\u00f3ria de\u00a0<a href=\"http:\/\/especiais.jconline.ne10.uol.com.br\/adeus-a-eduardo-campos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Eduardo Campos, falecido h\u00e1 cinco anos<\/a>; e de Miguel Arraes, morto h\u00e1 14 anos. Ambos faleceram no mesmo dia.<\/p>\n<p style=\"text-align: justify;\">\u201cSaudade\u201d foi a palavra mais citada por Paulo C\u00e2mara assim como pelo prefeito do Recife, Geraldo Julio (PSB). \u201c\u00c9 uma noite para celebrar o legado, os ensinamentos, e refer\u00eancia que Eduardo representa. Celebrar a saudade do futuro, uma express\u00e3o que ele usava para mostrar que acreditava num mundo melhor\u201d, comentou Geraldo Julio.<\/p>\n<p style=\"text-align: justify;\">Durante a missa, Pedro Campos lembrou que o seu bisav\u00f4, o ex-governador Miguel Arraes, dizia que a sua consci\u00eancia pol\u00edtica surgiu depois de ver a fome e a sede provocada pela seca de 1932. \u201cTemos muitas secas que precisamos ver. As secas da falta de compaix\u00e3o, da fome, da desigualdade. Esse \u00e9 um motivo para seguir em frente e imagino que era isso que Eduardo queria que a gente fizesse\u201d. Ele foi muito aplaudido pelos presentes.<\/p>\n<p style=\"text-align: justify;\">A missa foi realizada pelo padre Luciano, amigo da fam\u00edlia, que citou passagens da B\u00edblia envolvendo Mois\u00e9s. \u201cCoragem foi o que Deus disse a Mois\u00e9s. Coragem e for\u00e7a, porque vamos continuar pegando no servi\u00e7o\u201d, disse o religioso, lembrando da trajet\u00f3ria da vida de Eduardo \u2013 v\u00edtima de um acidente a\u00e9reo quando concorria \u00e0 Presid\u00eancia da Rep\u00fablica, em 2014.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\" style=\"text-align: justify;\">\n<div class=\"player_dynad_tv\"><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Ainda na celebra\u00e7\u00e3o, o religioso citou, nominalmente, todos os que estavam no avi\u00e3o \u2013 o jornalista Carlos Percol, o fot\u00f3grafo Alexandre Severo, o ex-deputado federal Pedro Valadares, o cinegrafista Marcelo Lyra e os pilotos: Geraldo Magela e Marcos Martins.<\/p>\n<h2 style=\"text-align: justify;\">PRESEN\u00c7A<\/h2>\n<p style=\"text-align: justify;\">A missa reuniu parentes, t\u00e9cnicos e ex-secret\u00e1rios ligados \u00e0 administra\u00e7\u00e3o de Eduardo Campos (2007-2011 e 2011-2014) e Miguel Arraes (1963-1964; 1987-1990 e 1995-1999). Estiveram presentes tamb\u00e9m o presidente da Assembleia Legislativa de Pernambuco, Eriberto Medeiros (PP); o presidente do Tribunal de Contas de Pernambuco, Marcos Loreto, entre outros do meio pol\u00edtico.<\/p>\n<p style=\"text-align: justify;\">Renata Campos estava acompanha por tr\u00eas dos seus cinco filhos: Pedro, Jos\u00e9 e Maria Eduarda. O filho mais velho, o deputado federal Jo\u00e3o Campos (PSB), estava em Bras\u00edlia participando das vota\u00e7\u00f5es na C\u00e2mara dos Deputados. Ele postou foto nas redes sociais de algumas homenagens que os socialistas e amigos fizeram a Eduardo no \u00faltimo fim de semana. (JC)<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ambos num 13 de agosto. Eduardo h\u00e1 cinco anos e Miguel Arraes, h\u00e1 14 anos<\/p>\n","protected":false},"author":5,"featured_media":292103,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-292102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/missa-em-memoria-de-eduardo-e-arraes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=292102"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/292103"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=292102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=292102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=292102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}