{"id":292366,"date":"2019-08-16T08:31:49","date_gmt":"2019-08-16T11:31:49","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=292366"},"modified":"2019-08-16T08:31:49","modified_gmt":"2019-08-16T11:31:49","slug":"pms-do-rio-emprestaram-caveirao-para-fotos-de-traficantes-da-serrinha","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/pms-do-rio-emprestaram-caveirao-para-fotos-de-traficantes-da-serrinha\/","title":{"rendered":"PMs do Rio &#8216;emprestaram&#8217; caveir\u00e3o para fotos de traficantes da Serrinha"},"content":{"rendered":"<header>\n<h1 style=\"text-align: justify;\"><em>Caderno do tr\u00e1fico mostra partilha de propina entre oficiais de batalh\u00e3o no Rio<\/em><\/h1>\n<\/header>\n<figure class=\"horizontal\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/extra.globo.com\/incoming\/23879429-5f4-a4b\/w640h360-PROP\/xwhatsapp-image-2019-08-15-at-13.42.00.jpeg.png.pagespeed.ic.9alJ5KvcLK.jpg\" alt=\"Fotos motivaram abertura de investiga\u00e7\u00e3o\" width=\"640\" height=\"360\" \/><figcaption><span class=\"credit\">Fotos motivaram abertura de investiga\u00e7\u00e3o<\/span><\/figcaption><\/figure>\n<div class=\"story\">\n<div class=\"header\" style=\"text-align: justify;\">\n<div class=\"credits info\"><span class=\"author\">Rafael Soares<\/span><\/div>\n<div class=\"text_size\"><\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"left\">Um caderno de anota\u00e7\u00f5es do tr\u00e1fico do Complexo da Serrinha, na Zona Norte do Rio, revela a partilha da propina entre oficiais do 9\u00ba BPM (<a class=\"news no_blog\" href=\"https:\/\/extra.globo.com\/noticias\/rio\/rocha-miranda\/\" rel=\"follow\">Rocha Miranda<\/a>). O documento foi apreendido pela pol\u00edcia em 2015, quando dois traficantes da quadrilha foram presos. Na planilha, obtida pelo EXTRA, h\u00e1 a men\u00e7\u00e3o a repasses a capit\u00e3es e tenentes, ao Grupo de A\u00e7\u00f5es T\u00e1ticas (GAT) \u2014 unidade operacional do batalh\u00e3o \u2014 e \u00e0 P2, o Servi\u00e7o Reservado do batalh\u00e3o.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Ontem, o EXTRA revelou que nove policiais militares do batalh\u00e3o \u2014 sete deles, oficiais \u2014 foram denunciados pelo Minist\u00e9rio P\u00fablico do Rio por receberem propina do tr\u00e1fico de drogas dos morros da Serrinha, Jorge Turco e do Complexo da Pedreira. Em troca, os agentes avisavam previamente os traficantes sobre opera\u00e7\u00f5es do 9\u00ba BPM. A investiga\u00e7\u00e3o teve in\u00edcio quando a Corregedoria da PM descobriu que criminosos da Serrinha tiraram fotos armados num caveir\u00e3o da unidade durante uma opera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">No caderno de anota\u00e7\u00f5es, ao lado da express\u00e3o \u201cCap\u201d, os traficantes escreveram R$ 2 mil. J\u00e1 ao lado das inscri\u00e7\u00f5es \u201c1 Ten\u201d e \u201c2 Ten\u201d, h\u00e1 a men\u00e7\u00e3o aos valores de, respectivamente, R$ 4 mil e R$ 3 mil. Segundo a investiga\u00e7\u00e3o, o montante era repartido entre os oficiais de cada patente. Ao GAT, composto por v\u00e1rios agentes, os traficantes pagavam R$ 9 mil. \u00c0 P2, R$ 4 mil. Os repasses eram semanais.<\/p>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/23880949-c8b-f09\/w448\/xserrinha.jpg.pagespeed.ic.VppJXfkxb0.jpg\" alt=\"P\u00e1gina do caderno de anota\u00e7\u00f5es do tr\u00e1fico\" \/><figcaption>P\u00e1gina do caderno de anota\u00e7\u00f5es do tr\u00e1fico<\/figcaption><\/figure>\n<p style=\"text-align: justify;\" align=\"left\">A propina era repartida em envelopes dentro do batalh\u00e3o. Em depoimento, um policial que trabalhou na se\u00e7\u00e3o de pessoal da unidade (P1) revelou que pra\u00e7as entregavam envelopes com dinheiro ao chefe do setor.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Os di\u00e1logos entre policiais e traficantes revelam como funcionava o pagamento aos agentes. Em 18 de novembro de 2014, uma opera\u00e7\u00e3o do batalh\u00e3o na Serrinha acabou com a pris\u00e3o de dois traficantes e a apreens\u00e3o de duas pistolas e um fuzil. O traficante Walace de Brito Trindade, o Lacoste, chefe do tr\u00e1fico da Serrinha, reclamou com o sargento Fl\u00e1vio Fagundes Padiglione que s\u00f3 foi informado da a\u00e7\u00e3o horas antes. &#8220;Passei a vis\u00e3o q essa semana vc n\u00e3o vai mandar nada para ningu\u00e9m&#8221;, escreveu o sargento a Lacoste.<\/p>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/23879431-68c-643\/w448\/xwhatsapp-image-2019-08-15-at-13.42.13.jpeg.png.pagespeed.ic.SUFekAKB-N.jpg\" alt=\"Traficantes armados tiraram fotos dentro de caveir\u00e3o\" \/><figcaption>Traficantes armados tiraram fotos dentro de caveir\u00e3o Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">De acordo com a conversa, os \u00fanicos que receberiam o dinheiro seriam os oficiais que passaram a informa\u00e7\u00e3o sobre a a\u00e7\u00e3o, o major Rodrigo Lavandeira Pereira e a tenente Adriana da Silva G\u00f3es Vista, chamada de &#8220;amiga&#8221; pela dupla. &#8220;J\u00e1 avisei se ficar de boa volta o normal&#8221;, diz o PM ao traficante.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">O 9\u00ba BPM, entretanto, n\u00e3o era a \u00fanica unidade na lista da propina do tr\u00e1fico da Serrinha. Numa troca de mensagens entre traficantes, um deles ordena ao outro que pague policiais do Bope que estavam na favela: \u201cCana do bope veio aqui pega o dinheiro deles. Mano, paga os cana ta bem, copiou, dinheiro deles agora \u00e9 sagrado\u201d.<\/p>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"inline\" src=\"https:\/\/extra.globo.com\/incoming\/23879430-c3a-60a\/w448\/xwhatsapp-image-2019-08-15-at-13.42.08.jpeg.png.pagespeed.ic.kFrTwT6x4y.jpg\" alt=\"Traficantes posaram tamb\u00e9m em frente \u00e0 viatura\" \/><figcaption>Traficantes posaram tamb\u00e9m em frente \u00e0 viatura<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">A ju\u00edza Ana Paula Monte Figueiredo Pena Barros, da Auditoria Militar, recebeu a den\u00fancia contra os policiais e determinou a suspens\u00e3o das fun\u00e7\u00f5es dos nove agentes. Oito deles v\u00e3o responder pelos crimes de associa\u00e7\u00e3o criminosa e corrup\u00e7\u00e3o passiva. Um foi denunciado por associa\u00e7\u00e3o para o tr\u00e1fico de drogas. A investiga\u00e7\u00e3o ainda concluiu que outros oito agentes da unidade &#8220;expuseram a perigo uma viatura policial&#8221;, j\u00e1 que traficantes da favela fizeram fotos posando armados em frente a um blindado e a uma viatura do batalh\u00e3o durante uma opera\u00e7\u00e3o que os agentes faziam no Largo da Raia, dentro da Serrinha, no dia 12 de janeiro de 2014.<\/p>\n<p style=\"text-align: justify;\">S\u00e3o r\u00e9us pelos crimes os majores Rodrigo Lavadeira Pereira e Andr\u00e9 Luiz Oliveira de Albuquerque, os capit\u00e3es Marcelo Baptista Pereira, Rodrigo Antunes Vieira e Bruno Borges Vidal, os tenentes Adriana da Silva G\u00f3es Vista e Paulo Rodolpho Batista de Oliveira e os sargentos Robson Avelino de Lima e Fl\u00e1vio Fagundes Padiglione.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Caderno do tr\u00e1fico mostra partilha de propina entre oficiais de batalh\u00e3o no Rio<\/p>\n","protected":false},"author":5,"featured_media":292367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-292366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/bandidos-com-caveirao.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=292366"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/292367"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=292366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=292366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=292366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}