{"id":292527,"date":"2019-08-19T03:19:44","date_gmt":"2019-08-19T06:19:44","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=292527"},"modified":"2019-08-19T03:19:44","modified_gmt":"2019-08-19T06:19:44","slug":"psl-cai-em-campo-ja-de-olho-em-2020","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/psl-cai-em-campo-ja-de-olho-em-2020\/","title":{"rendered":"PSL cai em campo j\u00e1 de olho em 2020"},"content":{"rendered":"<div class=\"category-content\">\n<h1 style=\"text-align: justify;\"><\/h1>\n<\/div>\n<div class=\"noticia-container m-b-2\">\n<div class=\"noticia-imagem\" style=\"text-align: justify;\"><img decoding=\"async\" title=\"PSL cai em campo j\u00e1 de olho em 2020 \" src=\"https:\/\/gncnews.com.br\/img\/crop?img=94f28383dccd83c3ac2972a5df0d9aad.jpg&amp;w=800&amp;h=400&amp;fit=crop&amp;fm=jpq&amp;q=90\" alt=\"Coluna Fogo Cruzado \u2013 17 de agosto de 2019\" \/><\/div>\n<div class=\"linha-fotografo\" style=\"text-align: justify;\">\n<p>Foto:\u00a0<strong>Divulga\u00e7\u00e3o<\/strong><\/p>\n<\/div>\n<div class=\"box\" style=\"text-align: justify;\">\n<div class=\"row\">\n<div class=\"col-md-6 col-sm-12 col-xs-12\">\n<div class=\"infos\"><span class=\"data\"><strong><i class=\"ti-calendar\"><\/i>\u00a0<\/strong><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"noticia-texto\">\n<p style=\"text-align: justify;\">No embalo da campanha de Bolsonaro, o Partido Social Liberal (PSL) conseguiu eleger quatro senadores e 54 deputados federais nas elei\u00e7\u00f5es do ano passado, perdendo apenas para o PT em n\u00famero de representantes na C\u00e2mara Federal. Pegaram carona na campanha do \u201ccapit\u00e3o\u201d e se deram bem delegados das Pol\u00edcias Civil e Federal, militares da ativa e da reserva das PMs e das For\u00e7as Armadas, etc. Uma das exce\u00e7\u00f5es foi Pernambuco, onde o \u201cbolsonarismo\u201d n\u00e3o conseguiu eleger o coronel Luiz Meira para a C\u00e2mara Federal porque \u00e0 \u00faltima hora tomaram-lhe o partido, obrigando-o a se abrigar em outra legenda.<\/p>\n<p style=\"text-align: justify;\">Apenas o presidente nacional,\u00a0<strong>Luciano Bivar<\/strong>, foi eleito para a C\u00e2mara Federal, ficando PSL sem nenhum representante na Assembleia Legislativa. Por isso o prop\u00f3sito dos seus dirigentes \u00e9 correr atr\u00e1s do preju\u00edzo nas elei\u00e7\u00f5es do pr\u00f3ximo ano lan\u00e7ando candidatos a prefeito nos principais col\u00e9gios eleitorais de Pernambuco, incluindo Recife, Jaboat\u00e3o, Caruaru e Petrolina. A preliminar ser\u00e1 a campanha de filia\u00e7\u00e3o que Bivar deflagra neste s\u00e1bado (17), no Recife, esperando fortalecer o partido com pelo menos 500 novos quadros na capital e no interior. (Inaldo Sampaio)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No embalo da campanha de Bolsonaro, o Partido Social Liberal (PSL) conseguiu eleger quatro senadores e 54 deputados federais nas elei\u00e7\u00f5es do ano passado, perdendo apenas para o PT em n\u00famero de representantes na C\u00e2mara Federal. Pegaram carona na camp<\/p>\n","protected":false},"author":5,"featured_media":243046,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-292527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/05\/bivar.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=292527"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/243046"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=292527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=292527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=292527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}