{"id":292532,"date":"2019-08-19T04:55:15","date_gmt":"2019-08-19T07:55:15","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=292532"},"modified":"2019-08-19T04:55:15","modified_gmt":"2019-08-19T07:55:15","slug":"policia-apreende-veiculo-e-prende-homem-em-lagoa-grande-por-pertubacao-do-sossego","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/policia-apreende-veiculo-e-prende-homem-em-lagoa-grande-por-pertubacao-do-sossego\/","title":{"rendered":"Policia apreende ve\u00edculo e prende homem em Lagoa Grande por pertuba\u00e7\u00e3o do sossego"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Reda\u00e7\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">No \u00faltimo s\u00e1bado (17), por volta 22h30m, policiais militares estavam fazendo rondas com abordagens no munic\u00edpio de Lagoa Grande quando foram informados por populares, que havia uma moto, com o escape adulterado, fazendo muito barulho pela cidade, atrapalhando assim o sossego das pessoas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93397 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/lagoa-grande.jpg\" alt=\"\" width=\"273\" height=\"184\" \/><\/p>\n<p style=\"text-align: justify;\">Diante dos fatos a guarni\u00e7\u00e3o fez deslocamento no sentido indicado pelas pessoas e conseguiu identificar a moto, uma CG Honda, de cor Vermelha, Placa NTQ 1660, juntamente com o condutor, a pessoa de Allan Felipe de Ara\u00fajo Valen\u00e7a de 30 anos, residente no projeto Senador Nilo Coelho (N5). Logo ap\u00f3s a abordagem, o ve\u00edculo e o condutor foram encaminhados a Delegacia de Plant\u00e3o local para que fossem tomadas as medidas cab\u00edveis, resultando em um TCO.<\/p>\n<p style=\"text-align: justify;\">Fonte: SDS &#8211; PMPE &#8211; DPO &#8211; DINTER II \u2013 7\u00aa CIPM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diante dos fatos a guarni\u00e7\u00e3o fez deslocamento no sentido indicado pelas pessoas e conseguiu identificar a moto, uma CG Honda, de cor Vermelha, Placa NTQ 1660, juntamente com o condutor, a pessoa de Allan Felipe de Ara\u00fajo Valen\u00e7a de 30 anos, residente no projeto S<\/p>\n","protected":false},"author":5,"featured_media":93397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-292532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2015\/11\/lagoa-grande.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=292532"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/93397"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=292532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=292532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=292532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}