{"id":292741,"date":"2019-08-21T08:10:11","date_gmt":"2019-08-21T11:10:11","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=292741"},"modified":"2019-08-21T08:10:11","modified_gmt":"2019-08-21T11:10:11","slug":"manuela-marinho-visita-petrolina-apos-ser-empossada-presidente-da-compesa","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/manuela-marinho-visita-petrolina-apos-ser-empossada-presidente-da-compesa\/","title":{"rendered":"Manuela Marinho visita Petrolina ap\u00f3s ser empossada presidente da Compesa"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Em seu segundo dia de trabalho \u00e0 frente da Companhia Pernambucana de Saneamento &#8211; Compesa, a presidente Manuela Marinho chegou, no final desta tarde (20), \u00e0 Petrolina, no sert\u00e3o do Estado, onde participa, amanh\u00e3 (21), do Programa Todos por Pernambuco, ao lado do governador Paulo C\u00e2mara e da Secret\u00e1ria de Infraestrutura e Recursos H\u00eddricos, Fernandha Batista. Em sua primeira visita ao munic\u00edpio como presidente da Compesa, Manuela fez quest\u00e3o de conhecer a Esta\u00e7\u00e3o de Tratamento de \u00c1gua Vit\u00f3ria, situada no Distrito Industrial.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-292742 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho.jpg 1024w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A ETA Vit\u00f3ria \u00e9 considerada uma das mais modernas unidades de tratamento de Pernambuco. Assim que desembarcou na cidade ao final da tarde, Manuela, acompanhada da diretora Regional de Interior, Simone Albuquerque, e de t\u00e9cnicos da Compesa, visitou o empreendimento. A ETA Vit\u00f3ria, que foi inaugurada no primeiro governo Paulo C\u00e2mara, tem a certifica\u00e7\u00e3o ambiental ISO 14.001 (Gest\u00e3o Ambiental) e foi um dos primeiros equipamentos de saneamento do Estado certificados na vers\u00e3o 2015.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Essa unidade ampliou em 60% a oferta de \u00e1gua na cidade, garantindo um incremento na vaz\u00e3o di\u00e1ria de mais de 400 litros por segundo. Cinco novos reservat\u00f3rios e tr\u00eas esta\u00e7\u00f5es de bombeamento foram constru\u00eddos para integrar o sistema, num investimento total de R$ 65 milh\u00f5es.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Com essa obra, Petrolina passou a ter um robusto sistema de abastecimento de \u00e1gua, que conta ainda com a ETA 1, localizada no Centro, e a ETA 2, no Distrito Industrial. Juntos, os sistemas t\u00eam uma produ\u00e7\u00e3o de 1.070 litros por segundo, o que garante aos petrolinenses uma situa\u00e7\u00e3o privilegiada de abastecimento de \u00e1gua, sem rod\u00edzio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em seu segundo dia de trabalho \u00e0 frente da Companhia Pernambucana de Saneamento &#8211; Compesa, a presidente Manuela Marinho chegou, no final desta tarde (2<\/p>\n","protected":false},"author":5,"featured_media":292742,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-292741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/manuela-marinho.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=292741"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/292741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/292742"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=292741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=292741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=292741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}