{"id":293020,"date":"2019-08-23T10:56:12","date_gmt":"2019-08-23T13:56:12","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=293020"},"modified":"2019-08-23T10:56:12","modified_gmt":"2019-08-23T13:56:12","slug":"finlandia-pede-que-uniao-europeia-pare-de-importar-de-carne-do-brasil-por-queimadas","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/finlandia-pede-que-uniao-europeia-pare-de-importar-de-carne-do-brasil-por-queimadas\/","title":{"rendered":"Finl\u00e2ndia pede que Uni\u00e3o Europeia pare de importar de carne do Brasil por queimadas"},"content":{"rendered":"<div class=\"preview-read\">\n<div class=\"preview-content\">\n<h1><\/h1>\n<div class=\"social-read\"><\/div>\n<\/div>\n<\/div>\n<div class=\"img-destaque\"><\/div>\n<div class=\"code-block code-block-4\">\n<div><\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-230271 lazyloaded\" src=\"https:\/\/controle.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto-600x306.jpg\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" srcset=\"https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto-600x306.jpg 600w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto.jpg 637w\" alt=\"\" width=\"600\" height=\"306\" data-srcset=\"https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto-600x306.jpg 600w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto.jpg 637w\" data-src=\"https:\/\/controle.esmaelmorais.com.br\/wp-content\/uploads\/2019\/08\/amazonia-pasto-600x306.jpg\" \/>O governo da Finl\u00e2ndia, que est\u00e1 na Presid\u00eancia rotativa da Uni\u00e3o Europeia, pediu que o bloco avalie a possibilidade de banir a carne bovina do Brasil devido \u00e0 devasta\u00e7\u00e3o causada pelas queimadas na Amaz\u00f4nia.<\/p>\n<p>\u201cO ministro das Finan\u00e7as, Mika Lintila, condena a destrui\u00e7\u00e3o da Floresta Amaz\u00f4nica e sugere que a UE e a Finl\u00e2ndia devem considerar urgentemente a possibilidade de banir a importa\u00e7\u00e3o de carne bovina brasileira\u201d, informou o o minist\u00e9rio em comunicado.<\/p>\n<p><em>A informa\u00e7\u00e3o \u00e9 da\u00a0<a href=\"https:\/\/br.reuters.com\/article\/worldNews\/idBRKCN1VD1A1-OBRWD\">Ag\u00eancia Reuters<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO ministro das Finan\u00e7as, Mika Lintila, condena a destrui\u00e7\u00e3o da Floresta Amaz\u00f4nica e sugere que a UE e a Finl\u00e2ndia devem considerar urgentemente a possibilid<\/p>\n","protected":false},"author":5,"featured_media":293021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-293020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/08\/gado-na-amazonia.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=293020"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/293021"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=293020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=293020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=293020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}