{"id":293230,"date":"2019-08-26T05:17:43","date_gmt":"2019-08-26T08:17:43","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=293230"},"modified":"2019-08-26T05:17:43","modified_gmt":"2019-08-26T08:17:43","slug":"a-briga-pela-direcao-do-pt-pernambucano","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/a-briga-pela-direcao-do-pt-pernambucano\/","title":{"rendered":"A briga pela dire\u00e7\u00e3o do PT pernambucano"},"content":{"rendered":"<div class=\"category-content\">\n<h1 style=\"text-align: justify;\">Com os mesmos 13 j\u00e1 teria lucro<\/h1>\n<\/div>\n<p style=\"text-align: justify;\">\n<div class=\"noticia-container m-b-2\">\n<div class=\"noticia-imagem\" style=\"text-align: justify;\"><img decoding=\"async\" title=\"Com os mesmos 13 j\u00e1 teria lucro\" src=\"https:\/\/gncnews.com.br\/img\/crop?img=a8511fcd8117468ab13ca5f85fd6cf51.jpeg&amp;w=800&amp;h=400&amp;fit=crop&amp;fm=jpq&amp;q=90\" alt=\"Coluna Fogo Cruzado \u2013 24 de agosto de 2019\" \/><\/div>\n<div class=\"box\" style=\"text-align: justify;\">\n<div class=\"row\">\n<div class=\"col-md-6 col-sm-12 col-xs-12\">\n<div class=\"infos\"><span class=\"data\"><strong><i class=\"ti-calendar\"><\/i>\u00a0<\/strong><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"noticia-texto\">\n<p style=\"text-align: justify;\">Seis chapas est\u00e3o inscritas para disputar agora em outubro o controle do PT pernambucano, que praticamente ficou \u00f3rf\u00e3o ap\u00f3s a ren\u00fancia do presidente Bruno Ribeiro. As de maior visibilidade t\u00eam como patrocinadores o senador Humberto Costa e a deputada\u00a0<strong>Mar\u00edlia Arraes<\/strong>. O senador j\u00e1 definiu o seu candidato \u2013 o deputado estadual Doriel Barros, ex-presidente da Fetape, com apoio do deputado federal Carlos Veras, da deputada estadual Dulcicleide Amorim e do secret\u00e1rio Dilson Peixoto (Agricultura). Todos pertencem \u00e0 corrente \u201cConstruindo um novo Brasil\u201d, que \u00e9 a mesma do ex-presidente Lula e sempre foi majorit\u00e1ria em Pernambuco.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 Mar\u00edlia Arraes tem como candidata a deputada Teresa Leit\u00e3o, ex-presidente do Sintepe, que \u00e9 apoiada pela vereadora Cristina Costa (Petrolina) e o ex-vereador M\u00facio Magalh\u00e3es (Recife). O problema com que o PT se defronta no momento \u00e9 a constru\u00e7\u00e3o de um discurso para as elei\u00e7\u00f5es municipais. Pela \u00e9tica na pol\u00edtica, contra o governo Bolsonaro e por crescimento com justi\u00e7a social? \u00c9 pouco para sensibilizar os opositores do atual governo. O partido elegeu 13 prefeitos em Pernambuco em 2016 e se sair das urnas de 2020 com o mesmo n\u00famero de prefeituras, ter\u00e1 obtido uma excelente vit\u00f3ria. (Inaldo Sampaio)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seis chapas est\u00e3o inscritas para disputar agora em outubro o controle do PT pernambucano, que praticamente ficou \u00f3rf\u00e3o ap\u00f3s a ren\u00fancia do presidente Bruno Ribeiro. As de maior visibilidade t\u00eam como patrocinadores o senador Humberto Costa e a deputada\u00a0Mar\u00edlia A<\/p>\n","protected":false},"author":5,"featured_media":240407,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-293230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/04\/Marilia-Arraes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=293230"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/240407"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=293230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=293230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=293230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}