{"id":293752,"date":"2019-08-30T15:12:46","date_gmt":"2019-08-30T18:12:46","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=293752"},"modified":"2019-08-30T15:12:46","modified_gmt":"2019-08-30T18:12:46","slug":"apos-queixas-na-alepe-rodrigo-novaes-diz-que-houve-equivoco-da-pasta","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/apos-queixas-na-alepe-rodrigo-novaes-diz-que-houve-equivoco-da-pasta\/","title":{"rendered":"Ap\u00f3s queixas na Alepe, Rodrigo Novaes diz que houve \u2018equ\u00edvoco\u2019 da pasta"},"content":{"rendered":"<div class=\"content-banner-principal\">\n<div class=\"container publicidade\">\n<div class=\"col-md-12\">\n<div class=\"publicidade-label\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row main\">\n<div class=\"container\">\n<section class=\"col-md-8 col-sm-8\">\n<article id=\"post-219009\" class=\"box-noticias box-interna\">\n<header>\n<figure><img decoding=\"async\" class=\"img-responsive\" title=\"Foto: Jarbas Ara\u00fajo\/Divulga\u00e7\u00e3o\" src=\"https:\/\/imagens1.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2018\/05\/rodrigo-novaes-748x410.jpg\" alt=\"Foto: Jarbas Ara\u00fajo\/Divulga\u00e7\u00e3o\" \/><figcaption>Foto: Jarbas Ara\u00fajo\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<div id=\"texto-noticia\">\n<p><a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/08\/29\/na-alepe-deputados-se-queixam-de-rodrigo-novaes\/\">Depois que deputados da base do governo Paulo C\u00e2mara (PSB) expuseram insatisfa\u00e7\u00e3o com o secret\u00e1rio estadual de Turismo, Rodrigo Novaes (PSD)<\/a>, o gestor da pasta resolveu responder, em nota, \u00e0s cr\u00edticas feitas na Assembleia Legislativa de Pernambuco (Alepe). As queixas giravam entorno de eventos da secretaria em bases eleitorais dos parlamentares.<\/p>\n<p>Os deputados Ant\u00f4nio Moraes (PP) e Rog\u00e9rio Le\u00e3o (PL) \u2013 que apesar do seu partido ser de oposi\u00e7\u00e3o, integra o grupo pol\u00edtico do deputado federal Sebasti\u00e3o Oliveira (PL), aliado de Paulo C\u00e2mara \u2013 puxaram o coro das cr\u00edticas.<\/p>\n<p>Moraes relatou uma cerim\u00f4nia da pasta em Timba\u00faba, na Mata Norte, com a presen\u00e7a de Novaes.<\/p>\n<p>\u201cO secret\u00e1rio n\u00e3o teve o respeito de telefonar para o parlamentar que \u00e9 majorit\u00e1rio no munic\u00edpio. S\u00f3 foi enviado um convite \u00e0 noite, na v\u00e9spera do evento\u201d, afirmou Ant\u00f4nio. \u201cEspero que essa rela\u00e7\u00e3o mude com o\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/08\/26\/nilton-mota-deixa-casa-civil-e-vai-para-a-perpart-jose-neto-assume-a-vaga\/\">novo secret\u00e1rio da Casa Civil, Jos\u00e9 Neto<\/a>\u201d, completou.<\/p>\n<p>O chefe da pasta de Turismo, que tamb\u00e9m \u00e9 deputado licenciado da Assembleia, disse que houve um \u201cequ\u00edvoco\u201d da sua equipe ap\u00f3s, em primeiro momento, ter preferido n\u00e3o se pronunciar.<\/p>\n<p><em>\u201cNa \u00faltima quarta feira a secretaria de turismo do governo do estado esteve presente no munic\u00edpio de Macaparana participando do semin\u00e1rio Bora Pernambucar. L\u00e1 estavam presentes prefeitos e representantes de munic\u00edpios da regi\u00e3o da Mata Norte.<\/em><\/p>\n<p><em>Por equ\u00edvoco da nossa equipe, o deputado Ant\u00f4nio Moraes somente foi avisado um dia antes.<\/em><\/p>\n<p><em>Devo registrar que o erro n\u00e3o representa nenhum tipo de desprest\u00edgio do deputado, ou desaten\u00e7\u00e3o. Sou colega do deputado Ant\u00f4nio Moraes nessas tr\u00eas \u00faltimas legislaturas. Tenho por ele grande estima, e admiro o papel importante que desempenha como parlamentar da base do governo na Assembleia\u201d.<\/em><\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO secret\u00e1rio n\u00e3o teve o respeito de telefonar para o parlamentar que \u00e9 majorit\u00e1rio no munic\u00edpio. S\u00f3 foi enviado um convite \u00e0 noite, na v\u00e9spera do evento\u201d, afirmou Ant\u00f4nio. \u201cEspero que essa rela\u00e7\u00e3o mude com o\u00a0novo secret\u00e1rio da Casa Civil, Jos\u00e9 Neto\u201d, completou.<\/p>\n","protected":false},"author":5,"featured_media":237084,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-293752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/03\/rodrigo-novaes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=293752"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/293752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/237084"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=293752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=293752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=293752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}