{"id":294081,"date":"2019-09-04T07:21:10","date_gmt":"2019-09-04T10:21:10","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=294081"},"modified":"2019-09-04T07:21:10","modified_gmt":"2019-09-04T10:21:10","slug":"sindacucar-pe-critica-aumento-em-importacoes-de-etanol-dos-eua","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sindacucar-pe-critica-aumento-em-importacoes-de-etanol-dos-eua\/","title":{"rendered":"Sinda\u00e7ucar-PE critica aumento em importa\u00e7\u00f5es de etanol dos EUA"},"content":{"rendered":"<header>\n<div class=\"data-post\">\n<div class=\"data-extenso\"><\/div>\n<\/div>\n<figure><img decoding=\"async\" class=\"img-responsive\" title=\"Foto: Pixabay\" src=\"https:\/\/imagens1.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2019\/09\/cana-jconline.jpg\" alt=\"Foto: Pixabay\" \/><figcaption>Foto: Pixabay<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<h1 class=\"titulo-noticia titulo-noticia-interna\"><\/h1>\n<div id=\"texto-noticia\">\n<p>O presidente do Sindicato da Ind\u00fastria do A\u00e7\u00facar e do \u00c1lcool no Estado de Pernambuco (Sinda\u00e7\u00facar-PE), Renato Cunha, criticou a decis\u00e3o do governo Jair Bolsonaro de aumentar a cota de importa\u00e7\u00e3o de cana-de-a\u00e7\u00facar dos Estados Unidos.<\/p>\n<p><a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/09\/03\/silvio-costa-filho-critica-aumento-da-cota-de-importacao-de-etanol-dos-eua\/\">A medida tamb\u00e9m foi criticada, mais cedo, pelo deputado federal Silvio Costa Filho (Republicanos-PE)<\/a>. O presidente da Federa\u00e7\u00e3o dos Plantadores de Cana do Brasil (Feplana), Alexandre Andrade Lima,\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/09\/03\/fornecedores-de-cana-esperam-contrapartida-apos-liberacao-de-mais-etanol-sem-imposto-para-eua\/\">tamb\u00e9m reagiu<\/a>.<\/p>\n<p>Para Renato: \u201dO Brasil assumiu com os seus produtores, h\u00e1 dois anos passados, um compromisso que essa isen\u00e7\u00e3o de 600 milh\u00f5es de litros por ano \u2013 que n\u00e3o tem contrapartida em cota para aumentarmos exporta\u00e7\u00e3o de a\u00e7\u00facar para refinarias americanas, n\u00e3o iria ser renovada, o que foi defendido pelos minist\u00e9rios da Economia e Agricultura, e agora fizeram com amplia\u00e7\u00e3o, prejudicando frontalmente o Nordeste e mais de 250 mil diretor empregos formais\u201d.<\/p>\n<p>Cunha complementa: \u201cN\u00e3o temos sequer uma explica\u00e7\u00e3o l\u00f3gica do porqu\u00ea desse aumento de ren\u00fancia fiscal de cerca de R$270 milh\u00f5es. N\u00e3o \u00e9 poss\u00edvel entender que conta o Governo Federal fez para abrir m\u00e3o de tarifa de 750 milh\u00f5es de litros ou mais de 25% do que era no ciclo passado\u201d.<\/p>\n<p>Para Renato, que tamb\u00e9m \u00e9 presidente Executivo da Associa\u00e7\u00e3o de Produtores de A\u00e7\u00facar, Etanol e Energia (Novabio), \u201co governo precisa rever ou alavancar uma reciprocidade\u201d, finalizou.<\/p>\n<h2>Decreto<\/h2>\n<p>De acordo com portaria do Minist\u00e9rio da Economia, publicada em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial da Uni\u00e3o (DOU) do \u00faltimo s\u00e1bado (31), o Brasil poder\u00e1 exportar at\u00e9 750 milh\u00f5es litros de etanol dos EUA.<\/p>\n<p>A cota anterior, vencida na \u00faltima sexta-feira (30), era de 600 milh\u00f5es de litros de etanol por ano.<\/p>\n<p>As importa\u00e7\u00f5es ficam, assim, limitadas a 187,5 milh\u00f5es de litros por trimestre, de acordo com portaria do Minist\u00e9rio da Economia e da Secretaria Especial de Com\u00e9rcio Exterior e Assuntos Internacionais.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\">\n<div class=\"player_dynad_tv\"><\/div>\n<\/div>\n<p>A expans\u00e3o da quantidade de \u00e1lcool importada atendeu a um pedido feito pelos Estados Unidos durante a visita do presidente Jair Bolsonaro (PSL) ao pa\u00eds.<\/p>\n<p>O imposto de importa\u00e7\u00e3o para o etanol \u00e9 de 20% atualmente. Contudo, o produto s\u00f3 \u00e9 tarifado se o pa\u00eds ultrapassar o volume estipulado como isento. Dentro do limite, a tarifa \u00e9 zero para qualquer pa\u00eds.<\/p>\n<h2>Negocia\u00e7\u00f5es<\/h2>\n<p>A medida foi discutida entre os minist\u00e9rios da Agricultura, da Economia e das Rela\u00e7\u00f5es Exteriores. A pasta da Agricultura era contra a expans\u00e3o da cota dos EUA. A nova cota j\u00e1 est\u00e1 em vigor, e vale por 12 meses.<\/p>\n<p>Segundo informa\u00e7\u00f5es do jornal O Globo, os dados de 2018 d\u00e3o conta de que 99,7% das importa\u00e7\u00f5es brasileiras de etanol v\u00eam dos Estados Unidos.<\/p>\n<p>A medida veio depois de uma reuni\u00e3o de Donald Trump com o chanceler brasileiro Eduardo Ara\u00fajo e o deputado federal Eduardo Bolsonaro (PSL-SP). Filho do presidente, Eduardo foi indicado pelo pr\u00f3prio pai para assumir a embaixada do Brasil em Washington.<\/p>\n<p>O novo limite foi estabelecido ap\u00f3s negocia\u00e7\u00f5es lideradas pela ministra da Agricultura, Teresa Cristina, respaldada pelo presidente Jair Bolsonaro.<\/p>\n<p>As condi\u00e7\u00f5es em troca da cota envolveriam \u201cabertura do mercado americano de a\u00e7\u00facar, um dos mais protegidos do mundo, e a implementa\u00e7\u00e3o efetiva do E15 (mistura de 15% de etanol na gasolina, versus os 10% atuais) nos Estados Unidos\u201d.<\/p>\n<p>Mesmo com a eleva\u00e7\u00e3o da cota para importa\u00e7\u00f5es, uma associa\u00e7\u00e3o de produtores de biocombust\u00edveis dos Estados Unidos criticou a decis\u00e3o do governo brasileiro. Os produtores estrangeiros definiram a medida como \u201cdesapontadora\u201d porque \u201cmant\u00e9m barreira comercial protecionista contra o etanol dos EUA\u201d.<\/p>\n<p>\u201cA simb\u00f3lica eleva\u00e7\u00e3o da cota n\u00e3o ajuda em nada os consumidores brasileiros que enfrentam pre\u00e7os mais altos de combust\u00edveis por causa da pol\u00edtica discriminat\u00f3ria do Brasil\u201d, afirmou em nota a Renewable Fuels Association (RFA).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para Renato, que tamb\u00e9m \u00e9 presidente Executivo da Associa\u00e7\u00e3o de Produtores de A\u00e7\u00facar, Etanol e Energia (Novabio), \u201co governo precisa rever ou alavanca<\/p>\n","protected":false},"author":5,"featured_media":294082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-294081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/canavial1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=294081"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/294082"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=294081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=294081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=294081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}