{"id":294475,"date":"2019-09-07T05:18:42","date_gmt":"2019-09-07T08:18:42","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=294475"},"modified":"2019-09-07T05:18:42","modified_gmt":"2019-09-07T08:18:42","slug":"la-e-lo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/la-e-lo\/","title":{"rendered":"L\u00e1 e l\u00f4"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-284081 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-620x340.jpg\" alt=\"\" width=\"620\" height=\"340\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-620x340.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-300x164.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-93x50.jpg 93w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-160x88.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-225x123.jpg 225w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina-640x351.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/bezerra-e-bolsonaro-em-petrolina.jpg 748w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Ao devolver ao senador Fernando Bezerra Coelho o controle do diret\u00f3rio do MDB em Petrolina, o presidente da executiva estadual, Raul Henry, deixou setores das Princesas com uma pulga atr\u00e1s da orelha. \u00c9 que Henry pode vir a ser apadrinhado por FBC, numa casadinha com Jarbas Vasconcelos, para concorrer \u00e0 presid\u00eancia nacional do partido contra Baleia Rossi (SP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao devolver ao senador Fernando Bezerra Coelho o controle do diret\u00f3rio do MDB em Petrolina, o presidente da executiva estadual, Raul Henry, deixou setor<\/p>\n","protected":false},"author":5,"featured_media":286764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-294475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/06\/bezerra-preocupado.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=294475"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/286764"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=294475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=294475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=294475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}