{"id":294699,"date":"2019-09-09T10:21:31","date_gmt":"2019-09-09T13:21:31","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=294699"},"modified":"2019-09-09T10:23:14","modified_gmt":"2019-09-09T13:23:14","slug":"na-semana-do-administrador-facape-realiza-palestra-gratuita-sobre-empreendedorismo-gestao-e-inovacao","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/na-semana-do-administrador-facape-realiza-palestra-gratuita-sobre-empreendedorismo-gestao-e-inovacao\/","title":{"rendered":"Na Semana do Administrador, Facape realiza palestra gratuita sobre empreendedorismo, gest\u00e3o e inova\u00e7\u00e3o"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Com o tema Tecnologia e Gera\u00e7\u00e3o de Neg\u00f3cios na Era Digital, ter\u00e1 in\u00edcio \u00e0s 19h desta segunda-feira (09\/09), a Semana do Administrador da FACAPE \u2013 Faculdade de Ci\u00eancias Aplicadas e Sociais de Petrolina. Ao todo ser\u00e3o realizados 13 eventos entre palestras, oficinas e minicursos, todos gratuitos, at\u00e9 quarta-feira, 11\/09. Na abertura, o palestrante Guilherme Alves vai falar sobre Mindset de Startup e Novos Modelos de Neg\u00f3cios. A palestra ser\u00e1 no audit\u00f3rio central da Facape.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-294700 size-full\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/facape.jpg\" alt=\"\" width=\"448\" height=\"299\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/facape.jpg 448w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/facape-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/facape-160x106.jpg 160w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O evento \u00e9 realizado todos os anos em comemora\u00e7\u00e3o ao dia do administrador, que \u00e9 o dia 09 de setembro. Florisvalto Cavalcanti dos Santos, coordenador do Curso de Administra\u00e7\u00e3o da FACAPE, destacou o p\u00fablico para o qual as atividades da semana de do administrador s\u00e3o voltadas.\u00a0<i>\u201cO nosso p\u00fablico alvo s\u00e3o estudantes de gradua\u00e7\u00e3o da nossa institui\u00e7\u00e3o e tamb\u00e9m de outras institui\u00e7\u00f5es de ensino superior, mas tamb\u00e9m \u00e9 voltado para estudantes do ensino m\u00e9dio que j\u00e1 pretendem entrar no mercado de trabalho e assim ter uma prepara\u00e7\u00e3o melhor. Al\u00e9m desses dois p\u00fablicos, temos tamb\u00e9m os profissionais de administra\u00e7\u00e3o que atuam na \u00e1rea, como auxiliares, assistentes, analistas, gerentes&#8230; as pessoas que trabalham na \u00e1rea de uma maneira geral tamb\u00e9m \u00e9 nosso p\u00fablico alvo\u201d<\/i>, frisou Florisvalto Cavalcanti.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\u00e3o e especialista em Food Service e Jo\u00e3o Neves, empreendedor, graduado em marketing e em engenharia de produ\u00e7\u00e3o, de uma maneira leve e descontra\u00edda, far\u00e3o uma reflex\u00e3o sobre os principais desafios e oportunidades no mundo dos neg\u00f3cios e a import\u00e2ncia de se trabalhar em algo que voc\u00ea acredita e se apaixona.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><i>\u201cA gente vai fazer essa correla\u00e7\u00e3o entre o que \u00e9 empreender, a trajet\u00f3ria do empreendedorismo, modelo de neg\u00f3cios e gest\u00e3o e a inova\u00e7\u00e3o, chegando a economia digital. Vamos mostrar toda a trajet\u00f3ria de Waldir J\u00fanior, algu\u00e9m que come\u00e7ou pequeninho, l\u00e1 na cidade de Senhor do Bonfim, como vendedor ambulante e que chega a ser um dos maiores empreendedores do Vale do S\u00e3o Francisco\u201d,\u00a0<\/i>destaca o professor da Facape Rinaldo Moraes, que vai mediar essa palestra.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Rinaldo convida os empreendedores da regi\u00e3o e tamb\u00e9m as pessoas quem pretendem montar seu pr\u00f3prio neg\u00f3cio para participar do evento.\u00a0<i>\u201cN\u00f3s estamos convidando toda sociedade de Juazeiro e Petrolina, os empreendedores, senhoras donas de casa que queira empreender, para conhecer a Facape e no dia 11 de setembro, quarta-feira, \u00e0s 19h, no audit\u00f3rio central, participar desse encontro buscando ideias novas, modelos de gest\u00e3o e empreendedorismo\u201d<\/i>, refor\u00e7ou Rinaldo Moraes.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">As inscri\u00e7\u00f5es s\u00e3o gratuitas e s\u00e3o feitas somente pela internet no site:\u00a0<a href=\"http:\/\/www.even3.com.br\/semadm2019\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">www.even3.com.br\/semadm2019<\/a>\u00a0. Outras informa\u00e7\u00f5es podem ser obtidas pelo telefone:\u00a0<a title=\"Ligar pelo Hangouts\" href=\"https:\/\/www.google.com\/search?q=facape+petrolina&amp;rlz=1C1CHZL_pt-BRBR696BR696&amp;sxsrf=ACYBGNQM_iKpq3gMxBzegwHF_QGvkHgi6Q:1568022785285&amp;source=lnms&amp;sa=X&amp;ved=0ahUKEwjokfeIvMPkAhUwDrkGHYBCCnEQ_AUIDCgA&amp;biw=1366&amp;bih=576&amp;dpr=1\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">(87) 3866-3200<\/a>.\u00a0Apesar de n\u00e3o pagar nada para se inscrever, a coordena\u00e7\u00e3o est\u00e1 sugerindo a doa\u00e7\u00e3o e 1 kg de alimento n\u00e3o perec\u00edvel. Os alimentos arrecadados ser\u00e3o destinados para a ONG Rua de Baixo, que funciona em Petrolina.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">ONG Rua de Baixo<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Rua De Baixo \u00e9 uma organiza\u00e7\u00e3o n\u00e3o governamental que tem como principal miss\u00e3o erradicar a extrema pobreza das comunidades carentes, atuando a curto, m\u00e9dio e longo prazos. O grupo atende demandas urgentes como a necessidade de alimentos, rem\u00e9dios, roupas, materiais escolares, etc. A m\u00e9dio e longo prazos, busca parcerias e financiamentos de iniciativas privadas para proporcionar mini-cursos gratuitos a pessoas que moram em comunidades carentes, como cursos para barbeiro e manicure. Assim, al\u00e9m de doar alimentos atendendo a demanda urgente, as pessoas s\u00e3o capacitadas para que elas mesmas comprem seus mantimentos. O Rua de Baixo abra\u00e7a v\u00e1rias causas como vulnerabilidade social, combate \u00e0 pobreza, educa\u00e7\u00e3o, idosos, m\u00fasica, pessoas em situa\u00e7\u00e3o de rua e dependentes qu\u00edmicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das palestras mais esperadas \u00e9 a Conversando Sobre Empreendedorismo, Gest\u00e3o e Inova\u00e7\u00e3o: pede a\u00ed uma solu\u00e7\u00e3o!, que ser\u00e1 realizada quarta-feira, 11\/09, \u00e0s 19h, no audit\u00f3rio central. Os palestrantes Waldir J\u00fanior, empreendedor, graduado em administra\u00e7<\/p>\n","protected":false},"author":5,"featured_media":294700,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-294699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/facape.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=294699"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/294700"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=294699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=294699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=294699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}