{"id":294960,"date":"2019-09-11T10:45:11","date_gmt":"2019-09-11T13:45:11","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=294960"},"modified":"2019-09-11T10:45:11","modified_gmt":"2019-09-11T13:45:11","slug":"governo-planeja-cobrar-imposto-de-04-para-saques-e-depositos-em-dinheiro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/governo-planeja-cobrar-imposto-de-04-para-saques-e-depositos-em-dinheiro\/","title":{"rendered":"Governo planeja cobrar imposto de 0,4% para saques e dep\u00f3sitos em dinheiro"},"content":{"rendered":"<header class=\"single-title\">\n<h1><\/h1>\n<p><em><strong>J\u00e1 para pagamentos no d\u00e9bito e no cr\u00e9dito, a al\u00edquota inicial estudada \u00e9 de 0,2% (para cada lado da opera\u00e7\u00e3o, pagador e recebedor)<\/strong><\/em><\/p>\n<\/header>\n<section class=\"post_content content-noticias clearfix\">\n<div id=\"attachment_554682\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-554682\" src=\"http:\/\/varelanoticias.com.br\/wp-content\/uploads\/2018\/06\/dinheiro-480x320.png\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" srcset=\"http:\/\/varelanoticias.com.br\/wp-content\/uploads\/2018\/06\/dinheiro-480x320.png 480w, http:\/\/varelanoticias.com.br\/wp-content\/uploads\/2018\/06\/dinheiro-263x175.png 263w, http:\/\/varelanoticias.com.br\/wp-content\/uploads\/2018\/06\/dinheiro-100x67.png 100w, http:\/\/varelanoticias.com.br\/wp-content\/uploads\/2018\/06\/dinheiro.png 1024w\" alt=\"\" width=\"480\" height=\"320\" \/><\/p>\n<p class=\"wp-caption-text\">Foto: TacioPhilip\/iStock<\/p>\n<div id=\"_ppads_video\"><\/div>\n<\/div>\n<p><strong>Folhapress<\/strong><br \/>\nF\u00e1bio Pupo<\/p>\n<p>O governo planeja em sua proposta de reforma tribut\u00e1ria que saques e dep\u00f3sitos em dinheiro sejam taxados com uma al\u00edquota inicial de 0,4%. A cobran\u00e7a integra a ideia do imposto sobre pagamentos, que vem sendo comparado \u00e0 antiga CPMF. J\u00e1 para pagamentos no d\u00e9bito e no cr\u00e9dito, a al\u00edquota inicial estudada \u00e9 de 0,2% (para cada lado da opera\u00e7\u00e3o, pagador e recebedor).<\/p>\n<p>Ambas as taxas tendem a crescer ap\u00f3s serem criadas, j\u00e1 que ideia do governo \u00e9 usar o novo imposto para substituir gradualmente a tributa\u00e7\u00e3o sobre os sal\u00e1rios, considerada pela equipe econ\u00f4mica como nociva para a gera\u00e7\u00e3o de empregos no pa\u00eds.<\/p>\n<p>Marcelo de Sousa Silva, secret\u00e1rio especial adjunto da Receita Federal, defendeu a contribui\u00e7\u00e3o nesta ter\u00e7a-feira (10) no F\u00f3rum Nacional Tribut\u00e1rio (promovido pelo sindicato dos auditores fiscais, em Bras\u00edlia), ao ressaltar que o instrumento substituiria tanto a tributa\u00e7\u00e3o sobre a folha como o IOF.<\/p>\n<p>\u201cEstamos ano a ano com uma regress\u00e3o percentual de pessoas empregadas formalmente. E isso n\u00e3o pode ficar de fora da reforma tribut\u00e1ria, porque o impacto mais significativo [para o emprego] talvez seja a desonera\u00e7\u00e3o sobre folha. Dentre todos os tributos no nosso ordenamento jur\u00eddico a tributa\u00e7\u00e3o sobre folha \u00e9 o mais perverso para a gera\u00e7\u00e3o de empregos\u201d, afirmou.<\/p>\n<p>O presidente Jair Bolsonaro j\u00e1 havia afirmado neste m\u00eas \u00e0 Folha que a recria\u00e7\u00e3o de um imposto nos moldes da antiga CPMF deve ser condicionada a uma compensa\u00e7\u00e3o para a popula\u00e7\u00e3o. \u201cJ\u00e1 falei para o Guedes: para ter nova CPMF, tem que ter uma compensa\u00e7\u00e3o para as pessoas. Se n\u00e3o, ele vai tomar porrada at\u00e9 de mim\u201d, disse o presidente.<\/p>\n<p>O presidente da C\u00e2mara, Rodrigo Maia (DEM-RJ), disse nesta ter\u00e7a-feira (10) que tema tem muita dificuldade de andar na C\u00e2mara e que estava esperando a formaliza\u00e7\u00e3o da proposta.<\/p>\n<p>\u201cA CPMF tem pouco apoio entre aqueles que conhecem a quest\u00e3o tribut\u00e1ria, n\u00e3o sei se esse \u00e9 o melhor caminho para voc\u00ea resolver os custos com m\u00e3o de obra\u201d, afirmou. \u201cN\u00f3s entendemos a preocupa\u00e7\u00e3o do governo. Acho que a inten\u00e7\u00e3o est\u00e1 correta, mas n\u00e3o sei se a f\u00f3rmula \u00e9 a melhor.\u201d<\/p>\n<div class=\"col-xs-12\">\n<div class=\"row\"><\/div>\n<\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12\">\n<div id=\"P_VARELA_NOTICIAS_FINAL_MATERIA_104167934518108467\" class=\"col-md-6 col-xs-12\" data-premium=\"\" data-adunit=\"VARELA_NOTICIAS_FINAL_MATERIA_1\" data-sizes=\"[[300,250]]\" data-device=\"all\" data-fetch=\"true\" data-google-query-id=\"CKizsYPzyOQCFU53wQodzMgDrA\"><\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 para pagamentos no d\u00e9bito e no cr\u00e9dito, a al\u00edquota inicial estudada \u00e9 de 0,2% (para cada lado da opera\u00e7\u00e3o, pagador e recebedor)<\/p>\n","protected":false},"author":5,"featured_media":294077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-294960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/dinheiroo-768x433.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=294960"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/294960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/294077"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=294960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=294960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=294960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}