{"id":295162,"date":"2019-09-13T05:25:53","date_gmt":"2019-09-13T08:25:53","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=295162"},"modified":"2019-09-13T05:25:53","modified_gmt":"2019-09-13T08:25:53","slug":"gabriel-menezes-desconfiado-com-ameaca-de-morte-ao-prefeito","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/gabriel-menezes-desconfiado-com-ameaca-de-morte-ao-prefeito\/","title":{"rendered":"Gabriel Menezes desconfiado com amea\u00e7a de morte ao prefeito"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-263137 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-620x349.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-620x349.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-300x169.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-768x432.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-160x90.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-480x270.jpg 480w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes-640x360.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes.jpg 1024w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p style=\"text-align: justify;\">O prefeito de Petrolina, Miguel Coelho, falou \u00e0 imprensa que foi amea\u00e7ado de morte devido ao processo de licita\u00e7\u00e3o para contrata\u00e7\u00e3o de uma nova empresa para operar o transporte coletivo urbano. O prefeito n\u00e3o citou nomes e nem a empresa. Na C\u00e2mara, o vereador Gabriel Menezes questionou o comportamento do gestor sobre a veracidade do fato em saber se ele fez o BO na delegacia. Provavelmente, Menezes tenha achado que o prefeito esteja jogando para a galera neste ano pr\u00e9-eleitoral. (<em>Com informa\u00e7\u00f5es de Cl\u00e1udio farias\/Rural FM)<\/em><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Petrolina, Miguel Coelho, falou \u00e0 imprensa que foi amea\u00e7ado de morte devido ao processo de licita\u00e7\u00e3o para contrata\u00e7\u00e3o de uma nova empresa pa<\/p>\n","protected":false},"author":5,"featured_media":263137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-295162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/11\/gabriel-menezes.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/295162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=295162"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/295162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/263137"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=295162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=295162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=295162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}