{"id":295778,"date":"2019-09-19T07:57:10","date_gmt":"2019-09-19T10:57:10","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=295778"},"modified":"2019-09-19T07:57:10","modified_gmt":"2019-09-19T10:57:10","slug":"a-cara-de-pau-de-daniel-coelho","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/a-cara-de-pau-de-daniel-coelho\/","title":{"rendered":"A cara de pau de Daniel Coelho"},"content":{"rendered":"<h2 class=\"blog-post-title\"><\/h2>\n<div id=\"container_clear\"><\/div>\n<p><img decoding=\"async\" src=\"http:\/\/blogdomagno.com.br\/admin\/ckeditor\/ckfinder\/images\/4A59A730-2DD5-43E4-AEB7-7E0E5AF4E125.jpeg\" alt=\"\" \/>N\u00e3o vi, ainda, o painel da vota\u00e7\u00e3o de ontem do projeto que regula as elei\u00e7\u00f5es municipais do ano que vem, para saber como votaram os nobres deputados, mas um detalhe chamou a aten\u00e7\u00e3o dos parlamentares que assistiram o pernambucano Daniel Coelho, l\u00edder do Cidadania, a bombardear o fundo eleitoral, aprovado na sess\u00e3o encerrada por volta da meia noite: nas elei\u00e7\u00f5es passadas, ele recebeu uma &#8220;ajudinha&#8221; de campanha de quase R$ 1,5 milh\u00e3o do seu partido, do mesmo fundo.<\/p>\n<p>Entre a teoria e a pr\u00e1tica, portanto, existe um distanciamento muito grande na a\u00e7\u00e3o parlamentar de Daniel.<\/p>\n<p>Ainda na sess\u00e3o de ontem, o l\u00edder do Podemos, Jos\u00e9 Nelton (GO), fez o discurso mais virulento contra o fundo eleitoral, mesmo tendo recebido R$ 250 mil de repasse do mesmo instrumento que agora combate na elei\u00e7\u00e3o passada.<\/p>\n<p>N\u00e3o d\u00e1 para entender como algu\u00e9m pode ter ainda, em tempos de tamanha transpar\u00eancia, uma postura de jogar para a plateia e outra para surrupiar o dinheiro p\u00fablico quando est\u00e1 em risco a sua sobreviv\u00eancia eleitoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o vi, ainda, o painel da vota\u00e7\u00e3o de ontem do projeto que regula as elei\u00e7\u00f5es municipais do ano que vem, para saber como votaram os nobres deputados, mas um detalhe chamou a aten\u00e7\u00e3o dos parlamentares que assistiram o pernambucano Daniel Coelho, l\u00edder do Cidadania, a bombardear o fundo eleitoral, aprovado na sess\u00e3o<\/p>\n","protected":false},"author":5,"featured_media":246802,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-295778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/06\/daniel-coelho-3.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/295778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=295778"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/295778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/246802"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=295778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=295778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=295778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}