{"id":296523,"date":"2019-09-27T14:41:03","date_gmt":"2019-09-27T17:41:03","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=296523"},"modified":"2019-09-27T14:41:03","modified_gmt":"2019-09-27T17:41:03","slug":"criador-da-raca-de-caes-labradoodle-se-arrepende-e-diz-que-animais-sao-doidos","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/criador-da-raca-de-caes-labradoodle-se-arrepende-e-diz-que-animais-sao-doidos\/","title":{"rendered":"Criador da ra\u00e7a de c\u00e3es labradoodle se arrepende e diz que animais s\u00e3o &#8216;doidos&#8217;"},"content":{"rendered":"<h1 class=\"story-body__h1\"><\/h1>\n<div class=\"with-extracted-share-icons\">\n<div class=\"story-body__mini-info-list-and-share\">\n<div class=\"story-body__mini-info-list-and-share-row\">\n<div class=\"mini-info-list-wrap\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"share-tools--no-event-tag\">\n<div id=\"comp-pattern-library\" class=\"distinct-component-group container-twite\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"story-body__inner\">\n<figure class=\"media-landscape has-caption full-width lead\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/660\/cpsprodpb\/C112\/production\/_108962494_image-1.jpg\" alt=\"Labradoodle Barney\" width=\"976\" height=\"549\" data-highest-encountered-width=\"660\" \/><\/span>A dona do labradoodle Barney discorda do criador da ra\u00e7a: &#8216;Eles s\u00e3o perfeitos para qualquer idade&#8217;<\/figure>\n<p class=\"story-body__introduction\">&#8220;Fofo&#8221; e &#8220;bonitinho&#8221; s\u00e3o os primeiros adjetivos que v\u00eam \u00e0 cabe\u00e7a da maioria das pessoas que veem um labradoodle pela primeira vez.<\/p>\n<p>O criador dessa ra\u00e7a, uma mistura entre labrador e poodle, prefere outras palavras, entretanto: &#8220;doido&#8221; e &#8220;monstro Frankenstein&#8221;, por exemplo.<\/p>\n<p>Em uma entrevista recente dada ao podcast da rede australiana ABC, Wally Conron diz que sua &#8220;inven\u00e7\u00e3o&#8221; \u00e9 um dos maiores arrependimentos de sua vida e que n\u00e3o faz ideia do que leva as pessoas a continuarem reproduzindo a ra\u00e7a ainda hoje.<\/p>\n<p>A &#8220;tend\u00eancia&#8221; de cruzar ra\u00e7as diferentes para tentar gerar c\u00e3es h\u00edbridos tem criado c\u00e3es propensos a uma s\u00e9rie de doen\u00e7as, ele ressalta.<\/p>\n<p>&#8220;Eu abri a caixa de Pandora&#8221;, afirmou o australiano \u00e0 ABC. &#8220;Libertei um Frankenstein.&#8221;<\/p>\n<p>&#8220;As pessoas est\u00e3o virando criadoras por dinheiro. Profissionais inescrupulosos est\u00e3o cruzando poodles com ra\u00e7as inapropriadas simplesmente para dizerem que foram os primeiros a fazer isso.&#8221;<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/C176\/production\/_108962594_gettyimages-913089318.jpg\" alt=\"Labradoodles na grama\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span>Conron diz que criadores que entraram nesse mercado para ganhar dinheiro t\u00eam cruzado ra\u00e7as diferentes de forma irrespons\u00e1vel e criado c\u00e3es &#8216;doidos&#8217; ou com problemas de sa\u00fade<\/figure>\n<h2 class=\"story-body__crosshead\">O primeiro &#8216;cachorro design&#8217;?<\/h2>\n<p>Wally criou o labradoodle no fim dos anos 1980.<\/p>\n<p>Tudo come\u00e7ou quando uma senhora cega, uma americana do Estado do Hava\u00ed, escreveu-lhe uma carta contando que o marido era al\u00e9rgico a c\u00e3es de pelo longo. Foi a\u00ed que ele decidiu tentar criar um cachorro que pudesse servir de c\u00e3o-guia e morar com o casal.<\/p>\n<p>Ap\u00f3s tr\u00eas anos tentando encontrar uma solu\u00e7\u00e3o, em 1989 ele teve a ideia de criar um animal com &#8220;as habilidades do labrador para o trabalho e a pelagem de um poodle&#8221;.<\/p>\n<p>Apesar de ter conseguido o que queria, ele diz se arrepender porque a ra\u00e7a acabou criando uma onda que n\u00e3o necessariamente observa um princ\u00edpio caro a ele \u2014 o de criar apenas ra\u00e7as saud\u00e1veis.<\/p>\n<p>&#8220;Vejo que a maioria (dos labradoodles) ou \u00e9 doida ou tem problemas heredit\u00e1rios.&#8221;<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/13642\/production\/_108962497_image-11.jpg\" alt=\"Martha and her dog Barney\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span>Martha, dona de Barney, diz nunca ter conhecido &#8216;um labradoodle maluco&#8217;<\/figure>\n<h2 class=\"story-body__crosshead\">&#8216;O companheiro perfeito&#8217;<\/h2>\n<p>Muita gente, entretanto, n\u00e3o concorda com Wally.<\/p>\n<p>Para Martha Watton, de 20 anos, seu labradoodle Barney \u00e9 o cachorro dos sonhos.<\/p>\n<p>&#8220;Ele tem uma mistura perfeita de amor e intelig\u00eancia. Quando estou para baixo ou estressada, ele levanta meu humor, pede carinho e me sinto melhor&#8221;, disse a brit\u00e2nica ao programa de r\u00e1dio da BBC Newsbeat.<\/p>\n<p>Para ela, c\u00e3es como Barney s\u00e3o &#8220;perfeitos para qualquer idade&#8221;.<\/p>\n<p>&#8220;Meu av\u00f4 tem dem\u00eancia e levamos o Barney pra visit\u00e1-lo na casa de repouso \u2014 ele \u00e9 o cachorro perfeito (para fazer companhia a pessoas mais velhas), n\u00e3o late.&#8221;<\/p>\n<div class=\"social-embed\">\n<div class=\"social-embed-post social-embed-instagram\">\n<div class=\"embed embed-instagram\">\n<div class=\"embed-region embed-core-hidden\" role=\"region\" aria-label=\"Instagram post de houndsofmandeville\"><a class=\"off-screen jump-link\" href=\"https:\/\/www.bbc.com\/portuguese\/geral-49831395#jump-linkhttps:\/\/www.instagram.com\/p\/BwMxSFVB45e\/\">Pule Instagram post de houndsofmandeville<\/a><iframe id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BwMxSFVB45e\/embed\/captioned\/?cr=1&amp;v=12&amp;rd=https%3A%2F%2Fwww.bbc.com&amp;rp=%2Fportuguese%2Fgeral-49831395#%7B%22ci%22%3A0%2C%22os%22%3A11524.99999999418%7D\" height=\"979\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p id=\"jump-linkhttps:\/\/www.instagram.com\/p\/BwMxSFVB45e\/\" class=\"off-screen\" tabindex=\"-1\">Final de Instagram post de houndsofmandeville<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 class=\"story-body__crosshead\">&#8216;Parte da fam\u00edlia&#8217;<\/h2>\n<p>Grace Mandeville tem opini\u00e3o parecida \u2014 ela \u00e9 dona de Juno h\u00e1 dois anos e diz que ela &#8220;\u00e9 uma ursinha de pel\u00facia brincalhona louca por meias&#8221;.\u200e<\/p>\n<p>\u200e&#8221;Ela \u00e9 realmente parte da fam\u00edlia. Eu sou al\u00e9rgica a gato e cachorro\u200e, ent\u00e3o \u00e9 \u00f3timo poder ficar no sof\u00e1 com ela e n\u00e3o come\u00e7ar a espirrar.&#8221;<\/p>\n<p>\u200e&#8221;Todo dia pela manh\u00e3 ela senta do lado da cama esperando que a gente acorde para vir fazer um chamego.&#8221;<\/p>\n<div class=\"social-embed\">\n<div class=\"social-embed-post social-embed-instagram\">\n<div class=\"embed embed-instagram\">\n<div class=\"embed-region embed-core-hidden\" role=\"region\" aria-label=\"Instagram post de gracemandeville\"><a class=\"off-screen jump-link\" href=\"https:\/\/www.bbc.com\/portuguese\/geral-49831395#jump-linkhttps:\/\/www.instagram.com\/p\/Bwq48J6nES8\/\">Pule Instagram post de gracemandeville<\/a><iframe id=\"instagram-embed-1\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/Bwq48J6nES8\/embed\/captioned\/?cr=1&amp;v=12&amp;rd=https%3A%2F%2Fwww.bbc.com&amp;rp=%2Fportuguese%2Fgeral-49831395#%7B%22ci%22%3A1%2C%22os%22%3A11583.000000013271%7D\" height=\"996\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-1\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p id=\"jump-linkhttps:\/\/www.instagram.com\/p\/Bwq48J6nES8\/\" class=\"off-screen\" tabindex=\"-1\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Para o veterin\u00e1rio John Whitwell, os c\u00e3es da ra\u00e7a s\u00e3o &#8220;felizes, saud\u00e1veis&#8221; e n\u00e3o apresentam grandes problemas.<\/p>\n<p>&#8220;N\u00e3o acho que sejam malucos. Eles realmente parecem ser bons c\u00e3es para fam\u00edlias \u2014 nunca conheci algu\u00e9m que tenha dito que ele era agressivo ou que tenha atacado os donos.&#8221;<\/p>\n<h2 class=\"story-body__crosshead\">Dicas para os donos de c\u00e3es &#8216;mal educados&#8217;<\/h2>\n<p>Se voc\u00ea \u00e9 dono de um cachorrinho barulhento, entretanto, Whitwell diz que h\u00e1 algumas coisas para melhorar a vida na casa.<\/p>\n<p>Por mais irritantes que os latidos recorrentes possam ser, n\u00e3o repreenda o bichinho \u2014 porque assim ele vai acabar virando o &#8220;centro das aten\u00e7\u00f5es&#8221;.<\/p>\n<p>&#8220;Leve o cachorro para fora, para uma \u00e1rea tranquila, e deixe ele l\u00e1 por dez minutos.&#8221;<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/136A6\/production\/_108962597_gettyimages-535789383.jpg\" alt=\"Labradoodle na natureza\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span>Ra\u00e7a foi criada no fim dos anos 1980<\/figure>\n<p>Ele tamb\u00e9m recomenda que os donos &#8220;sintonizem sua paz interior&#8221; para desestimular os cachorros a correrem ou pularem pela casa quando algu\u00e9m entra pela porta.<\/p>\n<p>&#8220;Claro que voc\u00ea fica feliz quando chega em casa e v\u00ea seu cachorro. Mas, quando voc\u00ea imediatamente o &#8216;cumprimenta&#8217; e faz festa, refor\u00e7a para ele que aquele \u00e9 um momento de excita\u00e7\u00e3o.&#8221;<\/p>\n<p>&#8220;Fa\u00e7a um caf\u00e9, um ch\u00e1 e, depois que o c\u00e3ozinho estiver mais calmo, a\u00ed sim diga &#8216;oi&#8217;.&#8221;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ele tamb\u00e9m recomenda que os donos &#8220;sintonizem sua paz interior&#8221; para desestimular os cachorros a correrem ou pularem pela casa quando algu\u00e9m entra pela porta.<\/p>\n","protected":false},"author":5,"featured_media":296524,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-296523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/cachorro-doido1.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/296523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=296523"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/296523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/296524"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=296523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=296523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=296523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}