{"id":297122,"date":"2019-10-03T15:35:01","date_gmt":"2019-10-03T18:35:01","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=297122"},"modified":"2019-10-03T15:35:01","modified_gmt":"2019-10-03T18:35:01","slug":"trabalhadores-e-estudantes-saem-as-ruas-em-defesa-da-educacao-e-da-soberania-nacional","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/trabalhadores-e-estudantes-saem-as-ruas-em-defesa-da-educacao-e-da-soberania-nacional\/","title":{"rendered":"Trabalhadores e estudantes saem \u00e0s ruas em defesa da educa\u00e7\u00e3o e da soberania nacional"},"content":{"rendered":"<header class=\"entry-header\">\n<h1 class=\"entry-title\" style=\"text-align: justify;\"><\/h1>\n<\/header>\n<p style=\"text-align: justify;\">\n<div class=\"entry-content\">\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-232357 lazyloaded\" src=\"https:\/\/controle.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao.jpg\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" srcset=\"https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao.jpg 357w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao-768x711.jpg 768w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao-830x768.jpg 830w\" alt=\"\" width=\"357\" height=\"330\" data-src=\"https:\/\/controle.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao.jpg\" data-srcset=\"https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao.jpg 357w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao-768x711.jpg 768w, https:\/\/www.esmaelmorais.com.br\/wp-content\/uploads\/2019\/10\/greve-educacao-830x768.jpg 830w\" data-sizes=\"(max-width: 357px) 100vw, 357px\" \/>Contra os cortes na educa\u00e7\u00e3o do governo Bolsonaro e as amea\u00e7as de privatiza\u00e7\u00e3o de empresas p\u00fablicas, estudantes e trabalhadores saem \u00e0s ruas em diversas capitais e cidades do pa\u00eds nesta quarta-feira (3). Pela manh\u00e3, eles realizaram juntos uma caminhada entre a refinaria Presidente Get\u00falio Vargas (Repar) e a F\u00e1brica de Fertilizantes do Paran\u00e1 (Fafen-PR), que ficam em Arauc\u00e1ria, na regi\u00e3o metropolitana de Curitiba, ambas na mira para serem privatizadas. As manifesta\u00e7\u00f5es tamb\u00e9m marcam os 66 anos da Petrobras.<\/p>\n<p style=\"text-align: justify;\">Os petroleiros tamb\u00e9m apoiaram a manifesta\u00e7\u00e3o dos estudantes em Fortaleza. Eles se reuniram na reitoria da Universidade Federal do Cear\u00e1 (UFC) e caminharam pelas ruas da capital. Tamb\u00e9m foram registrados atos em Salvador, Manaus, Teresina e Campo Grande. O programa Future-se, que prev\u00ea a participa\u00e7\u00e3o do capital privado nas universidades, foi alvo dos protestos.<\/p>\n<p style=\"text-align: justify;\">Durante a tarde, estudantes e petroleiros tamb\u00e9m devem realizar manifesta\u00e7\u00f5es em S\u00e3o Paulo, Rio de Janeiro, e diversas outras capitais. Um dos atos principais vai ocorrer em Curitiba, onde o ex-presidente Luiz In\u00e1cio Lula da Silva \u00e9 mantido como preso pol\u00edtico da Lava Jato desde abril de 2018. Segundo os petroleiros, Lula foi o principal respons\u00e1vel pelos investimentos que fortaleceram a estatal nos \u00faltimos anos e possibilitaram a descoberta do pr\u00e9-sal.<\/p>\n<p style=\"text-align: justify;\">\u201cN\u00e3o estamos falando s\u00f3 de desemprego nas estatais e, sim, em toda a cadeira produtiva, al\u00e9m de riscos de acidentes e piora na presta\u00e7\u00e3o dos servi\u00e7os, pois as empresas privadas s\u00f3 visam o lucro e a alta nos pre\u00e7os. Hoje, o brasileiro j\u00e1 paga caro pelos combust\u00edveis, nossa gasolina \u00e9 a segunda mais cara do mundo porque a pol\u00edtica de pre\u00e7os \u00e9 gerenciada pelo mercado internacional\u201d, afirmou o coordenador da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP), Jos\u00e9 Maria Rangel.<\/p>\n<p style=\"text-align: justify;\">O presidente da Uni\u00e3o Nacional dos Estudantes (UNE), Iago Montalv\u00e3o, destacou a import\u00e2ncia dos royalties do pr\u00e9-sal para a Educa\u00e7\u00e3o e as amea\u00e7as a esses investimentos representada pelas sucessivas tentativas de esvaziamento do modelo de partilha, que garante participa\u00e7\u00e3o m\u00ednima de 30% da Petrobras nos cons\u00f3rcios de explora\u00e7\u00e3o do pr\u00e9-sal, e a aplica\u00e7\u00e3o dos recursos num fundo social para serem investidos em educa\u00e7\u00e3o (75%) e sa\u00fade (25%). Tamb\u00e9m participam das manifesta\u00e7\u00f5es os integrantes da Associa\u00e7\u00e3o Nacional de P\u00f3s-Graduandos (ANPG) e da Confedera\u00e7\u00e3o Nacional dos Trabalhadores em Educa\u00e7\u00e3o (CNTE).<\/p>\n<p style=\"text-align: justify;\">\u201cAtualmente a mudan\u00e7a no regime de explora\u00e7\u00e3o dos royalties ainda \u00e9 uma preocupa\u00e7\u00e3o porque impacta diretamente no que foi aprovado pelo Plano Nacional de Educa\u00e7\u00e3o (PNE) para o financiamento de 10% do PIB para a educa\u00e7\u00e3o. Se for realmente retirada a prefer\u00eancia da Petrobras na opera\u00e7\u00e3o dos campos do pr\u00e9-sal, automaticamente estamos colocando em risco o controle do governo brasileiro sobre a explora\u00e7\u00e3o, o que pode gerar sonega\u00e7\u00e3o de dados p\u00fablicos e redu\u00e7\u00e3o dos recursos para o Fundo\u201d, afirma Montalv\u00e3o. Os estudantes cobram ainda a libera\u00e7\u00e3o de R$ 3,8 bilh\u00f5es do or\u00e7amento da educa\u00e7\u00e3o para o ano de 2018 e a manuten\u00e7\u00e3o das bolsas de pesquisa, entre outras reivindica\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">No Rio de Janeiro, a mobiliza\u00e7\u00e3o dos petroleiros ser\u00e1 em frente \u00e0s sedes da Petrobras e Eletrobras, no central da capital, a partir das 16h. De l\u00e1, eles se encontram com os estudantes na Avenida Presidente Vargas, tamb\u00e9m no centro. Em Curitiba, os manifestantes se concentram na Pra\u00e7a Santos Andrade, na regi\u00e3o central, a partir das 17h, de onde sair\u00e3o em passeata. Em S\u00e3o Paulo, os manifestantes se concentram a partir das 17h na Avenida Paulista, em frente ao Masp, na Avenida Paulista, com caminhada prevista at\u00e9 a Pra\u00e7a da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">por\u00a0<a href=\"https:\/\/www.redebrasilatual.com.br\/politica\/2019\/10\/trabalhadores-e-estudantes-saem-as-ruas-em-defesa-da-educacao-e-da-soberania-nacional\/\">RBA<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cN\u00e3o estamos falando s\u00f3 de desemprego nas estatais e, sim, em toda a cadeira produtiva, al\u00e9m de riscos de acidentes e piora na presta\u00e7\u00e3o dos servi\u00e7os, pois as empresas privadas s\u00f3 visam o lucro e a al<\/p>\n","protected":false},"author":5,"featured_media":297123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-297122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/10\/greve-educacao.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/297122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=297122"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/297122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/297123"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=297122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=297122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=297122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}