{"id":297801,"date":"2019-10-10T07:20:11","date_gmt":"2019-10-10T10:20:11","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=297801"},"modified":"2019-10-10T07:20:11","modified_gmt":"2019-10-10T10:20:11","slug":"daniel-coelho-pede-a-moro-que-envie-forca-nacional-para-mais-cidades-pernambucanas","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/daniel-coelho-pede-a-moro-que-envie-forca-nacional-para-mais-cidades-pernambucanas\/","title":{"rendered":"Daniel Coelho pede a Moro que envie For\u00e7a Nacional para mais cidades pernambucanas"},"content":{"rendered":"<header>\n<div class=\"data-post\">\n<div class=\"data-extenso\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"img-responsive\" title=\"Daniel Coelho e Sergio Moro (Foto: Divulga\u00e7\u00e3o)\" src=\"https:\/\/imagens4.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2019\/10\/danielemoro.jpg\" alt=\"Daniel Coelho e Sergio Moro (Foto: Divulga\u00e7\u00e3o)\" \/><figcaption>Daniel Coelho e Sergio Moro (Foto: Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<div id=\"texto-noticia\" style=\"text-align: justify;\">\n<p>O deputado federal Daniel Coelho (Cidadania) se reuniu na tarde desta quarta-feira (9) com o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro. O encontro foi para sugerir a expans\u00e3o do programa \u201cEm Frente Brasil\u201d, que encaminha tropas da For\u00e7a Nacional para ajudar no combate \u00e0 viol\u00eancia urbana.<\/p>\n<p>O programa foi implantado no munic\u00edpio do Paulista, na Regi\u00e3o Metropolitana do Recife. \u201cFizemos um balan\u00e7o sobre as a\u00e7\u00f5es em Paulista, o ministro me apresentou alguns n\u00fameros e falou que em breve ir\u00e1 fazer uma visita a Pernambuco\u201d, relatou Coelho, em entrevista ao site Portal de Prefeitura.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\">\n<div class=\"player_dynad_tv\"><\/div>\n<\/div>\n<h2>Justificativa<\/h2>\n<p>Para o deputado, a expans\u00e3o do programa \u00e9 necess\u00e1ria.\u201cPor ficar em uma \u00e1rea metropolitana, os bandidos acabam migrando para outras cidades, por esse motivo falei com ministro para que o programa fosse expandido\u201d, disse.<\/p>\n<p>O parlamentar tamb\u00e9m contou que, na reuni\u00e3o, o ministro Moro falou sobre a articula\u00e7\u00e3o para aprovar o \u201cPacote Anticrime\u201d. O titular da pasta tamb\u00e9m quer a aprova\u00e7\u00e3o na C\u00e2mera da pris\u00e3o em segunda inst\u00e2ncia.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"box-widget\">\n<h4 class=\"titulo-box-widgets\" style=\"text-align: justify;\"><\/h4>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O programa foi implantado no munic\u00edpio do Paulista, na Regi\u00e3o Metropolitana do Recife. \u201cFizemos um balan\u00e7o sobre as a\u00e7\u00f5es em Paulista, o ministro me apresentou alguns n\u00fameros e falou que em breve ir\u00e1 fazer uma visita a Pernambuco\u201d, relatou Coelho, em entrevista ao<\/p>\n","protected":false},"author":5,"featured_media":297802,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-297801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/10\/danielemoro.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/297801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=297801"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/297801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/297802"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=297801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=297801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=297801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}