{"id":299529,"date":"2019-10-26T11:01:52","date_gmt":"2019-10-26T14:01:52","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=299529"},"modified":"2019-10-26T11:01:52","modified_gmt":"2019-10-26T14:01:52","slug":"ala-do-psl-vai-pedir-a-cpi-das-fake-news-que-divulgue-perfis-da-milicia-virtual-bolsonarista","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/ala-do-psl-vai-pedir-a-cpi-das-fake-news-que-divulgue-perfis-da-milicia-virtual-bolsonarista\/","title":{"rendered":"Ala do PSL vai pedir \u00e0 CPI das fake news que divulgue perfis da mil\u00edcia virtual bolsonarista"},"content":{"rendered":"<div class=\"container\">\n<h1><\/h1>\n<p class=\"description\"><em><strong>Ala bivarista do partido tem a expectativa de que uma quebra de IPs indique o uso de computadores do governo nos ataques a advers\u00e1rios de Bolsonaro<\/strong><\/em><\/p>\n<\/div>\n<div class=\"load-image\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive center-block wp-post-image lazyloaded\" src=\"https:\/\/revistaforum.com.br\/wp-content\/uploads\/2018\/12\/t-e1562587762923.jpg\" alt=\"\" width=\"700\" height=\"385\" data-lazy-src=\"https:\/\/revistaforum.com.br\/wp-content\/uploads\/2018\/12\/t-e1562587762923.jpg\" data-was-processed=\"true\" \/><\/p>\n<div class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o\/Flickr<\/div>\n<\/div>\n<div class=\"marginbottom\"><\/div>\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg-8 col-md-8 col-sm-12 col-xs-12\">\n<div class=\"author\">\n<div class=\"pull-left\"><a href=\"https:\/\/revistaforum.com.br\/autor\/redacao\/\">Por Reda\u00e7\u00e3o<\/a><\/div>\n<div class=\"pull-right socials\"><i class=\"fa fa-facebook-official\" aria-hidden=\"true\"><\/i>\u00a0<i class=\"fa fa-twitter-square\" aria-hidden=\"true\"><\/i>\u00a0<i class=\"fa fa-whatsapp\" aria-hidden=\"true\"><\/i><\/div>\n<\/div>\n<div class=\"text\">\n<div class=\"code-block code-block-7\"><\/div>\n<p>A ala do PSL que \u00e9 ligada ao presidente nacional da sigla, Luciano Bivar (PE), quer usar a CPMI das fake news para quebrar o sigilo de perfis respons\u00e1veis por ataques na Internet, como \u00e9 o caso da mil\u00edcia virtual bolsonarista. De acordo com\u00a0<a href=\"https:\/\/painel.blogfolha.uol.com.br\/2019\/10\/26\/ala-do-psl-ligada-a-bivar-quer-que-cpmi-descubra-de-quais-computadores-partiram-ataques-nas-redes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Daniela Lima<\/a>, da Folha de S.Paulo, deputados do PSL que fazem oposi\u00e7\u00e3o ao grupo ligado ao presidente Jair Bolsonaro j\u00e1 est\u00e3o levantando os respons\u00e1veis pelos ataques.<\/p>\n<p>A atua\u00e7\u00e3o da mil\u00edcia no Planalto n\u00e3o \u00e9 segredo entre parlamentares, mas o pedido da ala bivarista perante a CPI tem a expectativa de que uma quebra de IPs indique o uso de computadores do governo nos ataques a advers\u00e1rios de Bolsonaro.<\/p>\n<div class=\"code-block code-block-33\"><\/div>\n<div class=\"code-block code-block-1\"><\/div>\n<p>Deputados contam com Joice Hasselmann (SP), ex-l\u00edder do governo na C\u00e2mara e destitu\u00edda por Bolsonaro, para solicitar as provid\u00eancias que identifiquem de onde partiram os disparos. Em entrevista ao Roda Viva no come\u00e7o da semana, a deputada compartilhou que os filhos do presidente \u2013 Carlos, Eduardo e Fl\u00e1vio \u2013 possuem\u00a0<a href=\"https:\/\/revistaforum.com.br\/politica\/joice-denuncia-que-flavio-carlos-e-eduardo-tem-rede-de-fake-news-com-1-500-perfis\/\" target=\"_blank\" rel=\"noopener noreferrer\">cerca de 1.500 perfis<\/a>\u00a0destinados somente ao disparo de ataques nas redes.<\/p>\n<p>Ainda, os defensores do uso da CPMI para expor a rede bolsonarista esperam contar com o apoio da oposi\u00e7\u00e3o na den\u00fancia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ala bivarista do partido tem a expectativa de que uma quebra de IPs indique o uso de computadores do governo nos ataques a advers\u00e1rios de Bolsonaro<\/p>\n","protected":false},"author":5,"featured_media":283504,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-299529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/pai-e-filhos.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=299529"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/283504"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=299529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=299529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=299529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}