{"id":299841,"date":"2019-10-29T15:18:29","date_gmt":"2019-10-29T18:18:29","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=299841"},"modified":"2019-10-30T05:14:38","modified_gmt":"2019-10-30T08:14:38","slug":"reprovacao-alta-de-paulo-camara-e-um-sinal-de-alerta-para-joao-campos-diz-hidalgo","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/reprovacao-alta-de-paulo-camara-e-um-sinal-de-alerta-para-joao-campos-diz-hidalgo\/","title":{"rendered":"Reprova\u00e7\u00e3o alta de Paulo C\u00e2mara \u00e9 um \u2018sinal de alerta\u2019 para Jo\u00e3o Campos, diz Hidalgo"},"content":{"rendered":"<header>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"img-responsive\" title=\"Foto: Heudes Regis\/SEI\" src=\"https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2019\/10\/Paulo-C%C3%A2mara-Jo%C3%A3o-Campos-e-Geraldo-Julio-748x410.jpg\" alt=\"Foto: Heudes Regis\/SEI\" \/><figcaption>Foto: Heudes Regis\/SEI<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<div id=\"texto-noticia\">\n<p style=\"text-align: justify;\">Principal nome cotado do PSB para disputar a Prefeitura do Recife no ano que vem, o deputado federal Jo\u00e3o Campos n\u00e3o dever\u00e1 contar com o governador Paulo C\u00e2mara (PSB) e o prefeito da capital, Geraldo Julio (PSB), como bons cabos eleitorais para a disputa. A an\u00e1lise \u00e9 do diretor Instituto Paran\u00e1 Pesquisas, Murilo Hidalgo, em entrevista ao\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\"><strong>Blog de Jamildo<\/strong><\/a>\u00a0sobre a pesquisa que avaliou as gest\u00f5es municipal e estadual. Segundo ele, o filho do ex-governador Eduardo Campos deve apostar no resgate da figura do pai na eventual campanha.<\/p>\n<p style=\"text-align: justify;\">\u201cO fato do prefeito (Geraldo Julio) n\u00e3o estar muito bem e nem o governador (Paulo C\u00e2mara) \u00e9 um sinal de alerta ao deputado Jo\u00e3o Campos. Eu acho que n\u00e3o vai poder \u2018surfar\u2019 muito na onda dos dois e dever\u00e1 \u2018surfar\u2019 muito mais na mem\u00f3ria do pai. L\u00f3gico que a m\u00e1quina sempre ajuda. \u00c9 sempre bom disputar com o apoio da m\u00e1quina, mas n\u00e3o tenho d\u00favida que a grande for\u00e7a do Jo\u00e3o Campos vai ser a mem\u00f3ria e o nome do pai. Durante a campanha, ele deve crescer com isso\u201d, avaliou Murilo Hidalgo.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\" style=\"text-align: justify;\">\n<div class=\"player_dynad_tv\"><\/div>\n<\/div>\n<figure id=\"attachment_177906\" class=\"wp-caption alignnone\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-177906 img-responsive \" src=\"https:\/\/imagens3.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2017\/04\/eduardo_campos_600_MS.jpg\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" srcset=\"https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2017\/04\/eduardo_campos_600_MS.jpg 750w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2017\/04\/eduardo_campos_600_MS-300x164.jpg 300w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2017\/04\/eduardo_campos_600_MS-748x410.jpg 748w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2017\/04\/eduardo_campos_600_MS-219x120.jpg 219w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2017\/04\/eduardo_campos_600_MS-152x82.jpg 152w\" alt=\"\" width=\"750\" height=\"410\" \/><figcaption>Foto: Michele Souza\/Acervo JC Imagem<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">No levantamento sobre a administra\u00e7\u00e3o do governador, 60,3% dos entrevistados declaram reprovar a gest\u00e3o do socialista, 34,3% afirmaram aprovar o governo. 5,4% n\u00e3o souberam ou n\u00e3o opinaram. 31,8% a avaliam como regular. J\u00e1 entre os que aprovam a a gest\u00e3o, 15,8% avaliaram como boa e 3,1% opinaram como \u00f3tima. 1,8% dos entrevistados n\u00e3o souberam ou n\u00e3o opinaram.<\/p>\n<p style=\"text-align: justify;\">J\u00e1\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/10\/29\/recifenses-estao-divididos-sobre-avaliacao-de-geraldo-julio-diz-pesquisa\/\">na avalia\u00e7\u00e3o do prefeito houve empate t\u00e9cnico entre os que aprovam e desaprovam o governo municipal, com leve vantagem para a opini\u00e3o positiva<\/a>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-221433 img-responsive \" src=\"https:\/\/imagens1.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2019\/10\/Pesquisa.jpg\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" srcset=\"https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2019\/10\/Pesquisa.jpg 910w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2019\/10\/Pesquisa-300x192.jpg 300w, https:\/\/imagens2.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/2019\/10\/Pesquisa-641x410.jpg 641w\" alt=\"\" width=\"910\" height=\"582\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Pesquisa<\/strong><\/h2>\n<p style=\"text-align: justify;\">Foram ouvidos 828 eleitores nos dias 25, 26, 27 e 28 de outubro. O levantamento, bancado pelo pr\u00f3prio instituto, tem um grau de confian\u00e7a de 95%. Por n\u00e3o ter sido realizada em ano eleitoral, a pesquisa n\u00e3o precisa ser registrada no Tribunal Superior Eleitoral (TSE).<\/p>\n<p style=\"text-align: justify;\">Fonte: Blog de Jamildo<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foram ouvidos 828 eleitores nos dias 25, 26, 27 e 28 de outubro. O levantamento, bancado pelo pr\u00f3prio instituto, tem um grau de confian\u00e7a de 95%. Por n\u00e3o ter sido realizada em ano eleitoral, a pesquisa n\u00e3o precisa ser registrada no Tribunal Superior Eleitoral (TSE).<\/p>\n","protected":false},"author":5,"featured_media":299843,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-299841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/10\/joao-campos-e-haddad.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=299841"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/299843"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=299841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=299841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=299841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}