{"id":299933,"date":"2019-10-30T08:24:59","date_gmt":"2019-10-30T11:24:59","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=299933"},"modified":"2019-10-30T08:24:59","modified_gmt":"2019-10-30T11:24:59","slug":"militares-choram-na-camara-e-gritam-bolsonaro-traidor","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/militares-choram-na-camara-e-gritam-bolsonaro-traidor\/","title":{"rendered":"Militares choram na C\u00e2mara e gritam &#8220;Bolsonaro traidor&#8221;"},"content":{"rendered":"<div class=\"servicos-topo-post\">\n<div class=\"box-autoria-post\" style=\"text-align: justify;\">\n<div class=\"div_middle\"><\/div>\n<\/div>\n<\/div>\n<article class=\"artigo\">\n<section class=\"conteudo-post\">\n<h2 class=\"resumo\">Jair Bolsonaro mobiliza aliados para derrubar emenda que garantiria reajuste para pra\u00e7as e militares de baixa patente e provoca revolta. &#8220;Eu coordenei carreata para o senhor, eu gritei &#8216;Bolsonaro, 17&#8217; e hoje o senhor trai a tropa dessa maneira&#8221;<\/h2>\n<div class=\"foto-conteudo-post centro completa\">\n<div class=\"borda-foto\"><img decoding=\"async\" src=\"https:\/\/www.pragmatismopolitico.com.br\/wp-content\/uploads\/2019\/10\/reforma-militares.jpg\" alt=\"reforma dos militares bolsonaro\" \/><\/div>\n<\/div>\n<div class=\"pub_2_desktop\">\n<div class=\"pub_ads\"><\/div>\n<\/div>\n<p>A Comiss\u00e3o que votou a Reforma da Previd\u00eancia dos militares na C\u00e2mara dos Deputados nesta ter\u00e7a-feira (28) chegou a ser suspensa por conta de uma confus\u00e3o envolvendo manifestantes que protestavam contra a vota\u00e7\u00e3o.<\/p>\n<p class=\"par_texto\">Entre gritos de \u201ccovardes\u201d e \u201ctraidor\u201d, o grupo formado por soldados, pra\u00e7as e familiares exp\u00f4s as cr\u00edticas \u00e0 reforma e ao governo do presidente Jair Bolsonaro (PSL).<\/p>\n<p class=\"par_texto\">\u201cEu coordenei carreata para o senhor, eu gritei \u2018Bolsonaro, 17\u2019, enquanto eles estavam sob o ar condicionado e hoje o senhor trai a tropa dessa maneira. Isso \u00e9 um absurdo, dando benef\u00edcios aos generais\u201d, disse uma mulher, visivelmente indignada.<\/p>\n<p class=\"par_texto\">Enquanto isso, outra come\u00e7ou a gritar \u201ctrairagem\u201d ao fundo. Uma terceira mulher afirmou que nem Bolsonaro, nem seus filhos, ter\u00e3o os votos da \u201cfam\u00edlia militar\u201d outra vez.<\/p>\n<p class=\"par_texto\">A revolta ocorreu porque Jair Bolsomaro mobilizou deputados aliados para rejeitar um destaque que estenderia uma gratifica\u00e7\u00e3o para todos os integrantes das For\u00e7as Armadas, e n\u00e3o apenas para oficiais e militares de alta patente.<\/p>\n<p class=\"par_texto\">No funcionalismo, os militares s\u00e3o os que custam mais para a Previd\u00eancia, proporcionalmente. Ex-l\u00edder do PSL na C\u00e2mara, Delegado Waldir (PSL-GO) disparou: \u201cBolsonaro defendia soldados e cabos e agora n\u00e3o mais?\u201d<\/p>\n<p class=\"par_texto\">Vitor Hugo (PSL-GO), l\u00edder do governo na C\u00e2mara, confessou que foi uma op\u00e7\u00e3o da equipe econ\u00f4mica do presidente privilegiar as altas patentes. \u201cHouve uma preocupa\u00e7\u00e3o do governo federal de fazer algo que fosse voltado para o privil\u00e9gio do m\u00e9rito, da meritocracia, da perman\u00eancia dos militares nas for\u00e7as e para privilegiar aqueles militares que t\u00eam um desempenho melhor na carreira\u201d.<\/p>\n<p class=\"par_texto\"><strong>V\u00cdDEO:<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Militares e familiares gritam \u201cBolsonaro traidor\u201d na C\u00e2mara\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Dd0MgxMl8ms?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/section>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto isso, outra come\u00e7ou a gritar \u201ctrairagem\u201d ao fundo. Uma terceira mulher afirmou que nem Bolsonaro, nem seus filhos, ter\u00e3o os votos da \u201cfam\u00edlia militar\u201d outra vez.<\/p>\n<p>A revolta ocorreu porque Jair Bolsomaro mobilizou de<\/p>\n","protected":false},"author":5,"featured_media":299934,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-299933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/10\/reforma-militares.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=299933"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/299933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/299934"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=299933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=299933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=299933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}