{"id":300187,"date":"2019-11-01T10:14:03","date_gmt":"2019-11-01T13:14:03","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=300187"},"modified":"2019-11-01T10:14:03","modified_gmt":"2019-11-01T13:14:03","slug":"ciro-gomes-culpa-lula-por-tudo-de-ruim-que-esta-acontecendo-no-brasil","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/ciro-gomes-culpa-lula-por-tudo-de-ruim-que-esta-acontecendo-no-brasil\/","title":{"rendered":"Ciro Gomes culpa Lula por tudo de ruim que est\u00e1 acontecendo no Brasil"},"content":{"rendered":"<div class=\"servicos-topo-post\">\n<div class=\"box-autoria-post\" style=\"text-align: justify;\">\n<div class=\"div_middle\"><\/div>\n<\/div>\n<\/div>\n<article class=\"artigo\">\n<section class=\"conteudo-post\">\n<h2 class=\"resumo\" style=\"text-align: justify;\"><em>Em nova entrevista, Ciro Gomes diz que Lula \u00e9 culpado por &#8220;trag\u00e9dia que est\u00e1 acontecendo no Brasil&#8221;. Para o pedetista, o ex-presidente \u00e9 um &#8220;enganador profissional&#8221;. Sobre Bolsonaro, diz que \u00e9 um &#8220;menino de 13 anos, paranoico&#8221;<\/em><\/h2>\n<div class=\"foto-conteudo-post centro completa\" style=\"text-align: justify;\">\n<div class=\"borda-foto\"><img decoding=\"async\" src=\"https:\/\/www.pragmatismopolitico.com.br\/wp-content\/uploads\/2019\/11\/ciro-gomes-2018-2530.jpg\" alt=\"ciro gomes lula\" \/><\/div>\n<div class=\"legenda-foto\">Ciro Gomes (Imagem: (Dida Sampaio\/Estad\u00e3o Conte\u00fado)<\/div>\n<div><\/div>\n<\/div>\n<p>Ciro Gomes chamou o ex-presidente Luiz In\u00e1cio Lula da Silva de \u201cenganador profissional\u201d. A declara\u00e7\u00e3o foi dada nesta quinta-feira (31) ao site\u00a0<em>Congresso em Foco<\/em>. O pedetista afirmou que dificilmente haver\u00e1 um entendimento com o petista caso ele saia da pris\u00e3o.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Confira a \u00edntegra da entrevista:<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O senhor tem viajado o pa\u00eds desde que acabou a elei\u00e7\u00e3o de 2018. Quais setores tem procurado mais nessas viagens? Seja partidos, movimentos sociais, entidades de classe.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Quando voc\u00ea tira quase 14 milh\u00f5es de votos, em uma democracia sadia, est\u00e1 longe de ser, mas eu colaboro para que ela seja, voc\u00ea recebe uma esp\u00e9cie de mandato tamb\u00e9m. Quem recebeu os 57 milh\u00f5es recebe o mandato de governar e aquele que recebeu 14 milh\u00f5es de votos tem a tarefa de cobrar, vigiar, apontar os defeitos e estou procurando fazer isso, exercitar essa honrad\u00edssima tarefa de construir um movimento, criar uma corrente de opini\u00e3o que compreenda o que est\u00e1 acontecendo com o Brasil fora das paix\u00f5es e \u00f3dios reducionistas que estabelece uma esp\u00e9cie de simbiose, um parasitismo rec\u00edproco entre o bolsonarismo e o petismo corrupto, e propor solu\u00e7\u00f5es. A cada cr\u00edtica tenho me obrigado a estudar e a propor alternativas, isso preferencialmente s\u00e3o meios universit\u00e1rios porque meu foco \u00e9 criar essa corrente de opini\u00e3o, mas eu tenho circulado tamb\u00e9m em ambientes populares, todos os convites que recebo, tenho circulado.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Houve, desde a elei\u00e7\u00e3o, um movimento progressista na internet, dentre os nomes posso destacar o do Henry Bugalho, por exemplo, como est\u00e1 esse movimento para 2020?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Estamos explicitamente dedicados a construir uma corrente de opini\u00e3o, o trabalhismo, ambiente onde atuo, fa\u00e7o a minha milit\u00e2ncia, est\u00e1 aberto a novas filia\u00e7\u00f5es, mas esse movimento extrapola o PDT e tem um foco na juventude universit\u00e1ria por uma circunst\u00e2ncia pr\u00e1tica, eles s\u00e3o a um s\u00f3 tempo as maiores v\u00edtimas do que est\u00e1 acontecendo com o Brasil e t\u00eam o potencial de capturar os conceitos um pouco mais elaborados no ambiente que a pol\u00edtica a redu\u00e7\u00e3o o tempo inteiro. Saiu o Datafolha mostrando o desmilinguir da popularidade do Bolsonaro e ele ent\u00e3o faz um discurso dizendo que, claro que est\u00e1 errado, vai procurar corrigir, mas que as pessoas n\u00e3o ataquem muito se n\u00e3o o PT volta. No mesmo dia, a [presidente nacional do PT] Gleisi Hoffmann, que \u00e9 l\u00edder dessa quadrilha que hegemonizou o PT, diz que n\u00e3o existe centro no Brasil, o que existe no Brasil \u00e9 o PT e Bolsonaro. Eu acredito que este reducionismo est\u00e1 fazendo muito mal ao Brasil, foi isto que produziu o bolsonarismo e a gente precisa construir um caminho para sair disso.<\/p>\n<div id=\"lx_638863\" class=\"__lxG__multi __lxG__multi_lx_638863\" style=\"text-align: justify;\">\n<div data-lxpresource=\"1\"><\/div>\n<\/div>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Como avalia esses 10 meses do governo de Jair Bolsonaro?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Est\u00e1 pior do que supunha porque a Presid\u00eancia da Rep\u00fablica tem uma capacidade convocat\u00f3ria absolutamente extraordin\u00e1ria. Essa capacidade convocat\u00f3ria \u00e9 declinante com o tempo, mas ela no primeiro dia do governo, entre a elei\u00e7\u00e3o e a posse, atinge o limite m\u00e1ximo, que praticamente 100% das energias do pa\u00eds est\u00e3o dispon\u00edveis para uma convoca\u00e7\u00e3o do presidente. Qual n\u00e3o \u00e9 o meu susto, embora n\u00e3o esperasse nada bom do Bolsonaro, mas \u00e9 muito pior porque ele se cerca de um governo que tem basicamente tr\u00eas vetores: uma pseudo racionalidade neoliberal mofada que n\u00e3o conhece o Brasil, que \u00e9 o Paulo Guedes, um n\u00facleo que estou chamando de pra\u00e7a da alegria, um bando de louco, alucinado , esse ministro do Meio Ambiente [Ricardo Salles], o ministro das Rela\u00e7\u00f5es Exteriores [Ernesto Ara\u00fajo], a ministra da Mulher [Damares Alves], e esse n\u00facleo militar tamb\u00e9m corrompido, corrompido pelo poder, que pensou que ia tutelar o Bolsonaro e na verdade est\u00e1 sendo usado pelo Bolsonaro para navegar esse projeto de poder abirobado que ele tem.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Tem algum ministro que o sr. considere que esteja fazendo um bom trabalho?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">O ministro da Infraestrutura [Tarc\u00edsio de Freitas] n\u00e3o destoa sob o ponto de vista de qualifica\u00e7\u00e3o. O Paulo Guedes \u00e9 uma pessoa respeit\u00e1vel por mim, ele n\u00e3o conhece o Brasil, \u00e9 intoxicado ideologicamente, nunca compreendeu, nem jamais compreender\u00e1 o Brasil, parou de ler h\u00e1 muito tempo, mas \u00e9 uma pessoa trat\u00e1vel, respeit\u00e1vel sob esse ponto de vista. Mas esse ministro do Meio Ambiente \u00e9 um bandido, esse ministro das Rela\u00e7\u00f5es Exteriores \u00e9 um lun\u00e1tico e por a\u00ed vai.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O que o governo pode fazer sobre as manchas de \u00f3leo nas praias do Nordeste?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Discriminar uma regi\u00e3o atenta contra a unidade nacional, que \u00e9 um dos casos cl\u00e1ssicos de crime de responsabilidade. Eu tenho at\u00e9 defendido que o Minist\u00e9rio P\u00fablico deveria abrir uma investiga\u00e7\u00e3o para compreender, j\u00e1 se passaram 60 dias e n\u00e3o h\u00e1 nenhuma provid\u00eancia estrat\u00e9gica nas duas obriga\u00e7\u00f5es inadi\u00e1veis, uma \u00e9 a conten\u00e7\u00e3o do dano que ainda est\u00e1 se aprofundando, fui visitar agora o litoral, e o dano econ\u00f4mico, o que est\u00e1 acontecendo agora? Muita gente cancelando visita tur\u00edstica, que j\u00e1 um preju\u00edzo extenso, e todo mundo que vive da pesca est\u00e1 come\u00e7ando a sofrer porque as pessoas n\u00e3o compram mais com medo da intoxica\u00e7\u00e3o. De outro lado a identifica\u00e7\u00e3o dos respons\u00e1veis por isso, \u00e9 preciso pedir coopera\u00e7\u00e3o internacional, n\u00e3o \u00e9 razo\u00e1vel que a altura dessa fiquem em especula\u00e7\u00e3o pirada, ideol\u00f3gica ao inv\u00e9s de abrir um inqu\u00e9rito s\u00e9rio, pedir coopera\u00e7\u00e3o internacional, tem hoje sat\u00e9lite geoestacion\u00e1rio, mem\u00f3ria de v\u00eddeo de tudo que acontece no planeta Terra em tempo real com mem\u00f3rias recuper\u00e1veis, tem o mapeamento dos fluxos de petr\u00f3leo, mapeamento das correntes mar\u00edtimas, dos ventos. Com o cruzamento disso, acredito que seria muito dif\u00edcil a gente n\u00e3o identificar e cobrar a indeniza\u00e7\u00e3o.<\/p>\n<div id=\"lx_638863\" class=\"__lxG__multi __lxG__multi_lx_638863\" style=\"text-align: justify;\" data-cnt=\"2\">\n<div id=\"dfp_spec_lx_638863_2\" data-google-query-id=\"CPW9s4aKyeUCFcx2wQodOiEIpg\">\n<div id=\"google_ads_iframe_\/45470634\/clickio_area_638863_336x280_1__container__\"><iframe loading=\"lazy\" id=\"google_ads_iframe_\/45470634\/clickio_area_638863_336x280_1\" title=\"3rd party ad content\" src=\"https:\/\/tpc.googlesyndication.com\/safeframe\/1-0-36\/html\/container.html\" name=\"\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-pointer-lock allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-is-safeframe=\"true\" data-google-container-id=\"2\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O governo extinguiu em abril um comit\u00ea respons\u00e1vel por lidar com cat\u00e1strofe por \u00f3leo e al\u00e9m de acusar a Venezuela, o governo acusou o Greenpeace de fazer esse derramamento.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Esse ministro do Meio Ambiente \u00e9 um bandido, n\u00e3o \u00e9 uma express\u00e3o mais quente, mais calorosa, ele \u00e9 condenado por improbidade [quando secret\u00e1rio de Meio Ambiente do ex-governador de S\u00e3o Paulo Geraldo Alckmin (PSDB)] porque fraudou mapas da bacia do rio Tiet\u00ea para privilegiar interesses econ\u00f4micos. Ele tem seu sigilo banc\u00e1rio e fiscal requerido a queda porque ele \u00e9 um bandido. Ele est\u00e1 posto por Jair Messias Bolsonaro para ser bandido, que \u00e9 o que ele de fato \u00e9.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Foi divulgado e depois apagado pelo Twitter do presidente Bolsonaro um v\u00eddeo no qual ele \u00e9 comparado a um le\u00e3o atacado por hienas que seriam o PSL, PSDB, PT, PDT, PSB, STF, OAB, entre outros.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Se voc\u00ea reparar, o Bolsonaro tem uma l\u00f3gica, \u00e9 uma l\u00f3gica est\u00fapida, de um menino de 13 anos paranoico, mas a l\u00f3gica dele \u00e9 basicamente o seguinte, ele cria uma aberra\u00e7\u00e3o qualquer todas as vezes que tem um fato real, grave, grav\u00edssimo avan\u00e7ando na dire\u00e7\u00e3o dele. O que precisamos neste momento? \u00c9 n\u00e3o cair nesse jogo. As grava\u00e7\u00f5es do Queiroz revelam que ele \u00e9 muito mais do que j\u00e1 se supunha que ele fosse. Ele est\u00e1 lidando com seres estrat\u00e9gicos com uma intimidade, naturalidade depois do esc\u00e2ndalo j\u00e1 acontecido que revela tamb\u00e9m a renit\u00eancia delinquente de um homem que tem dez homic\u00eddios nas costas e que faz parte de um grupo ligado \u00e0s mil\u00edcias do Rio de Janeiro. \u00c9 dinheiro roubado, usando a express\u00e3o popular, dinheiro subtra\u00eddo dos cofres p\u00fablicos pelo Bolsonaro, ele pr\u00f3prio deputado federal, pelos filhos senador, vereador, deputado estadual e a mulher dele, Bolsonaro, recebendo dinheiro do Queiroz, e a conex\u00e3o com as mil\u00edcias. Isso \u00e9 o que precisa ser esclarecido, n\u00e3o adianta Jair Bolsonaro ficar inventando filmezinho, neg\u00f3cio de homem mijando em cima de homem como foi em outra ocasi\u00e3o o mesmo truque.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Como est\u00e1 a conversa com o PT?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">O Lula n\u00e3o est\u00e1 nada bem. S\u00f3 esclarecer, se algu\u00e9m vir uma \u00fanica sozinha declara\u00e7\u00e3o minha me queixando de que o PC do B n\u00e3o veio para mim, foi para o PT, ent\u00e3o Lula ter\u00e1 raz\u00e3o, mas ele est\u00e1 mentindo, nunca fiz essa queixa, jamais fiz essa queixa. O que eu tenho clareza \u00e9 o seguinte, com esta quadrilha que hegemonizou o PT eu n\u00e3o ando mais. Eu respeito muito o militante m\u00e9dio do PT, sei bastante bem separar o joio do trigo, se voc\u00ea pegar Ol\u00edvio Dutra, Raul Pont, Henrique Fontana, nenhum deles est\u00e1 envolvido em nenhuma falcatrua. Se pegar Eduardo Suplicy, n\u00e3o est\u00e1 envolvido em falcatrua. Se pegar Tarso Genro, enfim. Apoiei o Rui Costa [governador da Bahia], apoiei o Camilo Santana no meu estado nesta elei\u00e7\u00e3o, apoiei o Wellington Dias no Piau\u00ed nesta elei\u00e7\u00e3o, apoiei o Ti\u00e3o Viana no Acre de novo nesta elei\u00e7\u00e3o [Marcus Alexandre foi o candidato do PT na sucess\u00e3o de Ti\u00e3o Viana. Ficou em 2\u00ba lugar, atr\u00e1s do governador Gladson Camelli, eleito pelo PP]. Vamos separar bem as coisas, esta burocracia \u00e9 respons\u00e1vel pela debacle econ\u00f4mica mais grave da hist\u00f3ria do Brasil. O PT est\u00e1 forjando uma novil\u00edngua porque basicamente eles querem lembrar do per\u00edodo Lula em que o consumo cresceu de forma bastante generosa pelo sal\u00e1rio m\u00ednimo que melhorou, pelo cr\u00e9dito que explodiu de 17% para 55% do PIB, isto tudo \u00e9 verdade. Vem a Dilma e pega o desemprego em 4% e entrega com 14%, n\u00e3o consegue reunir um ter\u00e7os dos deputados federais no primeiro ano de governo. A Dilma que entra e promete uma faxina, faxina de que, cara p\u00e1lida? Quem faz faxina est\u00e1 limpando o que? Sujeira, quem produziu a sujeita? Ela nomeou Geddel Vieira Lima para a vice-presid\u00eancia da Caixa Econ\u00f4mica. O Lula nomeou Geddel e o Gedddel aquele que usa 51 milh\u00f5es de reais dentro de mala em um apartamento. Quem nomeou a diretoria da Petrobras toda que a Dilma afasta como uma faxina? Parece assim que o povo \u00e9 imbecil, eu n\u00e3o sou. Em um momento para diante, sabendo o que eu sei, se eu n\u00e3o rompo, eu sou c\u00famplice.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O senador Paulo Paim afirmou que o PT devia ter apoiado o senhor em 2018. Se o PT tivesse apoiado, o senhor aceitaria?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Outro petista, Paulo Paim, cad\u00ea Paulo Paim? S\u00f3 tenho elogios. N\u00e3o [aceitaria o apoio do PT], o meu plano n\u00e3o era esse, meu plano era apresentar uma alternativa, eu achava que se o PT tivesse um pingo de apre\u00e7o ao pa\u00eds e pensasse um minuto no Brasil e nos brasileiros e n\u00e3o em si pr\u00f3prio como m\u00e1quina de poder pelo poder, eles poderiam n\u00e3o ter lan\u00e7ado candidato. Se o PT vem comigo, quem iria perder era eu porque a for\u00e7a dominante naquelas elei\u00e7\u00f5es muito justamente, ou parte injustamente porque a vida real \u00e9 assim, era o antipetismo, se o PT vem comigo eu perdia a elei\u00e7\u00e3o.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O governador do Cear\u00e1, Camilo Santana, falava desde 2017, mais de um ano antes da elei\u00e7\u00e3o, que defendia uma chapa com o senhor e Fernando Haddad e essa declara\u00e7\u00e3o nunca foi desautorizada pelo senhor.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Eu tive essa conversa com Haddad e disse para ele que primeiro a natureza do PT \u00e9 como a do escorpi\u00e3o, n\u00e3o me apoiaria em nenhuma circunst\u00e2ncia. A segunda quest\u00e3o \u00e9 que o PT preferia perder na elei\u00e7\u00e3o, obviamente o Lula. Luiz In\u00e1cio Lula da Silva, que \u00e9 um g\u00eanio da pol\u00edtica sabia que a elei\u00e7\u00e3o estava perdida e resolveram fazer aquilo que ele sempre fez, cuidar do PT. O Lula faz uma fraude, vamos ter conveni\u00eancia, n\u00e3o \u00e9 poss\u00edvel que o Brasil esteja t\u00e3o anestesiado, que a generosidade do nosso povo com Lula seja tanta que se esque\u00e7a tudo. Quem botou a Lei da Ficha Limpa em vigor foi o Lula, contra a minha opini\u00e3o, por qu\u00ea? Eles hoje est\u00e3o advogando que a pris\u00e3o em segunda inst\u00e2ncia n\u00e3o \u00e9 correta. Pois bem, o que \u00e9 a Lei da Ficha Lima se n\u00e3o a subtra\u00e7\u00e3o dos direitos pol\u00edticos de um cidad\u00e3o subjudice? Cuja senten\u00e7a n\u00e3o transita em julgado ainda. Dentro do melhor direito \u00e9 uma aberra\u00e7\u00e3o, pois ele bota em vigor a lei e depois se apresenta como candidato? Todo mundo sabia que ele n\u00e3o podia ser candidato e o Haddad se presta a essa fraude e no limite ele queria que eu me prestasse a essa fraude, eu recusei.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Se Lula for solto, procuraria ou aceitaria conversar com ele caso ele convidasse?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Eu n\u00e3o me recuso a conversar com ningu\u00e9m, mas n\u00e3o tenho nenhum apre\u00e7o pol\u00edtico pelo Lula, nenhum. Acho que ele \u00e9 o grande respons\u00e1vel por essa trag\u00e9dia econ\u00f4mica, social e pol\u00edtica que o Brasil est\u00e1 vivendo, n\u00e3o tem grandeza, s\u00f3 pensa em si e virou um enganador profissional. Eu vi a \u00faltima entrevista dele e fiquei chocado, disse que acertou com Eduardo Campos para suced\u00ea-lo, mentira, mentira, ele vetou a candidatura de Eduardo Campos a governador [em 2006, o PT lan\u00e7ou Humberto Costa candidato ao governo de Pernambuco] e o Eduardo Campos chegou na minha sala chorando, trabalh\u00e1vamos no mesmo pr\u00e9dio [Campos era ministro da Ci\u00eancia e Tecnologia e Ciro da Integra\u00e7\u00e3o Nacional]. Liguei para o Lula e fui diretamente l\u00e1 exigir a retirada do veto. O Eduardo Campos foi candidato e eles fizeram o diabo para derrotar Eduardo Campos.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Passando um ano desde a elei\u00e7\u00e3o, ao que o senhor credita a sua derrota?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Isso n\u00e3o tem culpa, \u00e9 falta de voto, a \u00fanica explica\u00e7\u00e3o para derrota eleitoral \u00e9 que meu advers\u00e1rio teve mais voto que eu.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Como virar isso na pr\u00f3xima elei\u00e7\u00e3o?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Na minha mente, ideia, exemplo e milit\u00e2ncia.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Faltou isso em 2018?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Faltou tudo, no ambiente em que a principal for\u00e7a, isso a gente v\u00ea depois, n\u00e3o v\u00ea com tanta clareza antes, a principal for\u00e7a dominante no pa\u00eds do Sudeste para baixo e no Centro-Oeste era o antipetismo. Portanto a ideia minha estava mais ou menos sombreada porque corretamente as pessoas me identificaram como aliado do PT. Eu era o segundo voto da esquerda, o segundo voto da direita, mas o primeiro voto era o antipetismo. A grande elite tentou o Alckmin, n\u00e3o era Bolsonaro, engoliu o Bolsonaro, mas engoliu com muita dist\u00e2ncia porque o Amoedo n\u00e3o deu no coro, o Meirelles n\u00e3o deu para cima. Eu fiquei com 38 segundos [de tempo de propaganda eleitoral] na televis\u00e3o.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>A ex-senadora Marta Suplicy pode se filiar ao PDT?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Eu n\u00e3o conversei com a Marta, n\u00e3o, somos amigos de longa data, mas quem est\u00e1 conversando com ela \u00e9 o Lupi [presidente nacional do PDT]. Estamos conversando com todo mundo, temos uma conversa por exemplo com ACM Neto [presidente nacional do DEM e prefeito de Salvador], conversa relativamente ami\u00fade com Rodrigo Maia. Com Rodrigo Maia n\u00f3s fizemos uma exig\u00eancia para apoi\u00e1-lo para presidente da C\u00e2mara e ele est\u00e1 cumprindo rigorosamente. Exigimos dele duas coisas, que garantisse o espa\u00e7o de conten\u00e7\u00e3o de danos que n\u00f3s precisamos ocupar e ele est\u00e1 cumprindo rigorosamente, j\u00e1 conseguimos v\u00e1rias proezas no Congresso, sendo uma bancada pequena. A outra \u00e9 obrigar o Bolsonaro ao jogo democr\u00e1tico, ele est\u00e1 cumprindo exemplarmente. A hist\u00f3ria vai registrar por exemplo que ele foi o mais gravemente respons\u00e1vel por impedir que o Bolsonaro levasse o Brasil a uma guerra contra a Venezuela.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acha que na reforma da Previd\u00eancia, Maia conseguiu conter os danos?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Sim, ele \u00e9 diferente de tudo que a gente pensa, tem um pensamento absolutamente conservador, alinhado a essa economia rentista, do baronato financeiro do Brasil, e nosso compromisso n\u00e3o \u00e9 tir\u00e1-lo dessa condi\u00e7\u00e3o, \u00e9 garantir por exemplo que nas comiss\u00f5es especiais que nossa participa\u00e7\u00e3o seja garantida, nossos requerimentos sejam considerados e sejam deliberados, a gente sabe que somos minoria e nesse sentido ele tem cumprido 100% do que acertou conosco.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Tanto na C\u00e2mara quanto no senado teve gente do PDT que votou a favor da proposta do governo, defende que Tabata Amaral e K\u00e1tia Abreu tenham o mesmo tratamento por votarem pela reforma da Previd\u00eancia?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Votar a favor do governo nesse tipo de Previd\u00eancia n\u00e3o guarda a menor coer\u00eancia com um partido trabalhista, partido que carrega a mem\u00f3ria de Get\u00falio Vargas que foi quem criou a Previd\u00eancia P\u00fablica no Brasil. Tem um rito, esse rito foi seguido religiosamente, foi mat\u00e9ria de conven\u00e7\u00e3o nacional, todo mundo teve o direito de contestar posi\u00e7\u00e3o e ningu\u00e9m contestou, foi un\u00e2nime a posi\u00e7\u00e3o de fechar quest\u00e3o contra e hoje temos clareza que o partido tem rumo, rumo estrat\u00e9gico.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acredita que no campo da direita o DEM possa se fundir com o PSL e no da esquerda uma fus\u00e3o entre PDT e PSB?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">N\u00e3o \u00e9 prov\u00e1vel nem aquilo nem isto porque hoje com quest\u00e3o do fundo eleitoral, tendo por crit\u00e9rio bancadas, imaginar que o PSL vai se fundir com o Democratas, quem vai dirigir esse partido? Portanto quem vai ficar com caneta do fundo eleitoral gigantesca se isso acontecer? N\u00e3o h\u00e1 a menor probabilidade. N\u00f3s aqui respeitamos muito os nossos parceiros do PSB, \u00e9 um partido grande, temos um di\u00e1logo com o PSB que \u00e9 hist\u00f3rico, antigo e vamos manter esse di\u00e1logo, mas fus\u00e3o n\u00e3o \u00e9 prov\u00e1vel.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Tem participado das discuss\u00f5es sobre reforma tribut\u00e1ria? Em linhas gerais, qual seria a reforma defendida pelo senhor?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">As duas propostas que est\u00e3o tramitando, nenhuma delas merece o nome reforma tribut\u00e1ria. S\u00e3o duas iniciativas de simplifica\u00e7\u00e3o da administra\u00e7\u00e3o tribut\u00e1ria para atender aos empres\u00e1rios, o que n\u00e3o \u00e9 ileg\u00edtimo, mas ela n\u00e3o cumpre as outras graves tarefas de uma coisa que mere\u00e7a o nome de reforma tribut\u00e1ria. A primeira \u00e9 o financiamento eficaz do setor p\u00fablico, a segunda \u00e9 a progressividade, a ferramenta mais relevante na distribui\u00e7\u00e3o de renda. S\u00f3 o Brasil e a Est\u00f4nia n\u00e3o cobram impostos sobre lucros e dividendos, eu cobrei quando fui ministro da Fazenda do Itamar [Franco, presidente do Brasil entre 1992 e 1994], Fernando Henrique revogou e o lulopetismo manteve revogado. Ningu\u00e9m \u00e9 de esquerda porque se afirma de esquerda. S\u00f3 Brasil e Est\u00f4nia n\u00e3o cobram sobre lucros e dividendos. Voc\u00ea tem hoje as ren\u00fancias fiscais, antes de fazer uma reforma tribut\u00e1ria, voc\u00ea tem a\u00ed 350 bilh\u00f5es de reais este ano de ren\u00fancia fiscal sem nenhum crit\u00e9rio. Em tempos de crise, n\u00f3s j\u00e1 fizemos no Cear\u00e1, por que voc\u00ea n\u00e3o desconta 20% disso? As duas provid\u00eancias acabam com o d\u00e9ficit. Voc\u00ea tem o ITR [Imposto sobre a Propriedade Rural] no Brasil, nessa grande fazenda do agroneg\u00f3cio mundial que \u00e9 o Brasil, recolhe um bilh\u00e3o de reais por ano, o IPTU da classe m\u00e9dia recolhe 20 milh\u00f5es de reais. Imposto sobre grandes heran\u00e7as, acima de 3, 4, 5 bilh\u00f5es de reais, nos Estados Unidos \u00e9 40%, no Brasil \u00e9 4%. Essa reforma passa longe de uma reforma tribut\u00e1ria verdadeira.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O governo tem falado de desonerar empresas.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">A proposta do Guedes seria criar uma nova CPMF. Eu propus abrir a discuss\u00e3o na campanha porque considerava decente legitimar isso no processo eleitoral, eles [ campanha de Jair Bolsonaro] ficaram violentamente contra. O Guedes, talvez essa vai ser a raz\u00e3o final para ele ir embora, quer propor uma CPMF ainda mais dura que eu propus porque eu criava uma faixa de isen\u00e7\u00e3o de at\u00e9 5000 reais por CPF\/MEI. Era uma coisa s\u00f3 para o andar de cima e ganharia 60, 70 bilh\u00f5es de reais. Eu tinha como virar o jogo do d\u00e9ficit p\u00fablico brasileiro em 24 meses apenas por conta da anterioridade, fiscalmente voc\u00ea tem condi\u00e7\u00f5es de virar o jogo em 12 meses. Qual era a l\u00f3gica do Guedes? Propor esse tributo e tirar a contribui\u00e7\u00e3o patronal da folha de pagamento. Isso \u00e9 uma aberra\u00e7\u00e3o, voc\u00ea acaba de fazer um sacrif\u00edcio imenso para fazer uma reforma da Previd\u00eancia que pesa 83 em cada 100 reais de quem ganha at\u00e9 3000 reais de sal\u00e1rio e vai agora desonerar dois ter\u00e7os da arrecada\u00e7\u00e3o da Previd\u00eancia. Temos que fazer uma reforma previdenci\u00e1ria s\u00e9ria, essa reforma previdenci\u00e1ria s\u00e9ria foi proposta por n\u00f3s na campanha enquanto Bolsonaro dizia com todos os esses e erres que era contra. Falava que [se aposentar aos] 65 anos \u00e9 um absurdo, como falava em privatiza\u00e7\u00e3o, a entrega criminosa, o Fernando Henrique devia ser fuzilado porque vendeu a Vale do Rio Doce. Agora est\u00e1 a\u00ed como mascate de quinta categoria entregando as riquezas do Brasil aos estrangeiros.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acha que h\u00e1 consenso hoje no pa\u00eds para algum tipo de reforma tribut\u00e1ria?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">N\u00e3o \u00e9 prov\u00e1vel. Estamos no pior momento para propor uma reforma tribut\u00e1ria, momento de d\u00e9ficit grave. Toda e qualquer reforma tribut\u00e1ria que vai em dire\u00e7\u00e3o de atender ao empresariado diminui a receita e o governo pode abrir m\u00e3o de receita neste momento? Tanto que o governo at\u00e9 o presente momento n\u00e3o tem proposta nenhuma. Essas propostas que est\u00e3o circulando e a gente est\u00e1 esmiu\u00e7ando \u00e9 inacredit\u00e1vel. Por exemplo diminuir a incid\u00eancia dos bancos, o \u00fanico setor que est\u00e1 nadando de bra\u00e7ada com a economia real toda indo para o vinagre, os bancos t\u00eam o maior lucro dos \u00faltimos 25 anos, e olhe que o lucro do governo PT foi sem precedente internacional. Isso \u00e9 ser de esquerda para essa burocracia corrompida do PT, ser de esquerda \u00e9 garantir a concentra\u00e7\u00e3o de 85% das opera\u00e7\u00f5es financeiras em apenas cinco bancos, \u00e9 fazer a popula\u00e7\u00e3o carcer\u00e1ria, o jovem negro, subir de 270 mil para 720 mil, \u00e9 resolver o problema depois de 14 anos da sa\u00fade p\u00fablica do Brasil trazendo m\u00e9dico de Cuba, n\u00e3o alteraram uma linha na quest\u00e3o da forma\u00e7\u00e3o. \u00c9 basicamente um projeto de pa\u00eds que n\u00e3o tem, o projeto deles \u00e9 poder pelo poder. Hoje os bancos pagam ISS sobre as tarifas, est\u00e3o fundindo o ISS com o IVA, que \u00e9 o que vai se chamar IBS nessa duas propostas [IVA \u00e9 o imposto unificado no texto do Senado e IBS \u00e9 o do texto da C\u00e2mara], s\u00f3 que os bancos pagam Contribui\u00e7\u00e3o Social sobre Lucro L\u00edquido sobre PIS\/Cofins na rentabilidade das transa\u00e7\u00f5es financeiras, como eles v\u00e3o trazer isso tamb\u00e9m para dentro [do imposto unificado], fica desonerado o banco. Por que n\u00e3o temos uma reforma tribut\u00e1ria correta? As melhores pr\u00e1tica internacionais cobram IVA, qual \u00e9 caracter\u00edstica do IVA? Imposto sobre consumo destacado na nota e cobrado no destino. Nunca S\u00e3o Paulo vai permitir que isso se enquadre no Brasil. Isso ser\u00e1 apoiado por Minas, Rio e e Rio Grande do Sul. O ICMS, que foi imposto pela ditadura e foi recopiado pela Constitui\u00e7\u00e3o de 1988, que foi o Serra que fez, o que acontece? Hoje o sistema de tributa\u00e7\u00e3o no consumo brasileiro \u00e9 cobrado na origem. Se hoje l\u00e1 no Cear\u00e1 o camarada paga 17% em uma televis\u00e3o, 8% vai bater em S\u00e3o Paulo. Se eu cobro um IVA, esses 17% ficam l\u00e1, S\u00e3o Paulo perde 8%. S\u00e3o Paulo est\u00e1 com a linha dada para quebrar, n\u00e3o quebrou ainda porque faz quatro anos que n\u00e3o reajusta os funcion\u00e1rios e passou oito meses sem pagar d\u00edvida com uma liminar, dessas aberra\u00e7\u00f5es que acontecem no Brasil. Posso at\u00e9 ser surpreendido, mas S\u00e3o Paulo est\u00e1 com a linha dada no nariz para se afogar, vai deixar? V\u00e3o criar o IVA que \u00e9 um mostrengo. Eu crio um IVA no destino, mas pego a receita adicional que der, boto em um fundo para S\u00e3o Paulo, ora, isso \u00e9 um ICMS.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Quem ser\u00e1 o candidato do PDT em S\u00e3o Paulo ano que vem? Marta Suplicy \u00e9 uma op\u00e7\u00e3o?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Vamos dar o tempo dela, n\u00e3o vamos especular isso n\u00e3o.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Lula fez em entrevista ao Uol uma analogia com o filme Central do Brasil, se comparou a personagem da Fernanda Montenegro e disse que o senhor \u00e9 o menino rebelde que ela tenta ajudar.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Ele n\u00e3o est\u00e1 nada bem porque n\u00e3o entendeu nada do filme ou ato falho, que mais Freud explica do que eu. O personagem da Fernanda Montenegro \u00e9 uma velha picareta, desonesta, que rouba, recebe dinheiro do povo para escrever cartas , do povo analfabeto mais simples e joga as cartas fora e fica com o dinheiro do povo. Ela estava negociando o corpo do menino, que ia ser assassinado, para vender os \u00f3rg\u00e3os do menino. Esse \u00e9 o personagem que o Lula assumiu para si e eu seria o menino, ele n\u00e3o est\u00e1 nada bem.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Depois do encontro no Cine Cear\u00e1, houve alguma conversa com Fernando Haddad?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">O festival Cine Cear\u00e1 acontece todo ano e eu tenho hist\u00f3ria de comparecer,ajudei a consolidar o festival e fui ver o filme [A Vida Invis\u00edvel de Eur\u00eddice Gusm\u00e3o], filme espetacular de um diretor cearense [Karim Ainouz] com a Fernanda Montenegro que \u00e9 uma querida amiga de 30 anos, minha eleitora inclusive, que o Lula fique sabendo. Ele [Fernando Haddad] senta e quando acaba a solenidade, baixou o escurinho, levantou e foi embora, s\u00f3 quem assistiu ao filme fui eu. A fake news, a vers\u00e3o \u00e9 o que importa agora. Nos cumprimentamos como sempre.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Mas ele tem procurado o senhor depois da elei\u00e7\u00e3o?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">N\u00e3o, nem no dia da elei\u00e7\u00e3o, esse povo n\u00e3o gosta muito da verdade, n\u00e3o. Aqui meu telefone, meu sigilo de telefone, se tiver uma liga\u00e7\u00e3o dele aqui voc\u00ea pode ficar com meu bra\u00e7o.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Qual sua avalia\u00e7\u00e3o sobre Fernando Haddad independente de PT e Lula?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">\u00c9 uma boa pessoa. Agora qual pa\u00eds e democracia do mundo o cidad\u00e3o que \u00e9 candidato a reelei\u00e7\u00e3o no cargo da principal cidade do pa\u00eds tem 16% apenas dos votos, perde em todas as urnas de S\u00e3o Paulo, da classe pobre, classe m\u00e9dias e dos ricos, \u00e9 ele pr\u00f3prio escolhido para ser candidato a presidente um ano depois? L\u00e1 no Cear\u00e1 eu ganhei a elei\u00e7\u00e3o. Na capital [Fortaleza] onde est\u00e1 o eleitorado mais cr\u00edtico Haddad foi o terceiro lugar. Veio o segundo [turno], ele [Haddad] tirou 75% dos votos no Cear\u00e1. Na terra dele tirou 32% e o Bolsonaro tirou 68% dos votos. Sou eu o problema?<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O senhor foi o primeiro governador eleito pelo PSDB. O que tem achado desse novo momento com a ascend\u00eancia de Jo\u00e3o Doria?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">A hist\u00f3ria no Brasil se repete como farsa, estou vendo ali o novo Adhemar de Barros, do PRP. N\u00e3o existe mais PSDB, foi destru\u00eddo pelo Doria e est\u00e1 organizando nos escombros do PSDB o PRP, um partido dele com base em S\u00e3o Paulo e basicamente nenhuma inser\u00e7\u00e3o no resto do pa\u00eds.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acha que Doria vai conseguir transformar o PSDB?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Eu n\u00e3o consigo ver o governador do Rio Grande do Sul [Eduardo Leite], Tasso Jereissati e Geraldo Alckmin caminhando junto com Doria mais o Frota e Joice Hasselmann. N\u00e3o consigo ver isso, a n\u00e3o ser que esteja muito enganado. O que estou vendo \u00e9 o seguinte, o Alckmin com toda a estrutura que tinha perdeu para mim em S\u00e3o Paulo, aparentemente \u00e9 um quadro respeitabil\u00edssimo. Parece que o problema \u00e9 com o PSDB, tanto que o Doria fica inventando essas coisas de novo PSBD, todo picareta no Brasil bota novo na frente.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Eduardo Leite apoiou Bolsonaro no 2\u00ba turno, acha que foi um apoio diferente do Doria?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">L\u00e1 no Rio Grande do Sul o Bolsonaro tirou quase 70%. Em Porto Alegre por exemplo eu tirei o segundo lugar. A mim me parece [sobreviv\u00eancia eleitoral] pelo quadro geral dele, o tipo de pessoa que me parece \u00e0 dist\u00e2ncia.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Bolsonaro termina o mandato?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">J\u00e1 dei esse palpite, na minha mente n\u00e3o. De onde vem esse meu palpite? Vem de dois fatos, um a hist\u00f3ria brasileira, no Brasil moderno s\u00f3 tr\u00eas presidentes terminaram o mandato, Juscelino, Fernando Henrique e Lula. J\u00e1 \u00e9 uma regra mais ou menos constrangedora na hist\u00f3ria do Brasil. Segundo que Bolsonaro n\u00e3o tem treinamento para o antagonismo, todo dia revela, n\u00e3o tem capacidade, ele \u00e9 paranoico, outro dia deu entrevista pat\u00e9tica dizendo que acorda de madrugada chorando, voc\u00ea imagina no come\u00e7o do governo quando tem a lua de mel e Congresso ajudando, todo mundo querendo ajudar, imagina daqui a pouco quando estourar mesmo o esc\u00e2ndalo do Queiroz, o dinheiro na conta da mulher dele, os filhos tudo ali enrolado com mil\u00edcia, ele pr\u00f3prio enrolado com mil\u00edcia, tudo isso est\u00e1 ali e a economia jogando de lado.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acredita que Luciano Huck pode ser candidato em 2022?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">A elite brasileira est\u00e1 desesperada atr\u00e1s de um novo animador de audit\u00f3rio. Se voc\u00ea reparar, a Presid\u00eancia da Rep\u00fablica virou lugar para qualquer pessoa, qualquer estagi\u00e1rio, desde que o baronato controle o Banco Central e eles v\u00e3o exigir do Bolsonaro que ele pr\u00f3prio fa\u00e7a a castra\u00e7\u00e3o de seu pr\u00f3prio poder, fazendo o estatuto de autonomiza\u00e7\u00e3o do Banco Central. Coisa que ali\u00e1s o Haddad prop\u00f4s no programa dele. No Brasil \u00e9 assim, o PT se diz de esquerda e faz um programa propondo uma constituinte, um neg\u00f3cio completamente sem p\u00e9 nem cabe\u00e7a e prop\u00f5e a autonomia do Banco Central.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Vai se candidatar em 2022 novamente, mas com um discurso menos acad\u00eamico?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Eu sou um velho ganhador de elei\u00e7\u00f5es, n\u00e3o \u00e9 poss\u00edvel fazer essa redu\u00e7\u00e3o. A explica\u00e7\u00e3o \u00e9 isso, o outro lado teve mais votos. A inclina\u00e7\u00e3o da opini\u00e3o p\u00fablica naquele momento, de uma polariza\u00e7\u00e3o que vinha de d\u00e9cadas, era o antipetismo mais tosco, mais claro de ser visto e todo o baronato acabou fechando ali para apoiar. Fui visto como uma pessoa respeit\u00e1vel, tinha a menor rejei\u00e7\u00e3o de todos, por\u00e9m aliado do PT, o que rigorosamente era verdade. Fiquei na contram\u00e3o do principal trending naquela elei\u00e7\u00e3o. Minha quest\u00e3o de linguagem \u00e9 que n\u00e3o tem lugar para mim nesta briga de preto contra encarnado, nem para ningu\u00e9m no Brasil. Se a gente deixar: Bolsonaro \u00e9 um merda, n\u00e3o, merda \u00e9 voc\u00ea. Fica a\u00ed o rebosteio e o pa\u00eds vai para o brejo. Eu sou um velho ganhador de elei\u00e7\u00f5es, acabei de ganhar elei\u00e7\u00f5es no meu estado porque as pessoas me conhecem. Estou propondo um projeto nacional porque a qualidade desse voto me interessa. Acha que eu n\u00e3o sei se falar em reforma da Previd\u00eancia na campanha pode gerar incompreens\u00f5es? Acha que eu n\u00e3o sei se falar em uma nova CPMF com faixa de isen\u00e7\u00e3o n\u00e3o pode arriscar porque n\u00e3o tem voto? Tudo bem, o que eu estava fazendo? Aquilo que achava a \u00fanica forma de atenuar a l\u00f3gica de impasse do presidencialismo \u00e0 brasileira, que \u00e9 voc\u00ea propor antes e portanto fazer das elei\u00e7\u00f5es presidenciais um plebiscito ao redor de ideias e n\u00e3o de personalidades. Vou apostar nisso, meu esfor\u00e7o de traduzir isso est\u00e1 sendo todo dia aperfei\u00e7oado, quero achar um caminho, todo mundo entende que no Brasil rico n\u00e3o paga imposto e pobre \u00e9 que paga. \u00c0s vezes quando desco um pouquinho mais v\u00eam me acusar de outra coisa, de pavil curto, de temperamental porque n\u00e3o querem que o povo saiba as coisas.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Acompanhou as elei\u00e7\u00f5es na Argentina? Acha que Fern\u00e1ndez foi um bom candidato?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Acompanhei tudo desde o princ\u00edpio. Ele \u00e9 mais qualificado que a Cristina [Kirchner, ex-presidente e futura vice-presidente da Argentina] sob o ponto de vista de preparo pessoal. Acho que ele est\u00e1 com uma compreens\u00e3o mais sofisticada da quest\u00e3o, um mark to the past da Cristina n\u00e3o tira da Argentina da trag\u00e9dia onde ela se encontra. O capital pol\u00edtico dele vai durar muito pouco se n\u00e3o tomar provid\u00eancias importantes. Na pr\u00e9-campanha eu fui contratado profissionalmente para dar uma consultoria para uma empresa de marketing que estava fazendo assessoria, eu estava ajudando a desenhar o programa, por isso mergulhei fundo na quest\u00e3o da Argentina, \u00e9 uma trag\u00e9dia, uma trag\u00e9dia monstruosa. Se eles n\u00e3o fizerem um rumo novo, diferente, \u00e9 muito dif\u00edcil que ele consiga se engrenar.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Como avalia a crise entre Jair Bolsonaro e PSL?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Bolsonaro \u00e9 um despreparado paranoico. Uma caracter\u00edstica do paran\u00f3ico \u00e9 brigar com sua circunst\u00e2ncia, \u00e9 ver o inimigo do seu lado. Ele \u00e9 um despreparado completo e paranoico.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Alguns deputados do PSL afirmam que n\u00e3o t\u00eam contato com o presidente Bolsonaro, seria isso a causa?<br \/>\nEle tem horror a isso. Fui colega dele na C\u00e2mara, ningu\u00e9m cumprimentava o Bolsonaro porque ele tem horror, \u00e9 avesso \u00e0 conviv\u00eancia com as pessoas. Eu chegava, me comunicava com ele, [Bolsonaro] dizia que tinha votado em mim, tinha um gabinete a 50 metros, 30 metros do meu, passava na minha sala para me perguntar as coisas. Bolsonaro \u00e9 um paranoico, ele n\u00e3o acreditava\u2026 Um cara como eu, todo dia acordo e: \u2018porra, como elegeram esse cara?\u2019.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Como vislumbra o bolsonarismo daqui a 10 anos?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Essa for\u00e7a vai estar pesada no Brasil e ela est\u00e1 sendo j\u00e1 rivalizada com Huck, Doria e esse Witzel [governador do Rio de Janeiro]. O Huck est\u00e1 melhor assessorado porque est\u00e1 percebendo que \u00e9 necess\u00e1rio dourar a p\u00edlula. Toda declara\u00e7\u00e3o ele fala assim: \u2018a pol\u00edtica econ\u00f4mica est\u00e1 correta\u2019. Depois come\u00e7a a falar que o pa\u00eds tem desigualdade, como se a desigualdade n\u00e3o fosse produto daquilo que ele defende \u00c9 isso, o problema de botar estagi\u00e1rio na Presid\u00eancia da Rep\u00fablica.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Quem deve ser o candidato do centro? Huck, Doria, o senhor? Acha que consegue atrair o DEM e partidos de esquerda na pr\u00f3xima elei\u00e7\u00e3o?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Deus \u00e9 quem sabe, essa travessia do Rubic\u00e3o, assim como aquela do J\u00falio C\u00e9sar, \u00e9 meio solit\u00e1ria. Eu tenho que provar que sou vi\u00e1vel, tenho que atravessar o rio e correr os riscos sozinho.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>DEM e outros partidos do Centr\u00e3o ficaram entre o senhor e Alckmin na \u00faltima elei\u00e7\u00e3o, mas decidiram pelo Alckmin.<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Dancei na curva, pronto, \u00e9 isso a\u00ed. Mas eles fizeram uma aposta errada [Ciro teve quase o triplo de votos de Alckmin no primeiro turno da elei\u00e7\u00e3o presidencial de 2018], agora \u00e9 outra data com as li\u00e7\u00f5es de ontem. Tenho que ter os meus 15% e tal, com o PDT, isso aqui \u00e9 cacife, vamos conversar, senta aqui que tem 15 milh\u00f5es de pessoas olhando para mim, quanto que isso vale aqui nesta mesa?<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>O di\u00e1logo com ACM Neto e Maia \u00e9 nesse sentido de apoio eleitoral?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">Temos as elei\u00e7\u00f5es municipais, nossa macro diretriz \u00e9 lan\u00e7ar candidato pr\u00f3prio do PDT nas grandes cidades, capitais e marcar o campo. Em princ\u00edpio n\u00e3o faremos alian\u00e7a com o PT. Estamos avan\u00e7ando e por exemplo em Salvador estamos conversando com o DEM.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>No Rio de Janeiro pode apoiar Eduardo Paes?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">No Rio de Janeiro vamos apoiar Marta [Rocha, pr\u00e9-candidata pelo PDT], nossa candidata. Eu duvido que Eduardo Paes seja candidato.<\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\"><strong>Ele \u00e9 pr\u00f3ximo do senhor?<\/strong><\/p>\n<p class=\"par_texto\" style=\"text-align: justify;\">\u00c9 meu amigo de mil anos. Tem nada a ver com DEM. Eduardo Paes, s\u00f3 para ver como as coisas s\u00e3o, Eduardo Paes era deputado federal agressivo na CPI dos Correios, que era a CPI do Mensal\u00e3o, tinha um requerimento para gente chamar o filho do Lula. Todo dia, sete horas da manh\u00e3, tinha reuni\u00e3o com Lula, o Lula chorou e tal. Ele disse que me viu chorando, tamb\u00e9m vi ele chorando muitas vezes e uma delas foi essa, n\u00e3o queria ser convocado [o filho] para CPI. Eu percebi que aquilo era o limite, liguei para algumas pessoas e disse: \u2018\u00e9 da\u00ed para tr\u00e1s\u2019. Uma das pessoas era A\u00e9cio Neves, que era governador de Minas Gerais. \u2018A\u00e9cio, \u00e9 da\u00ed para tr\u00e1s\u2019. \u2018Ciro, fico feliz que voc\u00ea tenha ligado porque tamb\u00e9m estou achando que est\u00e1 passando do limite e tal, mas ningu\u00e9m conversa\u2019. \u2018Estou te dizendo que \u00e9 da\u00ed para tr\u00e1s, n\u00e3o vamos aceitar e vamos tocar fogo no pa\u00eds se forem para cima do Lula com golpe. \u2018N\u00e3o, vamos agir e tal, voc\u00ea tem disponibilidade?\u2019. \u2018 Tenho\u2019. Mandou um avi\u00e3o me buscar aqui, em Bras\u00edlia, eu ministro [da Integra\u00e7\u00e3o Nacional], mandou um avi\u00e3o buscar Eduardo Paes, deputado federal, e Gustavo Fruet, deputado federal, dois membros da CPI, e ele mandou buscar. \u2018\u00c9 daqui para tr\u00e1s\u2019. O pau quebrou no hangar do governo de Minas, em toda Pampulha [bairro de Belo Horizonte]. \u2018Olha garoto, voc\u00eas est\u00e3o pensando o que, rapaz? V\u00e3o tocar fogo no pa\u00eds, ningu\u00e9m nunca mais governa esse pa\u00eds. Voc\u00eas s\u00e3o loucos? \u00c9 da\u00ed para tr\u00e1s. Vai estudar hist\u00f3ria, olha o que aconteceu com Get\u00falio, n\u00e3o v\u00e3o fazer isso com Lula, mas nem a pau, Juvenal. E conseguimos tirar o requerimento.<\/p>\n<\/section>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Em nova entrevista, Ciro Gomes diz que Lula \u00e9 culpado por &#8220;trag\u00e9dia que est\u00e1 acontecendo no Brasil&#8221;. Para o pedetista, o ex-presidente \u00e9 um &#8220;enganador profissional&#8221;. Sobre Bolsonaro, diz que \u00e9 um &#8220;menino de 13 anos, paranoico&#8221;<\/p>\n","protected":false},"author":5,"featured_media":300188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-300187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/ciro-gomes-com-raiva.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=300187"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/300188"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=300187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=300187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=300187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}