{"id":300202,"date":"2019-11-01T10:41:50","date_gmt":"2019-11-01T13:41:50","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=300202"},"modified":"2019-11-01T10:44:33","modified_gmt":"2019-11-01T13:44:33","slug":"gonzaga-patriota-reafirma-apoio-a-pre-candidatura-de-lucas-ramos-a-prefeitura-de-petrolina","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/gonzaga-patriota-reafirma-apoio-a-pre-candidatura-de-lucas-ramos-a-prefeitura-de-petrolina\/","title":{"rendered":"Gonzaga Patriota reafirma apoio \u00e0 pr\u00e9-candidatura de Lucas Ramos \u00e0 Prefeitura de Petrolina"},"content":{"rendered":"<p style=\"text-align: justify;\">O deputado federal Gonzaga Patriota (PSB) reafirmou seu apoio \u00e0 pr\u00e9-candidatura de Lucas Ramos \u00e0 Prefeitura de Petrolina, nas elei\u00e7\u00f5es do pr\u00f3ximo ano. O socialista reitera que o PSB tem o direito e o dever de encabe\u00e7ar uma chapa pr\u00f3pria para a Prefeitura e ressalta que o deputado estadual Lucas Ramos (PSB) re\u00fane todas as qualidades necess\u00e1rias para isso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-275724 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-525x500.jpg\" alt=\"\" width=\"525\" height=\"500\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-525x500.jpg 525w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-300x286.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-768x732.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-160x153.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-640x610.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido-30x30.jpg 30w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/03\/gonzaga-palido.jpg 1280w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Gonzaga Patriota (PSB) ratifica o que disse em entrevista a uma r\u00e1dio de Petrolina, sobre sua postura de oposi\u00e7\u00e3o ao prefeito Miguel Coelho (MDB) e deixa claro, mais uma vez, que apoiar\u00e1 o nome do seu companheiro de partido, o deputado estadual Lucas Ramos.\u00a0 Patriota ainda acredita na possibilidade de um segundo turno hist\u00f3rico em Petrolina.<\/p>\n<p style=\"text-align: justify;\">Em rela\u00e7\u00e3o a uma aproxima\u00e7\u00e3o com o prefeito Miguel Coelho, o deputado n\u00e3o exclui essa possibilidade futuramente e relembra que isso j\u00e1 aconteceu com o senador Fernando Bezerra Coelho.\u00a0 \u201cMeu candidato \u00e9 Lucas Ramos, vou brigar por ele. Vamos trabalhar pra ganhar essas elei\u00e7\u00f5es, se Deus quiser. Quanto a uma aproxima\u00e7\u00e3o com Miguel Coelho, l\u00e1 na frente, quem sabe, a gente pode estar juntos.\u00a0 Isso j\u00e1 ocorrera com o seu pai, Fernando Bezerra Coelho\u201d.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Em rela\u00e7\u00e3o a uma aproxima\u00e7\u00e3o com o prefeito Miguel Coelho, o deputado n\u00e3o exclui essa possibilidade futuramente e relembra que isso j\u00e1 aconteceu com o senador Fernando Bezerra Coelho.\u00a0 \u201cMeu candidato \u00e9 Lucas Ramos, vou brigar por ele. Vamos trabalhar pra ganhar essas elei\u00e7\u00f5es, se Deus quiser. Quanto a uma aproxima\u00e7\u00e3o com Miguel Coelho, l\u00e1 na frente, quem sabe, a gente pode estar junt<\/p>\n","protected":false},"author":5,"featured_media":294702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-300202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/09\/gonzaga-e-padre.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=300202"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/294702"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=300202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=300202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=300202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}