{"id":300488,"date":"2019-11-04T14:27:42","date_gmt":"2019-11-04T17:27:42","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=300488"},"modified":"2019-11-04T14:27:42","modified_gmt":"2019-11-04T17:27:42","slug":"caso-aldeia-vim-pelo-meu-pai-diz-filho-apos-acusar-mae-em-julgamento","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/caso-aldeia-vim-pelo-meu-pai-diz-filho-apos-acusar-mae-em-julgamento\/","title":{"rendered":"Caso Aldeia: &#8216;Vim pelo meu pai&#8217;, diz filho ap\u00f3s acusar m\u00e3e em julgamento"},"content":{"rendered":"<div class=\"col s12\">\n<section class=\"box-featured full-size header\">\n<h1 style=\"text-align: justify;\"><\/h1>\n<p style=\"text-align: justify;\">Daniel Paes Rodrigues dep\u00f4s contra a m\u00e3e em julgamento que come\u00e7ou nesta segunda-feira (4)<\/p>\n<div class=\"header-information\" style=\"text-align: justify;\">\n<p>Por:\u00a0<strong class=\"responsible\">Portal FolhaPE com informa\u00e7\u00f5es de Isabelle Barbosa<\/strong><\/p>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"content\" style=\"text-align: justify;\">\n<div class=\"col m6 l6 s12 medium-matler\">\n<figure><img decoding=\"async\" src=\"https:\/\/www.folhape.com.br\/obj\/1\/358382,475,80,0,0,475,365,0,0,0,0.png\" alt=\"Daniel Paes, filho mais novo do casal\" \/><\/p>\n<div class=\"caption\">Daniel Paes, filho mais novo do casal<em>Foto: L\u00e9o Malafaia\/Folha de Pernambuco<\/em><\/div>\n<\/figure>\n<\/div>\n<p>Filho ca\u00e7ula da farmac\u00eautica Jussara Rodrigues da Silva Paes e do m\u00e9dico cardiologista Denirson Paes da Silva, Daniel Paes Rodrigues \u00e9 uma das cinco testemunhas de acusa\u00e7\u00e3o do\u00a0<a href=\"https:\/\/folhape.com.br\/noticias\/noticias\/crime-em-aldeia\/2019\/11\/04\/NWS,121661,70,1191,NOTICIAS,2190-CASO-ALDEIA-COMECA-NESTA-SEGUNDA-JURI-VIUVA-ACUSADA-MATAR-MEDICO.aspx\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>julgamento da m\u00e3e, que come\u00e7ou nesta segunda-feira (4), no F\u00f3rum de Camaragibe<\/strong><\/a>, na Regi\u00e3o Metropolitana do Recife. A r\u00e9 \u00e9 acusada de matar o marido em 31 de maio de 2018.<\/p>\n<p>&#8220;Vim pelo meu pai, que era um excelente pai e amigo. Espero que seja feita a justi\u00e7a. \u00c9 um momento muito forte pra mim, mas eu estou aqui por ele&#8221;, afirmou Daniel \u00e0 imprensa ap\u00f3s depor no julgamento. O filho foi a primeira das testemunhas de acusa\u00e7\u00e3o a depor e contou que n\u00e3o tinha mais nenhum relacionamento com a m\u00e3e e nem com o irm\u00e3o, tamb\u00e9m acusado pela justi\u00e7a do assassinato.<\/p>\n<p>Segundo Daniel, os pais tinham &#8220;um casamento de muito anos, mas n\u00e3o era feliz&#8221;. &#8220;Eu quero que ela [Jussara] pague pelo que manda as leis e a justi\u00e7a. Eu t\u00f4 aqui para contribuir, mesmo n\u00e3o querendo estar&#8221;. Para ele, o m\u00e9dico cardiologista &#8220;\u00e9 um exemplo a ser seguido. Tudo o que fiz em minha vida foi sempre seguindo ele&#8221;. Eu confio muito da justi\u00e7a e na pol\u00edcia desde o in\u00edcio&#8221;.<\/p>\n<p>Daniel Paes foi a primeira testemunha a depor. Ele falou por cerca de vinte minutos, mas sem a presen\u00e7a da m\u00e3e na sala de j\u00fari &#8211; Jussara ficou, desde o in\u00edcio do julgamento, num carro estacionado diante do f\u00f3rum e s\u00f3 entrou no im\u00f3vel ap\u00f3s os depoimentos do filho e da empregada dom\u00e9stica\u00a0Josefa da Concei\u00e7\u00e3o dos Santos, que trabalhava na casa da fam\u00edlia havia cinco anos, mas n\u00e3o estava no local no dia no crime. A informa\u00e7\u00e3o \u00e9 de que essas testemunhas teriam pedido para depor sem a presen\u00e7a da r\u00e9.<\/p>\n<p>Al\u00e9m de Daniel e de Josefa, outras tr\u00eas testemunhas de acusa\u00e7\u00e3o foram arroladas pelo Minist\u00e9rio P\u00fablico de Pernambuco (MPPE): o policial civil Arlan Dourado Gomes da Silva, que participou das investiga\u00e7\u00f5es; e os peritos do Instituto de Criminal\u00edstica Diogo Henrique Leal de Oliveira Costa e Fernando Henrique Leal Benevides.<\/p>\n<p>Em sorteio nesta manh\u00e3, foi definida a composi\u00e7\u00e3o do Conselho de Senten\u00e7a: cinco mulheres e dois homens. Jussara responde por homic\u00eddio triplamente qualificado, cometido por motivo torpe, com emprego de meio cruel, e cometido \u00e0 trai\u00e7\u00e3o, de emboscada, ou mediante dissimula\u00e7\u00e3o, ou outro recurso que dificultou ou tornou imposs\u00edvel a defesa da v\u00edtima; e tamb\u00e9m por oculta\u00e7\u00e3o de cad\u00e1ver.<\/p>\n<p>A din\u00e2mica da sess\u00e3o prev\u00ea considera\u00e7\u00f5es da acusa\u00e7\u00e3o e defesa; ouvidas das testemunhas e acusa\u00e7\u00e3o e da r\u00e9; vota\u00e7\u00e3o e veredicto, dado pela ju\u00edza Mar\u00edlia Falcone, da 1\u00aa Vara Criminal da Comarca de Camaragibe. N\u00e3o haver\u00e1 testemunha de defesa.<\/p>\n<p><strong>Relembre o caso<\/strong><br \/>\nO cad\u00e1ver do m\u00e9dico cardiologista Denirson Paes foi encontrado em 4 de julho de 2018 dentro de uma cacimba da casa onde morava, no condom\u00ednio de luxo Torquato de Castro I, localizado no km 13 da Estrada de Aldeia, em Camaragibe, Regi\u00e3o Metropolitana do Recife. O desaparecimento do m\u00e9dico vinha sendo investigado desde o in\u00edcio de junho.<\/p>\n<p>Em um Boletim de Ocorr\u00eancia registrado em 20 de junho sobre o desaparecimento do marido, a farmac\u00eautica Jussara Rodrigues Silva Paes alegava que a v\u00edtima teria viajado para fora do Pa\u00eds e que n\u00e3o teria retornado desde ent\u00e3o. A delegada Carmem L\u00facia, de Camaragibe, desconfiou do envolvimento dos familiares e solicitou um mandado de busca e apreens\u00e3o no condom\u00ednio em que eles moravam.<\/p>\n<p>Na busca policial, realizada em 4 de julho, foram encontrados os primeiros restos mortais do m\u00e9dico na cacimba da resid\u00eancia. Para a pol\u00edcia, havia ind\u00edcios suficientes da participa\u00e7\u00e3o de m\u00e3e e filho na oculta\u00e7\u00e3o do corpo de Denirson, Danilo. Em 5 de julho, Jussara e Danilo foram presos temporariamente suspeitos de oculta\u00e7\u00e3o de cad\u00e1ver.<\/p>\n<p>Danilo foi encaminhado para o Centro de Observa\u00e7\u00e3o Criminol\u00f3gica e Triagem Professor Everaldo Luna (Cotel), em Abreu e Lima. Jussara foi levada para a Col\u00f4nia Penal Feminina do Recife. Em 20 de agosto, um laudo do Instituto M\u00e9dico Legal (IML) apontou asfixia por esganadura como a causa da morte do cardiologista. Os tr\u00eas pedidos de habeas corpus feitos pela defesa de Jussara. Em dezembro passado, Danilo recebeu habeas corpus, obtendo liberdade.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O cad\u00e1ver do m\u00e9dico cardiologista Denirson Paes foi encontrado em 4 de julho de 2018 dentro de uma cacimba da casa onde morava, no condom\u00ednio de luxo Torquato de Castro I, localizado no km 13 da Estrada de Aldeia, em Camaragibe, Regi\u00e3o Metropolitana do<\/p>\n","protected":false},"author":5,"featured_media":300490,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-300488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/filho-do-medico-morto.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=300488"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/300490"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=300488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=300488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=300488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}