{"id":300559,"date":"2019-11-05T08:20:51","date_gmt":"2019-11-05T11:20:51","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=300559"},"modified":"2019-11-05T15:35:13","modified_gmt":"2019-11-05T18:35:13","slug":"apos-queixa-do-pt-ao-stf-humberto-costa-entra-no-alvo-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/apos-queixa-do-pt-ao-stf-humberto-costa-entra-no-alvo-de-bolsonaro\/","title":{"rendered":"Ap\u00f3s queixa do PT ao STF, Humberto Costa entra no alvo de Bolsonaro"},"content":{"rendered":"<header>\n<div class=\"data-post\">\n<div class=\"data-extenso\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<figure style=\"text-align: justify;\"><img decoding=\"async\" class=\"img-responsive\" title=\"Foto: Roberto Stuckert Filho\/Divulga\u00e7\u00e3o\" src=\"https:\/\/imagens1.ne10.uol.com.br\/blogsne10\/jamildo\/uploads\/\/2019\/03\/humberto-costa-.jpg\" alt=\"Foto: Roberto Stuckert Filho\/Divulga\u00e7\u00e3o\" \/><figcaption>Foto: Roberto Stuckert Filho\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/header>\n<div class=\"content-noticia\">\n<h1 class=\"titulo-noticia titulo-noticia-interna\" style=\"text-align: justify;\"><\/h1>\n<p>Por <strong>Amanda Miranda <\/strong><\/p>\n<div id=\"texto-noticia\">\n<p style=\"text-align: justify;\">O presidente Jair Bolsonaro (PSL) e seu filho Carlos Bolsonaro, vereador pelo PSC do Rio de Janeiro, citaram o senador pernambucano Humberto Costa (PT) no Twitter nesta ter\u00e7a-feira (5),\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2018\/08\/14\/fachin-manda-para-moro-inquerito-sobre-humberto-costa\/\">ligando-o \u00e0 Opera\u00e7\u00e3o Lava Jato<\/a>.<\/p>\n<p style=\"text-align: justify;\">A publica\u00e7\u00e3o foi feita um dia ap\u00f3s o l\u00edder do PT no Senado e correligion\u00e1rios dele\u00a0<a href=\"https:\/\/jconline.ne10.uol.com.br\/canal\/politica\/nacional\/noticia\/2019\/11\/04\/pt-pede-que-stf-investigue-bolsonaro-por-obstrucao-da-justica-391986.php\">protocolarem uma not\u00edcia-crime no Supremo Tribunal Federal (STF) contra os Bolsonaro<\/a>\u00a0e o ministro da Justi\u00e7a, S\u00e9rgio Moro.<\/p>\n<p style=\"text-align: justify;\">\u201cAgora entram na Justi\u00e7a pelo fato de eu, como morador, ter acessado a secret\u00e1ria eletr\u00f4nica do meu condom\u00ednio\u201d, afirmou Bolsonaro na rede social.<\/p>\n<p style=\"text-align: justify;\">A\u00a0<a href=\"https:\/\/jconline.ne10.uol.com.br\/canal\/politica\/nacional\/noticia\/2019\/11\/02\/bolsonaro-diz-que-pegou-gravacao-em-condominio-mas-nega-obstrucao-de-justica-391889.php\">den\u00fancia foi apresentada \u00e0 Corte ap\u00f3s o presidente ter dito que obteve \u00e1udios da portaria do seu condom\u00ednio<\/a>, alegando que o objetivo era de que n\u00e3o fossem adulterados.<\/p>\n<p style=\"text-align: justify;\">A declara\u00e7\u00e3o foi ap\u00f3s vir a p\u00fablico o\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/10\/30\/aras-diz-que-arquivou-mencao-de-bolsonaro-no-caso-marielle-factoide\/\">conte\u00fado do depoimento de um dos porteiros do condom\u00ednio onde os Bolsonaro t\u00eam casa<\/a>\u00a0no Rio de Janeiro. Era l\u00e1 onde tamb\u00e9m vivia, antes de ser preso, Ronnie Lessa, um dos acusados pelo assassinato da vereadora\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/10\/31\/agu-vai-apurar-vazamento-de-informacoes-sobre-caso-marielle\/\">Marielle Franco<\/a>. Segundo o relato do porteiro, o outro suspeito, Elcio Queiroz, teria tido a entrada no condom\u00ednio autorizada por \u201cseu Jair\u201d no dia em que Marielle foi morta. Em 14 de mar\u00e7o de 2018, no entanto, o presidente estava na C\u00e2mara dos Deputados.<\/p>\n<p style=\"text-align: justify;\">\u201cTrata-se, \u00e0 toda evid\u00eancia, de uma clara tentativa de destrui\u00e7\u00e3o e\/ou manipula\u00e7\u00e3o de provas, visando afetar e mesmo frustrar a lisura das investiga\u00e7\u00f5es policiais e ministeriais em curso\u201d, afirmaram os petistas na not\u00edcia-crime.<\/p>\n<div id=\"smartIntxt\" class=\"publicidade-entre-texto\" style=\"text-align: justify;\">\n<div class=\"player_dynad_tv\"><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Os parlamentares pedem que seja determinado mandado de busca e apreens\u00e3o do material e que seja investigado se houve crime de obstru\u00e7\u00e3o \u00e0 investiga\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Assinam o documento, al\u00e9m de Humberto Costa, a presidente nacional do PT, deputada federal Gleisi Hoffmann (PR); os l\u00edderes na C\u00e2mara do PT, Paulo Pimenta (RS); do PDT, Andr\u00e9 Figueiredo (CE); do PSOL, Ivan Valente (SP); e a l\u00edder da Minoria, Jandira Feghali (PCdoB-RJ).<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m endossam a not\u00edcia-crime as deputadas Margarida Salom\u00e3o (PT-MG) e Rosa Neide (PT-MT) e os deputados Alencar Santana (PT-SP), Arlindo Chinaglia (PT-SP), Bohn Gass (PT-RS), Henrique Fontana (PT-RS), Jo\u00e3o Daniel (PT-SE), Nilto Tatto (PT-SP), Padre Jo\u00e3o (PT-MG), Paulo Teixeira (PT-SP), Reginaldo Lopes (PT-MG), Rui Falc\u00e3o (PT-SP) e Zeca Dirceu (PT-PR).<\/p>\n<h2 style=\"text-align: justify;\">Cassa\u00e7\u00e3o<\/h2>\n<p style=\"text-align: justify;\">Durante o fim de semana, ao apoiar outro filho de Bolsonaro, o deputado Eduardo Bolsonaro (PSL-SP),\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/11\/02\/em-apoio-a-eduardo-bolsonaro-feliciano-quer-cassar-humberto-costa\/\">Marco Feliciano (Podemos-SP) defendeu a cassa\u00e7\u00e3o de Humberto Costa<\/a>. Eduardo \u00e9 alvo de representa\u00e7\u00e3o no Conselho de \u00c9tica da C\u00e2mara por ter falado em um \u201cnovo\u00a0<a href=\"https:\/\/blogs.ne10.uol.com.br\/jamildo\/2019\/10\/31\/o-que-foi-o-ai-5-citado-por-eduardo-bolsonaro\/\">AI-5\u2033, ato considerado a medida que recrudesceu a ditadura militar<\/a>.<\/p>\n<h3 style=\"text-align: justify;\">Leia a \u00edntegra do pedido do PT ao STF<\/h3>\n<p style=\"text-align: justify;\"><iframe loading=\"lazy\" src=\"https:\/\/www.slideshare.net\/slideshow\/embed_code\/key\/c4JHC8aUzh1wwM\" width=\"100%\" height=\"714\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAgora entram na Justi\u00e7a pelo fato de eu, como morador, ter acessado a secret\u00e1ria eletr\u00f4nica do meu condom\u00ednio\u201d, afirmou Bolsonaro na rede social.<\/p>\n<p>A\u00a0den\u00fancia foi apresentada \u00e0 Corte ap\u00f3s o presidente ter dito q<\/p>\n","protected":false},"author":5,"featured_media":259385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-300559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2018\/10\/humberto-costa-grande.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=300559"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/259385"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=300559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=300559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=300559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}