{"id":300702,"date":"2019-11-06T09:19:43","date_gmt":"2019-11-06T12:19:43","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=300702"},"modified":"2019-11-06T09:19:43","modified_gmt":"2019-11-06T12:19:43","slug":"diretoria-executiva-da-acosap-toma-posse-durante-seminario-com-agentes-comunitarios-de-saude-e-de-combate-as-endemias-do-sertao-do-sao-francisco","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/diretoria-executiva-da-acosap-toma-posse-durante-seminario-com-agentes-comunitarios-de-saude-e-de-combate-as-endemias-do-sertao-do-sao-francisco\/","title":{"rendered":"Diretoria executiva da Acosap toma posse durante semin\u00e1rio com Agentes Comunit\u00e1rios de Sa\u00fade e de Combate \u00e0s Endemias do Sert\u00e3o do S\u00e3o Francisco"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A nova diretoria executiva da Acosap (Associa\u00e7\u00e3o dos Agentes Comunit\u00e1rios de Sa\u00fade de Petrolina), foi empossada nesta ter\u00e7a-feira (5), durante a realiza\u00e7\u00e3o do 1\u00ba semin\u00e1rio dos ACS &#8211; (Agentes Comunit\u00e1rios de Sa\u00fade) e dos ACE &#8211; (Agentes de Combate \u00e0s Endemias), do Sert\u00e3o do S\u00e3o Francisco, realizado no sal\u00e3o de eventos da Associa\u00e7\u00e3o. Em tempo, o \u00f3rg\u00e3o comemorou os 26 anos de atividades na regi\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-300703 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-620x414.jpg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-620x414.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap.jpg 1000w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Para o bi\u00eanio 2019\/2021, a Acosap ser\u00e1 administrada pelo presidente Manoel Ant\u00f4nio Coelho Neto, a vice\u2013presidente, Suyla Karina Dias de Carvalho e demais membros.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Considerada uma das Associa\u00e7\u00f5es mais organizadas em rela\u00e7\u00e3o aos agentes de Endemias de Pernambuco e Bahia, e um marco no servi\u00e7o em Petrolina, a nova gest\u00e3o ter\u00e1 como meta implementar o plano de cargos e carreiras no munic\u00edpio, e inserir os Agentes na Reforma de Previd\u00eancia, mas sem retrocessos financeiros para a categoria.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Lembrando dos tempos das mobiliza\u00e7\u00f5es na Capital Federal para conquistar direitos para os agentes de sa\u00fade. Manoel da Acosap ressaltou que esses 26 anos de atividades n\u00e3o foram f\u00e1ceis, pois naquele tempo, as caravanas iam ao Parque Bandeirantes e comiam p\u00e3o com mortadela: \u00a8N\u00e3o t\u00ednhamos dinheiro para comprar um prato de comida, mas t\u00ednhamos dignidade para lutar pelas suas cidades e seus estados l\u00e1 em Bras\u00edlia\u201d, recordou enfatizando ainda que: \u2018N\u00e3o vamos desistir da luta\u2019.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>Semin\u00e1rio<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Ministrado pela Presidente da Conacs (Confedera\u00e7\u00e3o Nacional dos Agentes Comunit\u00e1rios de Sa\u00fade, Ilda Ang\u00e9lica dos Santos Correia. O semin\u00e1rio teve como tema: \u201cA apresenta\u00e7\u00e3o do modelo de inclus\u00e3o das Categorias ACS e ACE na PEC 06\/2019, na Reforma da Previd\u00eancia\u201d.<\/p>\n<figure id=\"attachment_300704\" aria-describedby=\"caption-attachment-300704\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-300704 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-620x414.jpg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-620x414.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Presidente-da-Conacs-Confedera\u00e7\u00e3o-Nacional-dos-Agentes-Comunit\u00e1rios-de-Sa\u00fade-Ilda-Ang\u00e9lica.jpg 1000w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-300704\" class=\"wp-caption-text\">Presidente da Conacs (Confedera\u00e7\u00e3o Nacional dos Agentes Comunit\u00e1rios de Sa\u00fade, Ilda Ang\u00e9lica<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Para Ilda Ang\u00e9lica a categoria deve viver cotidianamente a partir do jarg\u00e3o da Confedera\u00e7\u00e3o Nacional que diz \u201c a uni\u00e3o faz a for\u00e7a\u201d. Ela ressaltou que a Conacs em reuni\u00e3o com o ministro da sa\u00fade &#8211; Luiz Henrique Mandetta apresentou mudan\u00e7as para os Agentes de sa\u00fade.<\/p>\n<figure id=\"attachment_300705\" aria-describedby=\"caption-attachment-300705\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-300705 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-620x414.jpg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-620x414.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-300x200.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-768x512.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-160x106.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-450x300.jpg 450w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina-640x427.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/Manoel-Ant\u00f4nio-Coelho-Neto-a-vice\u2013presidente-Suyla-Karina.jpg 1000w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-300705\" class=\"wp-caption-text\">Manoel Ant\u00f4nio Coelho Neto, a vice\u2013presidente, Suyla Karina<\/figcaption><\/figure>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\u201cN\u00f3s conquistamos com o ministro Mandetta o curso t\u00e9cnico do agente comunit\u00e1rio de sa\u00fade e o curso t\u00e9cnico dos agentes de combate as endemias. N\u00f3s vamos nos elevar do n\u00edvel m\u00e9dio, para o n\u00edvel t\u00e9cnico\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Para Ilda Ang\u00e9lica a categoria deve viver cotidianamente a partir do jarg\u00e3o da Confedera\u00e7\u00e3o Nacional que diz \u201c a uni\u00e3o faz a for\u00e7a\u201d. Ela ressaltou que a Conacs em reuni\u00e3o com o ministro da sa\u00fade &#8211; Luiz Henrique Mandetta apresentou mudan\u00e7as para os Agentes de<\/p>\n","protected":false},"author":5,"featured_media":300703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6,11],"tags":[],"class_list":["post-300702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","category-regional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/11\/manoel-da-acosap.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=300702"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/300702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/300703"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=300702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=300702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=300702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}