{"id":37915,"date":"2014-01-13T08:01:31","date_gmt":"2014-01-13T11:01:31","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=37915"},"modified":"2014-01-13T16:49:53","modified_gmt":"2014-01-13T19:49:53","slug":"inscricoes-para-o-prouni-comecam-segunda","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/inscricoes-para-o-prouni-comecam-segunda\/","title":{"rendered":"Inscri\u00e7\u00f5es para o ProUni come\u00e7am segunda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37916\" alt=\"download (1)\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/download-12.jpg\" width=\"100\" height=\"100\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/download-12.jpg 100w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/download-12-50x50.jpg 50w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<p>Come\u00e7am nesta segunda (13) as inscri\u00e7\u00f5es para a primeira edi\u00e7\u00e3o de 2014 do Programa Universidade para Todos (ProUni) pela internet. Segundo o Minist\u00e9rio da Educa\u00e7\u00e3o, o sistema estar\u00e1 aberto desde o in\u00edcio da manh\u00e3, mas n\u00e3o definiu hor\u00e1rio. O prazo vai at\u00e9 as 23h59 da sexta-feira (17). A primeira chamada dos estudantes pr\u00e9-selecionados ser\u00e1 divulgada no dia 20 de janeiro no site do programa, que vai publicar a segunda chamada no dia 3 de fevereiro.<\/p>\n<p>O ProUni \u00e9 destinado a alunos que querem concorrer a bolsas de estudo, integrais ou parciais, em institui\u00e7\u00f5es particulares de educa\u00e7\u00e3o superior. As bolsas integrais s\u00e3o para os estudantes com renda bruta familiar, por pessoa, at\u00e9 um sal\u00e1rio m\u00ednimo e meio. As bolsas parciais s\u00e3o destinadas aos candidatos com renda bruta familiar at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos por pessoa. O bolsista parcial poder\u00e1 utilizar o Fundo de Financiamento Estudantil (Fies) para custear o restante da mensalidade.<\/p>\n<p>Pode participar da sele\u00e7\u00e3o o estudante que tenha feito a prova do Exame Nacional do Ensino M\u00e9dio (Enem) de 2013 e obtido no m\u00ednimo 450 pontos na m\u00e9dia das notas. O candidato n\u00e3o pode ter tirado 0 na reda\u00e7\u00e3o e precisa ter cursado o ensino m\u00e9dio na rede p\u00fablica ou com bolsa integral na rede privada.<\/p>\n<p>Este ano, h\u00e1 mudan\u00e7a quanto aos procedimentos da lista de espera. Agora, o estudante que n\u00e3o for pr\u00e9-selecionado nas duas chamadas regulares e quiser participar da lista ter\u00e1 de manifestar interesse pela internet e, em seguida, nas datas previstas em edital, comparecer \u00e0 institui\u00e7\u00e3o de ensino na qual pretende estudar com os documentos necess\u00e1rios.<\/p>\n<p>Ap\u00f3s esse processo, a institui\u00e7\u00e3o ter\u00e1 prazo para avaliar a documenta\u00e7\u00e3o. O estudante selecionado receber\u00e1 o resultado por meio do boletim do candidato, dispon\u00edvel online na p\u00e1gina do ProUni. Nas edi\u00e7\u00f5es anteriores, o candidato tinha de manifestar interesse na lista de espera e aguardar a convoca\u00e7\u00e3o da institui\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n<p>Veja abaixo o cronograma do Prouni<\/p>\n<p>&nbsp;<\/p>\n<div>\n<div><\/div>\n<div>\n<div><img decoding=\"async\" id=\"ecxwm0\" alt=\"\" src=\"https:\/\/bay173.mail.live.com\/Handlers\/ImageProxy.mvc?bicild=&amp;canary=bEjldMblIqyJike9QiTeuhXTHiEExbEvj%2bRSmIvxJD4%3d0&amp;url=http%3a%2f%2fwww1.folhape.com.br%2fcms%2fopencms%2ffolhape%2fpt%2fcultura%2fimagens-cultura%2fJan2014%2f71prouni.jpg\" \/><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7am nesta segunda (13) as inscri\u00e7\u00f5es para a primeira edi\u00e7\u00e3o de 2014 do Programa Universidade para Todos (ProUni) pela internet. Segundo o Minist\u00e9rio da Educa\u00e7\u00e3o, o sistema estar\u00e1 aberto desde o in\u00edcio da manh\u00e3, mas n\u00e3o definiu hor\u00e1rio. O prazo vai at\u00e9 as 23h59 da sexta-feira (17). A primeira chamada dos estudantes pr\u00e9-selecionados ser\u00e1 divulgada [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":37916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1175],"tags":[1209],"class_list":["post-37915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-inscricoes"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2014\/01\/download-12.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/37915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=37915"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/37915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/37916"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=37915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=37915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=37915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}