{"id":390439,"date":"2022-06-09T09:33:54","date_gmt":"2022-06-09T12:33:54","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=390439"},"modified":"2022-06-09T09:33:54","modified_gmt":"2022-06-09T12:33:54","slug":"pesquisa-ipespe-censurada-pela-xp-mostra-que-eleitor-considera-lula-mais-honesto-que-bolsonaro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/pesquisa-ipespe-censurada-pela-xp-mostra-que-eleitor-considera-lula-mais-honesto-que-bolsonaro\/","title":{"rendered":"Pesquisa Ipespe censurada pela XP mostra que eleitor considera Lula mais honesto que Bolsonaro"},"content":{"rendered":"<h2 class=\"article__headline marginBottom30\"><\/h2>\n<div class=\"article__lead\">\n<p>Segundo o levantamento, Lula \u00e9, para o eleitor, mais honesto, mais preocupado com as pessoas, mais competente, mais inteligente, mais equilibrado e mais experiente que Bolsonaro.<\/p>\n<\/div>\n<figure><picture><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220526170552_568bdc82-0414-476e-bf22-c53794fce48b.webp\" type=\"image\/webp\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220526170552_568bdc82-0414-476e-bf22-c53794fce48b.jpg\" type=\"image\/jpeg\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220526170552_d6d22435-19bf-4969-ae2a-ae9b6c67d12e.webp\" type=\"image\/webp\" media=\"(min-width: 681px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220526170552_d6d22435-19bf-4969-ae2a-ae9b6c67d12e.jpg\" type=\"image\/jpeg\" media=\"(min-width: 681px)\" \/><img decoding=\"async\" title=\"Ex-presidente Luiz In\u00e1cio Lula da Silva e Jair Bolsonaro (Foto: Ricardo Stuckert | REUTERS\/Adriano Machado)\" src=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220526170552_d6d22435-19bf-4969-ae2a-ae9b6c67d12e.jpg\" alt=\"www.brasil247.com - Ex-presidente Luiz In\u00e1cio Lula da Silva e Jair Bolsonaro\" \/><\/picture><figcaption>Ex-presidente Luiz In\u00e1cio Lula da Silva e Jair Bolsonaro (Foto: Ricardo Stuckert | REUTERS\/Adriano Machado)<\/figcaption><\/figure>\n<div class=\"article__text marginTop30\">\n<p>A\u00a0<a href=\"https:\/\/www.brasil247.com\/poder\/xp-cancela-divulgacao-de-pesquisa-com-vantagem-para-lula-apos-pressao-de-bolsonaristas\" target=\"_blank\" rel=\"noopener\">pesquisa Ipespe encomendada pela XP Investimentos e censurada pela empresa<\/a>\u00a0mostra que o ex-presidente Lula (PT) \u00e9 visto como mais honesto que Jair Bolsonaro (PL), segundo dados divulgados por Carolina Botelho, colunista do Jota.<\/p>\n<p>Lula ganha de Bolsonaro em quase todos os aspectos positivos. O petista \u00e9, segundo o levantamento, mais honesto, mais preocupado com as pessoas, mais competente, mais inteligente, mais equilibrado, mais experiente e tem mais ideias novas e modernas que Bolsonaro.<\/p>\n<p>O atual chefe do governo federal ganha de Lula somente no aspecto de &#8220;pulso firme&#8221;.<\/p>\n<div class=\"contentAd contentAd--noBackground marginBottom30\">\n<div class=\"ml-form-embed marginBottom30 marginTop30\" data-account=\"3346585:a3c9r4n3k3\" data-form=\"4533589:q9s5r2\"><\/div>\n<\/div>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220609060652_f542a9a1fac4e61f802ca1acce9465e055c4c69318303772ac1d7f15cea22cd1.jpg\" alt=\"grafico\" width=\"828\" height=\"503\" data-media-id=\"editor_1\" data-image-id=\"20220609060652_f542a9a1fac4e61f802ca1acce9465e055c4c69318303772ac1d7f15cea22cd1\" data-rendition-name=\"original\" \/><\/figure>\n<p>Em nota, a XP negou que &#8220;a pesquisa ser\u00e1 cancelada e ratifica que contrata diversos tipos de pesquisas de diferentes institutos com o intuito de auxiliar seus clientes a tomarem as melhores decis\u00f5es sobre investimentos&#8221;.<\/p>\n<p>&#8220;A realiza\u00e7\u00e3o das pesquisas ter\u00e1 periodicidade mensal, com n\u00famero de entrevistas ampliado em rela\u00e7\u00e3o \u00e0s realizadas nos levantamentos anteriores, oferecendo dessa maneira uma ferramenta ainda mais ampla para que os investidores compreendam o cen\u00e1rio eleitoral e seus impactos no mercado. As pr\u00f3ximas pesquisas registradas no Tribunal Superior Eleitoral j\u00e1 estar\u00e3o adequadas ao novo formato&#8221;, acrescentou.<\/p>\n<div class=\"contentAd contentAd--noBackground marginBottom30\">\n<div class=\"marginTop10 adBackground\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o levantamento, Lula \u00e9, para o eleitor, mais honesto, mais preocupado com as pessoas, mais competente, mais inteligente, mais equilibrado e mais experiente que Bolsonaro.<\/p>\n","protected":false},"author":5,"featured_media":283488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-390439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2019\/05\/lula-rindo.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=390439"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/283488"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=390439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=390439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=390439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}