{"id":390505,"date":"2022-06-10T03:44:01","date_gmt":"2022-06-10T06:44:01","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=390505"},"modified":"2022-06-10T04:06:22","modified_gmt":"2022-06-10T07:06:22","slug":"por-respeito-a-bivar-neto-descarta-qualquer-aproximacao-com-candidatura-de-simone-tebet","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/por-respeito-a-bivar-neto-descarta-qualquer-aproximacao-com-candidatura-de-simone-tebet\/","title":{"rendered":"Por &#8216;respeito a Bivar&#8217;, Neto descarta qualquer aproxima\u00e7\u00e3o com candidatura de Simone Tebet"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Por Mauricio Leiro<\/p>\n<p>&nbsp;<\/p>\n<p>De improv\u00e1vel a imposs\u00edvel. Qualquer di\u00e1logo para ajustar o apoio do pr\u00e9-candidato ao governo da Bahia ACM Neto (Uni\u00e3o) a candidatura \u00e0 presid\u00eancia da senadora Simone Tebet (MDB) foi descartado pelo ex-prefeito de Salvador.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-390507 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-620x372.jpg\" alt=\"\" width=\"620\" height=\"372\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-620x372.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-300x180.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-768x461.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-160x96.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto-640x384.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto.jpg 1086w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>&#8220;N\u00e3o vou alterar minha posi\u00e7\u00e3o nacional. Palanque aberto [por] respeito ao [Luciano] Bivar. E assim vou seguir at\u00e9 o fim&#8221;, indicou ao BN.<\/p>\n<p>&nbsp;<\/p>\n<p>A executiva nacional do MDB oficializou a pr\u00e9-candidatura da senadora Simone Tebet (MDB-MS) \u00e0 Presid\u00eancia da Rep\u00fablica, para concorrer em nome de um grupo de partidos da chamada terceira via (<a href=\"https:\/\/www.bahianoticias.com.br\/noticia\/268917-mdb-confirma-pre-candidatura-de-tebet-para-3-via-em-meio-a-resistencias-no-partido.html\">veja aqui<\/a>), apesar de n\u00e3o ter a inclus\u00e3o do Uni\u00e3o Brasil no grupo. O partido anunciou a pr\u00e9-candidatura do deputado federal Luciano Bivar (Uni\u00e3o-PE).<\/p>\n<p>&nbsp;<\/p>\n<p>Sem problemas com palanque na Bahia, o nome da autoproclamada terceira via confirmou a vinda para a Bahia ainda no m\u00eas de junho. No estado, o presidente de honra do MDB na Bahia, L\u00facio Vieira Lima, descartou a possibilidade do partido dar palanque para Luiz In\u00e1cio Lula da Silva (PT), com a candidatura de Tebet se confirmando. (BN)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A executiva nacional do MDB oficializou a pr\u00e9-candidatura da senadora Simone Tebet (MDB-MS) \u00e0 Presid\u00eancia da Rep\u00fablica, para concorrer em nome de um grupo de partidos da chamada terceira via (veja aqui), apesar de n\u00e3o ter a inclus\u00e3o do Uni\u00e3o Brasil no grupo. O parti<\/p>\n","protected":false},"author":5,"featured_media":390507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-390505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/bivar-e-neto.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=390505"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/390507"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=390505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=390505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=390505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}