{"id":390955,"date":"2022-06-16T16:53:29","date_gmt":"2022-06-16T19:53:29","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=390955"},"modified":"2022-06-16T17:01:05","modified_gmt":"2022-06-16T20:01:05","slug":"secretaria-de-desenvolvimento-social-de-combate-a-pobreza-de-uaua-realiza-confraternizacao-em-ritmo-de-forro-veja-videos","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/secretaria-de-desenvolvimento-social-de-combate-a-pobreza-de-uaua-realiza-confraternizacao-em-ritmo-de-forro-veja-videos\/","title":{"rendered":"Secretaria de Desenvolvimento Social de Combate a Pobreza de Uau\u00e1 realiza confraterniza\u00e7\u00e3o em ritmo de forr\u00f3; veja v\u00eddeos"},"content":{"rendered":"<p style=\"text-align: justify;\">Reda\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify;\">A Secretaria de Desenvolvimento Social de Combate a Pobreza do munic\u00edpio de Uau\u00e1, realizou nesta quarta-feira (15) confraterniza\u00e7\u00e3o com ao som do forr\u00f3 arrasta p\u00e9, comidas t\u00edpicas e muitas alegria.<\/p>\n<p><iframe loading=\"lazy\" title=\"Confraterniza\u00e7\u00e3o no Social de Uau\u00e1\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9FLIdV7_4u4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Jorge Lobo prestigia confraterniza\u00e7\u00e3o do Social\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mo3QXun9ZcA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">&#8220;O objetivo \u00e9 fortalecer mais ainda os v\u00ednculos do social com o CREAS, CRAS, Conselho Tutelar, Primeira Inf\u00e2ncia, Servi\u00e7o de Conviv\u00eancia e com a administra\u00e7\u00e3o municipal&#8221;, comemorou a secret\u00e1ria Marlene Cardoso.<\/p>\n<p><iframe loading=\"lazy\" title=\"Muita alegria no Social de Uau\u00e1\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ZYO2sp0Jilg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Anima\u00e7\u00e3o na confraterniza\u00e7\u00e3o do Social em Uau\u00e1\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/UFQyv-6iL88?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Estiveram prestigiando o vento o secret\u00e1rio municipal de sa\u00fade, Jorge Lobo, a diretora do Hospital Municipal Dr, Jair Fragas, senhora Laires, o controlador do munic\u00edpio Silvio Romero e o ex-prefeito Ol\u00edmpio Cardoso.<\/p>\n<p style=\"text-align: justify;\"><strong>Galeria de imagem<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-390956 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/silvio-romero-e-olimpio.jpg 1024w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-390957 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-1536x1152.jpg 1536w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-equipe.jpg 1600w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-390958 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-620x465.jpg\" alt=\"\" width=\"620\" height=\"465\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-620x465.jpg 620w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-300x225.jpg 300w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-768x576.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-1536x1152.jpg 1536w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-80x60.jpg 80w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-118x88.jpg 118w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-160x120.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo-640x480.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo.jpg 1600w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-390959 size-large\" src=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-375x500.jpg\" alt=\"\" width=\"375\" height=\"500\" srcset=\"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-375x500.jpg 375w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-225x300.jpg 225w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-768x1024.jpg 768w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-1152x1536.jpg 1152w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-160x213.jpg 160w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio-640x853.jpg 640w, https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-povo-feio.jpg 1200w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O objetivo \u00e9 fortalecer mais ainda os v\u00ednculos do social com o CREAS, CRAS, Conselho Tutelar, Primeira Inf\u00e2ncia, Servi\u00e7o de Conviv\u00eancia e com a administra\u00e7\u00e3o municipal&#8221;, co<\/p>\n","protected":false},"author":5,"featured_media":390958,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-390955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/marlene-e-jorge-lobo.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=390955"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/390955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/390958"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=390955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=390955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=390955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}