{"id":391343,"date":"2022-06-21T16:54:11","date_gmt":"2022-06-21T19:54:11","guid":{"rendered":"http:\/\/acaopopular.net\/jornal\/?p=391343"},"modified":"2022-06-21T16:54:11","modified_gmt":"2022-06-21T19:54:11","slug":"alem-de-moro-tre-sp-nega-mudanca-de-domicilio-eleitoral-de-tarcisio","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/alem-de-moro-tre-sp-nega-mudanca-de-domicilio-eleitoral-de-tarcisio\/","title":{"rendered":"Al\u00e9m de Moro, TRE-SP nega mudan\u00e7a de domic\u00edlio eleitoral de Tarc\u00edsio"},"content":{"rendered":"<div class=\"col-sm-12 ig-container_headerText\">\n<h1 id=\"noticia-titulo-h1\" class=\"noticia-titulo-h1-ig_V04\"><\/h1>\n<h2 id=\"noticia-olho\">Dias atr\u00e1s, Tribunal havia negado mudan\u00e7a de t\u00edtulo de eleitor ao ex-ministro Sergio Moro, que voltou ao Paran\u00e1 para disputar a elei\u00e7\u00e3o<\/h2>\n<\/div>\n<div id=\"noticia-other\" class=\"noticia-other-ig_V04\">\n<div class=\"author-container\">\n<p>Por<strong>Ag\u00eancia O Globo<\/strong><\/p>\n<p><span id=\"dataHTML\"><br \/>\n<time><\/time><\/span><\/div>\n<\/div>\n<div class=\"contentNoticia\">\n<div class=\"main-content\">\n<div class=\"row\">\n<section class=\"noticia col-sm-12 plf-0\">\n<div id=\"noticia\">\n<div class=\"Noticia_Foto\">\n<figure class=\"foto-legenda \">\n<div class=\"foto-legenda-img\"><img loading=\"lazy\" decoding=\"async\" title=\"Tarc\u00edsio Gomes de Freitas (PL)\" src=\"https:\/\/i0.statig.com.br\/bancodeimagens\/4r\/r7\/ar\/4rr7aree1fzhjxf7ivmh7p6jw.jpg\" alt=\"Tarc\u00edsio Gomes de Freitas (PL)\" width=\"906\" height=\"509\" \/><\/div><figcaption class=\"foto-legenda-citacao \"><cite>Reprodu\u00e7\u00e3o\/Youtube<\/cite><\/p>\n<div class=\"foto-legenda-citacao-text\" data-gtm-vis-recent-on-screen-214867_1952=\"2340\" data-gtm-vis-first-on-screen-214867_1952=\"2340\" data-gtm-vis-total-visible-time-214867_1952=\"100\" data-gtm-vis-has-fired-214867_1952=\"1\">Tarc\u00edsio Gomes de Freitas (PL)<\/div>\n<\/figcaption><\/figure>\n<\/div>\n<p>O Tribunal Regional Eleitoral de S\u00e3o Paulo (TRE-SP) rejeitou nesta ter\u00e7a-feira uma peti\u00e7\u00e3o contra a transfer\u00eancia de domic\u00edlio eleitoral do ex-ministro Tarc\u00edsio de Freitas, pr\u00e9-candidato do PL ao Pal\u00e1cio dos Bandeirantes, para S\u00e3o Paulo.<\/p>\n<p>O desembargador Silmar Fernandes, vice-presidente do Tribunal e corregedor regional eleitoral, entendeu que a a\u00e7\u00e3o, proposta pelo presidente do PSOL, Juliano Medeiros, foi ajuizada fora do prazo previsto em lei. Com isso, Tarc\u00edsio poder\u00e1 concorrer na elei\u00e7\u00e3o de outubro ao governo do estado.<\/p>\n<p>Carioca radicado em Bras\u00edlia, Tarc\u00edsio havia tido sua transfer\u00eancia de domic\u00edlio eleitoral aceita pela 127\u00aa Zona Eleitoral, sediada em S\u00e3o Jos\u00e9 dos Campos. Ap\u00f3s o Tribunal rejeitar a mudan\u00e7a de t\u00edtulo do ex-juiz Sergio Moro (Uni\u00e3o) e obrig\u00e1-lo a retornar ao Paran\u00e1 para disputar a elei\u00e7\u00e3o, o ex-ministro de Jair Bolsonaro se viu alvo de opositores que criticavam sua n\u00e3o identifica\u00e7\u00e3o com S\u00e3o Paulo.<\/p>\n<p>&#8220;N\u00e3o ser\u00e1 adotada nenhuma provid\u00eancia (contra a transfer\u00eancia) por quest\u00e3o de intempestividade&#8221;.<\/p>\n<p>Em nota, o PSOL afirmou que a decis\u00e3o do TRE &#8220;\u00e9 totalmente equivocada por v\u00e1rios motivos&#8221;. Primeiro, diz o partido, por n\u00e3o haver prazo para fazer proposta de revis\u00e3o do cadastro eleitoral.<\/p>\n<p>&#8220;Segundo, independentemente do pedido do PSOL, \u00e9 um dever da Justi\u00e7a Eleitoral n\u00e3o permitir que o cadastro eleitoral contenha fraudes, ilegalidade ou abuso. Terceiro, n\u00e3o tem qualquer fundamento a instru\u00e7\u00e3o dada de que o PSOL, para poder entrar com o pedido de revis\u00e3o do cadastro, deveria ter antes pedido a impugna\u00e7\u00e3o da candidatura de Tarc\u00edsio de Freitas&#8221;, disse o PSOL, que vai recorrer da decis\u00e3o.<\/p>\n<p>Em 7 de junho, o TRE rejeitou a transfer\u00eancia do domic\u00edlio eleitoral de Moro. A decis\u00e3o se deu em julgamento do recurso do diret\u00f3rio municipal do PT contra a decis\u00e3o da 5\u00aa Zona Eleitoral, que aprovou o pedido de transfer\u00eancia de domic\u00edlio eleitoral do ex-juiz de Curitiba (PR) para a cidade de S\u00e3o Paulo.<\/p>\n<p>A a\u00e7\u00e3o movida pelo deputado federal Alexandre Padilha (PT-SP) e o diret\u00f3rio municipal da sigla argumentou que o ex-ministro de Bolsonaro n\u00e3o possu\u00eda v\u00ednculo profissional em S\u00e3o Paulo e ainda teria apresentado o endere\u00e7o de um hotel para comprovar v\u00ednculo residencial.<\/p>\n<p>Tamb\u00e9m citava que Moro ainda era inscrito na OAB do Paran\u00e1 e havia sido indicado a vice-presidente de um \u00f3rg\u00e3o de dire\u00e7\u00e3o partid\u00e1ria do estado do Paran\u00e1 dois meses antes de requerer a transfer\u00eancia para S\u00e3o Paulo.<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dias atr\u00e1s, Tribunal havia negado mudan\u00e7a de t\u00edtulo de eleitor ao ex-ministro Sergio Moro, que voltou ao Paran\u00e1 para disputar a elei\u00e7\u00e3o<\/p>\n","protected":false},"author":5,"featured_media":391344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6,7],"tags":[],"class_list":["post-391343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/tarcisio3.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/391343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=391343"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/391343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/391344"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=391343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=391343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=391343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}