{"id":391847,"date":"2022-06-29T09:24:27","date_gmt":"2022-06-29T12:24:27","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=391847"},"modified":"2022-06-29T09:24:27","modified_gmt":"2022-06-29T12:24:27","slug":"justica-determina-suspensao-do-pedrao-de-eunapolis","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/justica-determina-suspensao-do-pedrao-de-eunapolis\/","title":{"rendered":"Justi\u00e7a determina suspens\u00e3o do Pedr\u00e3o de Eun\u00e1polis"},"content":{"rendered":"<h1><\/h1>\n<h2>Evento estava marcado para ocorrer entre esta quarta-feira (29) e o dia 3 de julho<\/h2>\n<div class=\"autor\">Reda\u00e7\u00e3o<\/div>\n<div id=\"div-share\"><\/div>\n<div class=\"materia\">\n<div class=\"conteudo_post\">\n<figure id=\"attachment_320672\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/06\/23061816\/pedr%C3%A3o.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-320672\" src=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/06\/23061816\/pedr%C3%A3o.jpg\" alt=\"Foto: Divulga\u00e7\u00e3o \" width=\"600\" height=\"420\" \/><\/a><figcaption class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O Tribunal de Justi\u00e7a do Estado da Bahia (TJ-BA) determinou, nesta ter\u00e7a-feira (28), por meio de liminar, a suspens\u00e3o do Pedr\u00e3o de Eun\u00e1polis, no extremo-sul do estado. O Minist\u00e9rio P\u00fablico (MP-BA) entrou com um recurso contra a\u00a0<a href=\"https:\/\/bahia.ba\/justica\/liminar-do-mp-ba-e-indeferida-e-pedrao-de-eunapolis-e-confirmado\/\" target=\"_blank\" rel=\"noopener\">decis\u00e3o da 1\u00aa Vara da Fazenda P\u00fablica<\/a>\u00a0do munic\u00edpio, que havia liberado a realiza\u00e7\u00e3o do festejo junino.<\/p>\n<p>Na determina\u00e7\u00e3o, o juiz Ben\u00edcio Mascarenhas Neto, relator do recurso, acolheu os argumentos apresentados pelo MP-BA para a suspens\u00e3o do evento, marcado para ocorrer entre esta quarta-feira (29) e o dia 3 de julho.<\/p>\n<p>Segundo o magistrado, em an\u00e1lise aos documentos que constam nos autos do processo, foi poss\u00edvel observar que os custos do evento giram em torno de R$ 7 milh\u00f5es, valor que supera a dota\u00e7\u00e3o prevista na Lei Or\u00e7ament\u00e1ria Anual (LOA) em 2022, que \u00e9 de cerca de R$ 3,6 milh\u00f5es.<\/p>\n<p>Na\u00a0<a href=\"https:\/\/bahia.ba\/bahia\/mp-ba-entra-com-acao-na-justica-pedindo-a-suspensao-do-pedrao-de-eunapolis\/\" target=\"_blank\" rel=\"noopener\">a\u00e7\u00e3o ajuizada pelo MP-BA<\/a>, na semana passada, o promotor de Justi\u00e7a Rodrigo Rubiale, alega que o munic\u00edpio decidiu realizar a festa \u201csem o devido planejamento e programa\u00e7\u00e3o de recursos or\u00e7ament\u00e1rios e financeiros para tal fim\u201d.<\/p>\n<p>A Prefeitura de Eun\u00e1polis garantiu que o munic\u00edpio tem\u00a0<a href=\"https:\/\/bahia.ba\/bahia\/apos-acao-do-mp-prefeitura-garante-que-pedrao-nao-afeta-saude-financeira-de-eunapolis\/\" target=\"_blank\" rel=\"noopener\">or\u00e7amento justific\u00e1vel<\/a>\u00a0para a realiza\u00e7\u00e3o do Pedr\u00e3o. De acordo com a gest\u00e3o municipal, a estimativa era de que este\u00a0<a href=\"https:\/\/bahia.ba\/municipios\/prefeitura-preve-aquecimento-da-economia-com-pedrao\/\" target=\"_blank\" rel=\"noopener\">evento injetasse cerca de R$ 50 milh\u00f5es na economia local<\/a>\u00a0com o aquecimento do com\u00e9rcio e a circula\u00e7\u00e3o de turistas.<\/p>\n<p>Entre os artistas esperados para a festa est\u00e3o Wesley Safad\u00e3o, Jo\u00e3o Gomes, Amado Batista, Zez\u00e9 di Camargo e Luciano e Tarc\u00edsio do Acordeon.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Evento estava marcado para ocorrer entre esta quarta-feira (29) e o dia 3 de julho<\/p>\n","protected":false},"author":5,"featured_media":391848,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-391847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/06\/pedrao.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/391847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=391847"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/391847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/391848"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=391847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=391847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=391847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}