{"id":392114,"date":"2022-07-02T08:05:51","date_gmt":"2022-07-02T11:05:51","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392114"},"modified":"2022-07-02T08:05:51","modified_gmt":"2022-07-02T11:05:51","slug":"celsinho-contrim-pode-concorrer-ao-governo-da-bahia-pelo-prtb","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/celsinho-contrim-pode-concorrer-ao-governo-da-bahia-pelo-prtb\/","title":{"rendered":"Celsinho Contrim pode concorrer ao Governo da Bahia pelo PRTB"},"content":{"rendered":"<h1><\/h1>\n<h2>Pol\u00edtico afirmou que at\u00e9 o dia 15 de julho bate o martelo sobre a poss\u00edvel candidatura<\/h2>\n<div class=\"autor\">Matheus Morais \/ Mattheus Miranda<\/div>\n<div id=\"div-share\"><\/div>\n<div class=\"materia\">\n<div class=\"conteudo_post\">\n<figure id=\"attachment_321687\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/07\/02044709\/contrim.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-321687\" src=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/07\/02044709\/contrim.jpg\" alt=\"Foto: Jorge Jesus\/bahia.ba\" width=\"600\" height=\"420\" \/><\/a><figcaption class=\"wp-caption-text\">Foto: Jorge Jesus\/bahia.ba<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>O presidente estadual do Partido Renovador Trabalhista Brasileiro (PRTB), Celsinho Contrim, comentou sobre a possibilidade de sair candidato ao Governo da Bahia ainda nas elei\u00e7\u00f5es deste ano. Em conversa com o\u00a0<strong>bahia.ba<\/strong>, durante o Cortejo C\u00edvico do Dois de Julho, na Lapinha, o pol\u00edtico afirmou que vive um \u201cdilema\u201d.<\/p>\n<p>\u201cTra\u00e7amos uma estrat\u00e9gia de fortalecer a chapa proporcional, fazendo com que os deputados federais e estaduais tenham maior relev\u00e2ncia nas elei\u00e7\u00f5es de 2022. Estamos conversando com outros governador\u00e1veis. Setores do PRTB est\u00e3o me pressionando para que eu saia candidato a Governo do Estado\u201d, revelou.<\/p>\n<p>Contrim foi candidato a prefeitura de Salvador, em 2020, e em 2018, tentou uma vaga ao Senado Federal, quando recebeu 41.055 votos.<\/p>\n<p>\u201cVim tomar inspira\u00e7\u00e3o do caboclo e da cabocla do Dois de Julho para que a gente possa definir esses rumos. Dia 15 de julho eu bato o martelo se somos candidatos a governador ou se n\u00e3o somos e quem iremos apoiar para governador, j\u00e1 que esse ano a gente n\u00e3o tem uma candidata governadora no pleito\u201d, acrescentou.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtico afirmou que at\u00e9 o dia 15 de julho bate o martelo sobre a poss\u00edvel candidatura<\/p>\n","protected":false},"author":5,"featured_media":392115,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6,7],"tags":[],"class_list":["post-392114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios","category-nacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/contrim.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392114"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/392115"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}