{"id":392260,"date":"2022-07-04T10:00:34","date_gmt":"2022-07-04T13:00:34","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392260"},"modified":"2022-07-04T10:00:34","modified_gmt":"2022-07-04T13:00:34","slug":"eleicoes-podem-bater-recorde-de-debates-mas-com-ausencia-de-lula-e-bolsonaro","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/eleicoes-podem-bater-recorde-de-debates-mas-com-ausencia-de-lula-e-bolsonaro\/","title":{"rendered":"Elei\u00e7\u00f5es podem bater recorde de debates, mas com aus\u00eancia de Lula e Bolsonaro"},"content":{"rendered":"<h1><\/h1>\n<h2>Ao todo, est\u00e3o previstos dez debates no primeiro turno e outros seis no segundo, caso ocorra<\/h2>\n<div class=\"autor\">Reda\u00e7\u00e3o<\/div>\n<div id=\"div-share\"><\/div>\n<div class=\"materia\">\n<div class=\"conteudo_post\">\n<figure id=\"attachment_315600\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/05\/11051546\/BeFunky-collage.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-315600\" src=\"https:\/\/d1x4bjge7r9nas.cloudfront.net\/wp-content\/uploads\/2022\/05\/11051546\/BeFunky-collage.jpg\" alt=\"Fotos: Ricardo Stuckert | Ascom\/PR\" width=\"600\" height=\"420\" \/><\/a><figcaption class=\"wp-caption-text\">Fotos: Ricardo Stuckert | Ascom\/PR<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Os dois candidatos mais bem colocados nas pesquisas de inten\u00e7\u00e3o de voto para a presid\u00eancia da Rep\u00fablica,\u00a0Luiz In\u00e1cio Lula da Silva (PT) e \u200bJair Bolsonaro (PL), podem n\u00e3o participar dos debates televisivos neste ano. Trata-se do pleito com o maior n\u00famero de debates da hist\u00f3ria. Ao todo, est\u00e3o previstos\u00a0dez debates no primeiro turno e outros seis no segundo, caso ocorra.<\/p>\n<p>Se todos esses eventos forem realizados, ser\u00e1 batido o recorde da disputa de 2010, quando Dilma Rousseff (PT) se elegeu pela primeira vez. Naquele ano, nove debates foram organizados no primeiro turno e outros quatro no segundo.<\/p>\n<p>A campanha de Lula tem defendido a realiza\u00e7\u00e3o de apenas tr\u00eas debates no primeiro turno, por meio de um pool de emissoras. A de Bolsonaro sequer tem enviado representantes para as reuni\u00f5es com os \u00f3rg\u00e3os de imprensa, segundo as campanhas.<\/p>\n<p>Diferentemente das propagandas na TV e no r\u00e1dio, em que os candidatos s\u00e3o apresentados sob o verniz do marketing eleitoral, os debates submetem os concorrentes, ao vivo, ao escrut\u00ednio de advers\u00e1rios e jornalistas.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se todos esses eventos forem realizados, ser\u00e1 batido o recorde da disputa de 2010, quando Dilma Rousseff (PT) se elegeu pela primeira vez. Naquele ano, nove debates foram organizados no primeiro turno e outros quatro no segundo.<\/p>\n","protected":false},"author":5,"featured_media":392261,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-392260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/lula-e-bolso.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392260"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/392261"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}