{"id":392450,"date":"2022-07-05T15:03:15","date_gmt":"2022-07-05T18:03:15","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392450"},"modified":"2022-07-05T15:03:15","modified_gmt":"2022-07-05T18:03:15","slug":"randolfe-diz-que-acionara-stf-se-pacheco-adiar-instalacao-da-cpi-do-mec","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/randolfe-diz-que-acionara-stf-se-pacheco-adiar-instalacao-da-cpi-do-mec\/","title":{"rendered":"Randolfe diz que acionar\u00e1 STF se Pacheco adiar instala\u00e7\u00e3o da CPI do MEC"},"content":{"rendered":"<h2 class=\"article__headline marginBottom30\"><\/h2>\n<div class=\"article__lead\">\n<p><strong>Presidente do Senado, Rodrigo Pacheco, anunciou pelo Twitter que a cria\u00e7\u00e3o do colegiado dever\u00e1 ficar para depois do per\u00edodo eleitoral<\/strong><\/p>\n<\/div>\n<div class=\"articleMetadata marginBottom30\">\n<p>&nbsp;<\/p>\n<\/div>\n<figure><picture><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220623130648_3a14990398bfa468946a1cee5c8bf8c8e07634004d5ab8fc4086828c9ad0d3cd.webp\" type=\"image\/webp\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220623130648_3a14990398bfa468946a1cee5c8bf8c8e07634004d5ab8fc4086828c9ad0d3cd.jpg\" type=\"image\/jpeg\" media=\"(max-width: 680px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220623130648_140ff62d3108960b4f4f128184fd97e48a671e347fa50c1ca0141a35e598111a.webp\" type=\"image\/webp\" media=\"(min-width: 681px)\" \/><source srcset=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220623130648_140ff62d3108960b4f4f128184fd97e48a671e347fa50c1ca0141a35e598111a.jpg\" type=\"image\/jpeg\" media=\"(min-width: 681px)\" \/><img decoding=\"async\" title=\"Randolfe Rodrigues (Foto: Pedro Fran\u00e7a\/Ag\u00eancia Senado | Marcos Oliveira\/Ag\u00eancia Senado)\" src=\"https:\/\/publisher-publish.s3.eu-central-1.amazonaws.com\/pb-brasil247\/swp\/jtjeq9\/media\/20220623130648_140ff62d3108960b4f4f128184fd97e48a671e347fa50c1ca0141a35e598111a.jpg\" alt=\"www.brasil247.com - Randolfe Rodrigues\" \/><\/picture><figcaption>Randolfe Rodrigues (Foto: Pedro Fran\u00e7a\/Ag\u00eancia Senado | Marcos Oliveira\/Ag\u00eancia Senado)<\/figcaption><\/figure>\n<div class=\"article__text marginTop30\">\n<p>O senador Randolfe Rodrigues (Rede-AP) usou as redes sociais nesta ter\u00e7a-feira (5) para afirmar que acionar\u00e1 o Supremo Tribunal Federal (STF) caso o presidente do Senado, Rodrigo Pacheco (PSD-MG), n\u00e3o leia o requerimento de instala\u00e7\u00e3o da CPI do MEC at\u00e9 esta quarta-feira (6). Ainda segundo o parlamentar, o\u00a0<a href=\"https:\/\/www.brasil247.com\/regionais\/brasilia\/pacheco-diz-que-cpi-do-mec-ficara-para-depois-do-periodo-eleitoral\" target=\"_blank\" rel=\"noopener\">adiamento para depois da elei\u00e7\u00e3o<\/a>\u00a0\u201cfoi previamente acordado por um grupo ligado ao Pal\u00e1cio do Planalto\u201d.<\/p>\n<p><iframe width=\"1\" height=\"1\" frameborder=\"0\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe>\u201cA CPI do MEC atende todos os requisitos constitucionais para sua instala\u00e7\u00e3o. N\u00e3o cabe interpreta\u00e7\u00e3o, de quem quer que seja, da Constitui\u00e7\u00e3o Federal, isso inclui o col\u00e9gio de l\u00edderes. Aguardo at\u00e9 amanh\u00e3 a leitura do requerimento. Caso contr\u00e1rio, n\u00e3o nos restar\u00e1 alternativa, a n\u00e3o ser acionar o STF\u201d, escreveu Randolfe no Twitter.<\/p>\n<p><a href=\"https:\/\/www.brasil247.com\/regionais\/brasilia\/pacheco-diz-que-cpi-do-mec-ficara-para-depois-do-periodo-eleitoral\" target=\"_blank\" rel=\"noopener\">Pacheco anunciou\u00a0<\/a>pelo Twitter que a instala\u00e7\u00e3o da CPI do MEC, que visa investigar um suposto esquema de corrup\u00e7\u00e3o e tr\u00e1fico de influ\u00eancia no Minist\u00e9rio da Educa\u00e7\u00e3o comandado pelo ex-ministro Milton Ribeiro com a ajuda de pastores, deve ficar para depois do per\u00edodo eleitoral.<\/p>\n<div class=\"contentAd contentAd--noBackground marginBottom30\">\n<div class=\"marginBottom30 marginTop30\" data-account=\"3346585:a3c9r4n3k3\" data-form=\"4533589:q9s5r2\">\n<div id=\"mlb2-4533589\" class=\"ml-form-embedContainer ml-subscribe-form ml-subscribe-form-4533589\">\n<div class=\"ml-form-align-center\">\n<div class=\"ml-form-embedWrapper embedForm\">\n<div class=\"ml-form-embedBody ml-form-embedBodyHorizontal row-form\">\n<form class=\"ml-block-form\" action=\"https:\/\/static.mailerlite.com\/webforms\/submit\/q9s5r2\" method=\"post\" target=\"_blank\" data-code=\"q9s5r2\">\n<div class=\"ml-form-formContent horozintalForm\">\n<div class=\"ml-form-horizontalRow\">\n<div class=\"ml-button-horizontal primary\"><\/div>\n<\/div>\n<\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/track.mailerlite.com\/webforms\/o\/4533589\/q9s5r2?v1654535749\" alt=\".\" width=\"1\" height=\"1\" border=\"0\" \/><\/div>\n<\/div>\n<p>Segundo a\u00a0<a href=\"https:\/\/politica.estadao.com.br\/blogs\/coluna-do-estadao\/randolfe-diz-que-reuniao-foi-artificial\/\" target=\"_blank\" rel=\"noopener\">Coluna do Estad\u00e3o,<\/a>\u00a0do jornal O Estado de S. Paulo, Randolfe deixou a reuni\u00e3o de l\u00edderes com o presidente do Senado antes do fim, afirmando que \u201co encontro foi \u2018artificial\u2019 e que a ideia de adiar a CPI do MEC para depois da elei\u00e7\u00e3o foi previamente acordada por um grupo ligado ao Pal\u00e1cio do Planalto\u201d.<\/p>\n<p>\u201cN\u00e3o cabe ao col\u00e9gio de l\u00edderes fazer julgamento de valor de CPI. Os l\u00edderes devem fazer as indica\u00e7\u00f5es. Alguns l\u00edderes est\u00e3o andando muito com o Jair Bolsonaro (PL) e est\u00e3o aprendendo a desrespeitar a Constitui\u00e7\u00e3o\u201c, disse Randolfe.<\/p>\n<div class=\"contentAd contentAd--noBackground marginBottom30\">\n<div class=\"marginTop10 adBackground\">\n<div id=\"div-gpt-ad-1560994795217-0\" data-google-query-id=\"CNXFl9yp4vgCFdEeuQYdA9wDuQ\">\n<div id=\"google_ads_iframe_\/55115104\/article-728x90-3_0__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Veja a postagem de Randolfe Rodrigues.<\/p>\n<div class=\"embed-block\">\n<div class=\"twitter-tweet twitter-tweet-rendered\"><iframe id=\"twitter-widget-0\" class=\"\" title=\"Twitter Tweet\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?creatorScreenName=brasil247&amp;dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfdHdlZXRfZWRpdF9iYWNrZW5kIjp7ImJ1Y2tldCI6Im9mZiIsInZlcnNpb24iOm51bGx9LCJ0ZndfcmVmc3JjX3Nlc3Npb24iOnsiYnVja2V0Ijoib2ZmIiwidmVyc2lvbiI6bnVsbH0sInRmd190d2VldF9yZXN1bHRfbWlncmF0aW9uXzEzOTc5Ijp7ImJ1Y2tldCI6InR3ZWV0X3Jlc3VsdCIsInZlcnNpb24iOm51bGx9LCJ0Zndfc2Vuc2l0aXZlX21lZGlhX2ludGVyc3RpdGlhbF8xMzk2MyI6eyJidWNrZXQiOiJpbnRlcnN0aXRpYWwiLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2V4cGVyaW1lbnRzX2Nvb2tpZV9leHBpcmF0aW9uIjp7ImJ1Y2tldCI6MTIwOTYwMCwidmVyc2lvbiI6bnVsbH0sInRmd191c2VyX2ZvbGxvd19pbnRlbnRfMTQ0MDYiOnsiYnVja2V0IjoiZm9sbG93IiwidmVyc2lvbiI6bnVsbH0sInRmd190d2VldF9lZGl0X2Zyb250ZW5kIjp7ImJ1Y2tldCI6Im9mZiIsInZlcnNpb24iOm51bGx9fQ%3D%3D&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1544324623126433793&amp;lang=pt&amp;origin=https%3A%2F%2Fwww.brasil247.com%2Fbrasil%2Frandolfe-diz-que-acionara-stf-se-pacheco-adiar-instalacao-da-cpi-do-mec&amp;sessionId=99dff03bc93a27d091ad835e1b5cbb7a9c6fd2c4&amp;siteScreenName=brasil247&amp;theme=light&amp;widgetsVersion=b45a03c79d4c1%3A1654150928467&amp;width=550px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1544324623126433793\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Presidente do Senado, Rodrigo Pacheco, anunciou pelo Twitter que a cria\u00e7\u00e3o do colegiado dever\u00e1 ficar para depois do per\u00edodo eleitoral<\/p>\n","protected":false},"author":5,"featured_media":365473,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-392450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2021\/08\/randolfe-boa.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392450"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/365473"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}