{"id":392671,"date":"2022-07-07T07:11:03","date_gmt":"2022-07-07T10:11:03","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392671"},"modified":"2022-07-07T07:11:03","modified_gmt":"2022-07-07T10:11:03","slug":"sem-franca-haddad-cresce-seis-pontos-e-chega-a-522-dos-votos-validos-em-sp-diz-genial-quaest","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/sem-franca-haddad-cresce-seis-pontos-e-chega-a-522-dos-votos-validos-em-sp-diz-genial-quaest\/","title":{"rendered":"Sem Fran\u00e7a, Haddad cresce seis pontos e chega a 52,2% dos votos v\u00e1lidos em SP, diz Genial\/Quaest"},"content":{"rendered":"<header class=\"main-article--header\">\n<h1 class=\"titulo\"><\/h1>\n<h2 class=\"bajada\">Fernando Haddad foi o principal beneficiado com a sa\u00edda do ex-governador do PSB da disputa ao governo de SP. Fran\u00e7a passa a liderar a disputa ao Senado.<\/h2>\n<\/header>\n<div class=\"margen-top1\"><\/div>\n<div class=\"main-article--body\">\n<figure class=\"main-photo\"><img decoding=\"async\" class=\"i-amphtml-fill-content i-amphtml-replaced-content\" src=\"https:\/\/revistaforum.com.br\/u\/fotografias\/m\/2022\/7\/7\/f960x540-84145_158220_15.jpg\" alt=\"\" data-amp-auto-lightbox-disable=\"\" \/><figcaption class=\"epigrafe\"><strong>Fernando Haddad.<\/strong><span class=\"creditos\">Cr\u00e9ditos: Reprodu\u00e7\u00e3o\/Instagram<\/span><\/figcaption><\/figure>\n<div class=\"article-content\">\n<div class=\"article-content--autor\">\n<div class=\"el-autor\">\n<div class=\"foto-autor\"><\/div>\n<div class=\"nombre-autor\"><a class=\"nota-link-autor\" title=\"Ir al perfil de  Plinio Teodoro\" href=\"https:\/\/revistaforum.com.br\/autor\/plinioteodoro.html\">Por\u00a0<span class=\"post-author-name change-utf\">Plinio Teodoro<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"share-group\"><\/div>\n<div class=\"article-content--cuerpo\">\n<p>Pesquisa Genial\/Quaest divulgada nesta quinta-feira (7) mostra que Fernando Haddad (PT) cresceu seis pontos percentuais com a sa\u00edda de M\u00e1rcio Fran\u00e7a (PSB) e lidera a disputa ao governo de S\u00e3o Paulo com 35% das inten\u00e7\u00f5es de votos no cen\u00e1rio estimulado &#8211; quando s\u00e3o apresentados os nomes dos candidatos. O percentual representa 52,2% dos votos v\u00e1lidos e pode dar a vit\u00f3ria ao petista ainda no primeiro turno.<\/p>\n<p>Candidato de Jair Bolsonaro (PL), Tarc\u00edsio Gomes de Freitas (Republicanos) oscilou dois pontos para mais, dentro da margem de erro, e est\u00e1 em segundo com 14% &#8211; 20,8% dos v\u00e1lidos.<\/p>\n<p>Atual governador, Rodrigo Garcia (PSDB) foi o segundo que mais se beneficiou com a sa\u00edda de Fran\u00e7a, saltando de 8% para 12%. Fel\u00edcio Ramuth (PSD), que deve ser anunciado como vice de Tarc\u00edsio nesta quinta, tem 2%, mesmo percentual de Vin\u00edcius Poit (Novo). Indecisos s\u00e3o 12% e brancos e nulos somam 24%.<\/p>\n<p>Na pesquisa espont\u00e2nea, quando n\u00e3o s\u00e3o revelados os nomes dos candidatos, Tarc\u00edsio \u00e9 citado por 7%, seguido de Haddad, com 5% das men\u00e7\u00f5es, e Fran\u00e7a, com 2%. Outros 81% dizem estar<\/p>\n<h2>Segundo turno<\/h2>\n<p>A pesquisa mostra ainda que Haddad vence todos os advers\u00e1rios nas simula\u00e7\u00f5es de segundo turno. Contra Tarc\u00edsio, o placar \u00e9 de 44% a 28%. J\u00e1 com Garcia, o petista vence por 42% a 27%.<\/p>\n<h2>Senado<\/h2>\n<p>Sem Jos\u00e9 Luiz Datena (PSC), que abandonou mais uma vez a disputa, Fran\u00e7a lidera a corrida ao Senado com 27% das inten\u00e7\u00f5es de votos. Ex-presidente da Fiesp, o bolsonarista Paulo Skaf (Republicanos) vem em segundo com 13%.<\/p>\n<p>Outra bolsonarista, Carla Zambelli (PL) marca 9%, seguida por Jana\u00edna Paschoal (PRTB), que tem 7%. \u00a0Milton Leite (Uni\u00e3o Brasil) e Aldo Rebelo (PDT) pontuam 5% e 3%, respectivamente. Os demais candidatos n\u00e3o passaram de 1% das inten\u00e7\u00f5es de voto.<\/p>\n<p>A pesquisa presencial entrevistou 1.640 pessoas entre os dias 1 a 4 de julho e est\u00e1 registrada no TSE sob os n\u00fameros SP-05318\/2022 e BR-03964\/2022. A margem de erro \u00e9 de 2,4 pontos porcentuais e o n\u00edvel de confiabilidade \u00e9 de 95%.<\/p>\n<div class=\"content-banner\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Outra bolsonarista, Carla Zambelli (PL) marca 9%, seguida por Jana\u00edna Paschoal (PRTB), que tem 7%.  Milton Leite (Uni\u00e3o Brasil) e Aldo Rebelo (PDT) pontuam 5% e 3%, respectivamente. Os demais candidatos n\u00e3o passaram de 1% das inten\u00e7\u00f5es de voto.<\/p>\n<p>A pesquisa presencial entrevistou 1.640 pessoas entre os dias 1 a 4 de julho e est\u00e1 registrada no TSE sob os n\u00fameros SP-05318\/2022 e BR-03964\/2022. A margem de erro \u00e9 de 2,4 pontos porcentuais e o n\u00edvel de confiabilidade \u00e9 de 95%. <\/p>\n","protected":false},"author":5,"featured_media":392672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-392671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/haddad-vermelho.jpg","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392671"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/392672"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}