{"id":392951,"date":"2022-07-11T08:32:08","date_gmt":"2022-07-11T11:32:08","guid":{"rendered":"https:\/\/acaopopular.net\/jornal\/?p=392951"},"modified":"2022-07-11T08:32:08","modified_gmt":"2022-07-11T11:32:08","slug":"nordeste-tem-4-mil-vagas-em-concursos-publicos-com-salarios-de-ate-r-115-mil","status":"publish","type":"post","link":"https:\/\/acaopopular.net\/jornal\/nordeste-tem-4-mil-vagas-em-concursos-publicos-com-salarios-de-ate-r-115-mil\/","title":{"rendered":"Nordeste tem 4 mil vagas em concursos p\u00fablicos com sal\u00e1rios de at\u00e9 R$ 11,5 mil"},"content":{"rendered":"<div class=\"row visible-lg\">\n<div class=\"col-xs-12\">\n<div class=\"noticias-single__tags\"><\/div>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-lg-3\">\n<div class=\"noticias-single__meta\">\n<div class=\"noticias-single__author\">\n<div>Carmen Vasconcelos<\/div>\n<\/div>\n<div class=\"noticias-single__share \">\n<div class=\"noticias-single__share-item noticias-single__share-item--whatsapp noticias-single__share-item--whatsapp--desktop  \"><\/div>\n<div class=\"noticias-single__share-item noticias-single__share-item--more   \"><\/div>\n<\/div>\n<div class=\"noticias-single__content-area__left\">\n<div class=\"col-xs-12 col-lg-12 col-md-12 \">\n<div id=\"CW3677\" class=\"publicidade publicidade-responsive1  \">\n<div id=\"emprego_300x250_02\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-xs-12 col-lg-9\">\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div class=\"noticias-single__image\"><picture class=\"noticias-single__picture\"><source srcset=\"https:\/\/correio-cdn1.cworks.cloud\/fileadmin\/_processed_\/d\/d\/csm_concurso_publico_1_6dbdd5c2ad.jpg\" media=\"(min-width: 420px)\" \/><img decoding=\"async\" class=\"noticias-single__image-source\" src=\"https:\/\/correio-cdn2.cworks.cloud\/fileadmin\/_processed_\/d\/d\/csm_concurso_publico_1_2a22ab1d1f.jpg\" alt=\"O desemprego e o desejo por estabilidade tem levado in\u00fameros concurseiros a buscarem oportunidades fora da Bahia\" \/><\/picture><span class=\"noticias-single__image-caption\">O desemprego e o desejo por estabilidade tem levado in\u00fameros concurseiros a buscarem oportunidades fora da Bahia (Shutterstock\/reprodu\u00e7\u00e3o)<\/span><\/div>\n<\/div>\n<div class=\"col-xs-12 noticias-single__stick-parent\">\n<div class=\"row\">\n<div class=\"col-xs-12 col-md-7 col-lg-7\">\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<h1 class=\"noticias-single__title noticias-single__title--desktop noticias-single__title--with-image visible visible-lg\"><\/h1>\n<div class=\"noticias-single__description visible-lg\">As oportunidades est\u00e3o fora da Bahia e podem interessar aos candidatos que desejam estabilidade e maiores sal\u00e1rios<\/div>\n<div class=\"noticias-single__content-area noticias-single__content-area--before-content\">\n<div class=\"chamada-assinatura\"><\/div>\n<\/div>\n<div class=\"noticias-single__content is-blocked\">\n<div class=\"noticias-single__content__text js-mediator-article\">\n<p class=\"bodytext\">Buscar alternativas profissionais longe de casa tem sido a sa\u00edda encontrada por muitas pessoas que n\u00e3o conseguem se inserir no mercado de trabalho baiano, especialmente aqueles que buscam nos concursos p\u00fablicos a estabilidade e a seguran\u00e7a profissional. Talvez esteja na hora de sair da Bahia para buscar a t\u00e3o sonhada estabilidade em outros estados nordestinos. O CORREIO fez um levantamento e constatou que o Nordeste tem mais de 4 mil vagas dispon\u00edveis em concursos p\u00fablicos, com sal\u00e1rios de at\u00e9 R$ 11,5 mil.<\/p>\n<p class=\"bodytext\">Para quem opta pela sa\u00edda, os desafios v\u00e3o desde as saudades da fam\u00edlia e amigos at\u00e9 os choques culturais. No entanto, os que conquistaram uma vaga garantem que o esfor\u00e7o \u00e9 compensado e, dependendo da \u00e1rea, sempre h\u00e1 a esperan\u00e7a de garantir a transfer\u00eancia que possibilite o retorno. Outros terminam estabelecendo ra\u00edzes nos seus destinos e passam a estabelecer outras rela\u00e7\u00f5es com as regi\u00f5es onde passaram a viver e trabalhar.<\/p>\n<div class=\"single-publicidade\">\n<div id=\"emprego_300x250_01\"><\/div>\n<\/div>\n<table class=\"table\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.correio24horas.com.br\/fileadmin\/_processed_\/e\/c\/csm_Caravana_do_Marcao_2_1_b50d4f45f0.jpg\" width=\"1000\" height=\"750\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"text-center\"><strong>Respons\u00e1vel por um projeto chamado Caravana do Marc\u00e3o, o professor Marcus Vinicius vem ajudando estudantes que desejam oportunidades fora da Bahia\u00a0<\/strong>(Foto: Arquivo pessoal)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"bodytext\">Em 2016, o professor de curso preparat\u00f3rio Marcus Vinicius Mendes, mais conhecido como Professor Marc\u00e3o, junto com o s\u00f3cio L\u00e9o Morais, criaram o projeto Caravana do Marc\u00e3o(@caravanadomarcao ), que leva candidatos para realizarem as provas em outros estados. Na proposta, os estudantes contam com o preparo para as provas, al\u00e9m do transporte de ida e volta, hospedagem e seguran\u00e7a. \u201cEstamos comemorando seis anos de exist\u00eancia e, ao longo desse per\u00edodo, conseguimos transformar sonhos em realidade\u201d, comemora.<\/p>\n<p class=\"bodytext\"><strong>Oportunidade<\/strong><\/p>\n<div class=\"single-publicidade\">\n<div id=\"div-gpt-ad-1558981264142-0\"><\/div>\n<\/div>\n<p class=\"bodytext\">Amanda Coelho,26, foi uma dessas estudantes que conseguiu uma vaga na Pol\u00edcia Militar de Pernambuco gra\u00e7as \u00e0 iniciativa. \u201cComo muita gente, comecei estudando sozinha em casa, tentei PMSE , PMBA ,e bati na trave. Quando conheci o curso Impacto, tive tr\u00eas intensos meses de prepara\u00e7\u00e3o, mas o esfor\u00e7o valeu a pena e me trouxe a aprova\u00e7\u00e3o. Foi no projeto que aprendi estudar focada, concentrada no que era importante e resolver incont\u00e1veis quest\u00f5es\u201d, recorda.<\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td class=\"text-center\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.correio24horas.com.br\/fileadmin\/_processed_\/4\/c\/csm_Amanda_Coelho_1_71abc10b6f.jpg\" width=\"1000\" height=\"843\" \/><\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"text-center\"><strong>Amanda Coelho realizou o sonho de atuar junto a Pol\u00edcia Militar em Pernambuco e salienta o papel que o esfor\u00e7o tem para os \u00eaxitos nas provas (Foto: Acervo pessoal)\u00a0<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"bodytext\">Amanda lembra do mantra que dizia: A repeti\u00e7\u00e3o at\u00e9 a exaust\u00e3o, leva a perfei\u00e7\u00e3o. \u201cTodo aquele suporte me possibilitou encontrar calma na hora de fazer a prova, me fez lograr \u00eaxito e hoje ser soldado da Policia Militar de Pernambuco\u201d, completou.<\/p>\n<div class=\"single-publicidade\">\n<div id=\"div-gpt-ad-1558981401166-0\"><\/div>\n<\/div>\n<p class=\"bodytext\">O soldado Tiago Carvalho, 33, hoje lotado na PCC\u00e3es da 4\u00b0 Cia do Batalh\u00e3o de Choque da Pol\u00edcia Militar do Cear\u00e1, tamb\u00e9m se beneficiou do projeto. Na verdade, ele colecionou aprova\u00e7\u00f5es na Escola de Especialista da Aeron\u00e1utica, na PM de Pernambuco e do Cear\u00e1 e se emociona em lembrar do processo de prepara\u00e7\u00e3o e como o zelo dos professores resultaram no sucesso dele e de alguns colegas. \u201cMais que garantir a log\u00edstica, existe o suporte emocional que os professores oferecem, ent\u00e3o fica mais f\u00e1cil enfrentar e seguir com perseveran\u00e7a as horas dif\u00edceis\u201d, pontuou.<\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<td class=\"text-center\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.correio24horas.com.br\/fileadmin\/_processed_\/b\/7\/csm_Tiago_Carvalho_1_fd3af40052.jpg\" width=\"1000\" height=\"979\" \/><\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"text-center\"><strong>Tiago Carvalho lembra que o suporte oferecido no curso preparat\u00f3rio facilita a supera\u00e7\u00e3o das dificuldades no processo de prestar concurso fora (<\/strong>Foto: Acervo pessoal)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"bodytext\">Rubens Feitosa,33, reconhece que o suporte preparat\u00f3rio otimiza as chances de quem est\u00e1 se preparando para um concurso p\u00fablico, especialmente fora do estado natal. \u201cComecei a me preparar sem estrat\u00e9gia nenhuma. Quando comecei no curso, percebi que havia uma melhora no rendimento e o fato de treinar com provas anteriores foi permitindo ganhar seguran\u00e7a. Morando em Pernambuco, ele tamb\u00e9m ressalta a import\u00e2ncia das amizades feitas no percurso, especialmente dos instrutores que se tornaram amigos pessoais.<\/p>\n<div class=\"single-publicidade\">\n<div id=\"div-gpt-ad-1558985512674-0\"><\/div>\n<\/div>\n<table class=\"table\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.correio24horas.com.br\/fileadmin\/_processed_\/f\/8\/csm_Ranielly_1_9acbf30b72.jpg\" width=\"809\" height=\"1000\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"text-center\"><strong>Natural de Feira de Santana, Ranielly Freire diz que o concurso p\u00fablico mudou a perspectiva da fam\u00edlia e que a mudan\u00e7a de estado n\u00e3o \u00e9 nada\u00a0<\/strong>(Foto: Acervo pessoal)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"bodytext\">Morando em Fortaleza h\u00e1 pouco mais de dois meses, Ranielly Freire,30, deixou Feira de Santana em busca de um sonho. Antes de se mudar para a capital cearense, ela tentou a Pol\u00edcia Militar de Minas Gerais, mas foi reprovada no teste de aptid\u00e3o f\u00edsica. \u201cA vit\u00f3ria n\u00e3o se resume \u00e0 aprova\u00e7\u00e3o em todas as etapas de um concurso, mas \u00e9, antes de tudo, uma vit\u00f3ria de vida para mim e para minha fam\u00edlia\u201d, conclui.<\/p>\n<p class=\"bodytext\"><strong>Se voc\u00ea tamb\u00e9m sonha com concursos fora do estado, veja as oportunidades no nordeste:\u00a0<\/strong><\/p>\n<p class=\"bodytext\">Onde:\u00a0<strong>Prefeitura de Alto Santo, no Cear\u00e1<\/strong><br \/>\nBanca: Instituto Consulpam \u2013 Consultoria P\u00fablico-Privada<br \/>\nVagas:259 vagas s\u00e3o efetivas (seis destas reservadas a pessoas com defici\u00eancia), e 272 vagas para cadastro de reserva<br \/>\nSal\u00e1rios: de R$ 1.212,00 a R$ 9.000,00<br \/>\nInscri\u00e7\u00f5es: at\u00e9 22 de julho de 2022<br \/>\nContatos: Consulpam pelo telefone (85) 3224-9369 e WhatsApp (85) 9957-9369 (WhatsApp).<\/p>\n<p class=\"bodytext\">Onde:\u00a0<strong>Prefeitura de Ocara, no Cear\u00e1<\/strong><br \/>\nBanca: Instituto de Desenvolvimento Institucional Brasileiro (IDIB)<br \/>\nVagas:230 vagas de n\u00edveis m\u00e9dio, t\u00e9cnico e superior, distribu\u00eddas entre as \u00e1reas da Sa\u00fade e da Assist\u00eancia Social<br \/>\nSal\u00e1rios: entre R$ 1.212,00 e R$ 11.500,00.<br \/>\nInscri\u00e7\u00f5es: at\u00e9 18 de julho de 2022<br \/>\nContatos:\u00a0<a href=\"http:\/\/www.idib.org.br\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.idib.org.br<\/a><\/p>\n<p class=\"bodytext\">Onde:\u00a0<strong>Prefeitura de Prefeitura de S\u00e3o Lu\u00eds, Maranh\u00e3o<\/strong><br \/>\nBanca: Instituto Selecon<br \/>\nVagas:111 vagas imediatas e outras 333 para forma\u00e7\u00e3o de cadastro reserva de aprovados<br \/>\nSal\u00e1rios: vencimento-base \u00e9 de R$ 938,30, valor que contar\u00e1 com adicionais de compensa\u00e7\u00e3o, periculosidade, risco de vida e gratifica\u00e7\u00e3o, totalizando ganhos de R$ 3.272,40<br \/>\nInscri\u00e7\u00f5es: entre os dias 6 de julho e 19 de agosto de 2022<br \/>\nContatos:faleconosco@selecon.org.br.<\/p>\n<p class=\"bodytext\">Onde:\u00a0<strong>Secretaria de Educa\u00e7\u00e3o e Esportes, Pernambuco<\/strong><br \/>\nBanca: Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (Cebraspe)<br \/>\nVagas:2.907 vagas e formar cadastro reserva para Professores da Educa\u00e7\u00e3o B\u00e1sica em diversas \u00e1reas<br \/>\nSal\u00e1rios: R$ 3.900,00 para jornada de 200 horas mensais e R$ 2.925,00 para jornada de 150 horas mensais.<br \/>\nInscri\u00e7\u00f5es: at\u00e9 18 de julho de 2022<br \/>\nContatos:(61) 3448-0100 ou pelo e-mail sac@cebraspe.org.br.<\/p>\n<p class=\"bodytext\">Onde: \u00a0<strong>Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Piau\u00ed (IFPI)<\/strong><br \/>\nBanca: Comiss\u00e3o de Sele\u00e7\u00e3o de Pessoal (CSEP)<br \/>\nVagas:129 vagas de n\u00edveis m\u00e9dio, t\u00e9cnico e superior (31 para servidores e 98 para Professores).<br \/>\nSal\u00e1rios: R$ 2.904,96 a R$ 9.616,18, com jornadas de 20 ou 40 horas semanais<br \/>\nInscri\u00e7\u00f5es:25 de julho de 2022<br \/>\nContatos: concursos2022@ifpi.edu.br.<\/p>\n<\/div>\n<div id=\"paywall-barreiras-trial\" class=\"modal hide paywall-barreiras-inread paywall-barreiras--trial-wall is-active\" tabindex=\"-1\" role=\"dialog\" data-type=\"trial\" data-base-url=\"https:\/\/assine.correio24horas.com.br\/v2\" data-enable-modal=\"false\" data-enable-swg=\"true\" data-sku-plan=\"basic_monthly\" data-chartbeat=\"false\">\n<div class=\"paywall-barreiras-inread__content\">\n<div class=\"paywall-barreiras-inread__header\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As oportunidades est\u00e3o fora da Bahia e podem interessar aos candidatos que desejam estabilidade e maiores sal\u00e1rios<\/p>\n","protected":false},"author":5,"featured_media":392952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[327,6],"tags":[],"class_list":["post-392951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimidia","category-municipios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/acaopopular.net\/jornal\/wp-content\/uploads\/2022\/07\/concurso1.png","_links":{"self":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/comments?post=392951"}],"version-history":[{"count":0,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/posts\/392951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media\/392952"}],"wp:attachment":[{"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/media?parent=392951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/categories?post=392951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acaopopular.net\/jornal\/wp-json\/wp\/v2\/tags?post=392951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}